{"id":1788,"date":"2016-02-04T11:17:59","date_gmt":"2016-02-04T10:17:59","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/lacasadecora\/?p=1788"},"modified":"2016-02-04T11:17:59","modified_gmt":"2016-02-04T10:17:59","slug":"jugando-con-el-color","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/lacasadecora\/jugando-con-el-color\/2016\/02\/04\/","title":{"rendered":"Jugando con el color"},"content":{"rendered":"\n\t\t<style>\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 50%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-1788 gallery-columns-2 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href=\"https:\/\/blogs.diariovasco.com\/lacasadecora\/wp-content\/uploads\/sites\/59\/2016\/02\/6-ba\u00f1o-con-fondo.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/blogs.diariovasco.com\/lacasadecora\/wp-content\/uploads\/sites\/59\/2016\/02\/6-ba\u00f1o-con-fondo-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n\n<p>En este original apartamento, destacamos una parte de la casa, la zona de d\u00eda, donde destaca de forma especial el empleo del color, sobre todo en las paredes, d\u00e1ndole un protagonismo absoluto a estos rincones, y destacando el equipamiento que se encuentra sobre ellos.<\/p>\n<p>Por medio de la pintura y el color se ha dise\u00f1ado el lograr efectos de profundidad, para dar sensaci\u00f3n de mas amplitud.<\/p>\n<p>Te gusta este planteamiento de darle color a tu vivienda\u2026?<\/p>\n<p>Fotos v\u00eda: plasterline<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>En este original apartamento, destacamos una parte de la casa, la zona de d\u00eda, donde destaca de forma especial el empleo del color, sobre todo en las paredes, d\u00e1ndole un protagonismo absoluto a estos rincones, y destacando el equipamiento que se encuentra sobre ellos. Por medio de la pintura y el color se ha dise\u00f1ado [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":88,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[25,56,106],"class_list":["post-1788","post","type-post","status-publish","format-standard","hentry","category-casa","tag-apartamento","tag-color","tag-inspiracion"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/lacasadecora\/wp-json\/wp\/v2\/posts\/1788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/lacasadecora\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/lacasadecora\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/lacasadecora\/wp-json\/wp\/v2\/users\/88"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/lacasadecora\/wp-json\/wp\/v2\/comments?post=1788"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/lacasadecora\/wp-json\/wp\/v2\/posts\/1788\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/lacasadecora\/wp-json\/wp\/v2\/media?parent=1788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/lacasadecora\/wp-json\/wp\/v2\/categories?post=1788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/lacasadecora\/wp-json\/wp\/v2\/tags?post=1788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}