{"id":128,"date":"2009-09-07T11:53:42","date_gmt":"2009-09-07T11:53:42","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/masqueactualidad\/?p=128"},"modified":"2009-09-07T11:53:42","modified_gmt":"2009-09-07T11:53:42","slug":"marejadas_de_pareja","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/2009\/09\/07\/marejadas_de_pareja\/","title":{"rendered":"Marejadas de pareja"},"content":{"rendered":"<p>Esperar cosas contradictorias<br \/>\npaga peaje, dec\u00eda Jean-Claude Kaufmann, soci\u00f3logo de las relaciones de<br \/>\npareja en &#8216;La Vanguardia&#8217;. &#8220;Esperas sentirte plenamente libre y<br \/>\nautorrealizado como<br \/>\nindividuo, pero a la vez quieres sentirte en comuni\u00f3n c\u00f3mplice con tu<br \/>\npareja&#8221;. <\/p>\n<p>Estudiar ingles fuera durante una semana acarrea, seguro, alguna marejada, deb\u00ed de decirme. M\u00e1s val\u00eda aceptarlo.<\/p>\n<p>Asum\u00ed los hechos.El arrepentimiento es la m\u00e1s amarga de las pasiones,<br \/>\ndijo Spinoza. Qu\u00e9 triste amargarse un viaje, aunque s\u00f3lo sea el<br \/>\ndesplazamiento, por el sentimiento de culpa.&nbsp; Dijo alguna estudiosa de<br \/>\nla cosa femenina que las mujeres lo arrastramos. <\/p>\n<p>Estos vaivenes de conciencia me llevaron a esperar mi avi\u00f3n una hora<br \/>\nantes de lo necesario. Sentimiento-de-culpa-s\u00ed,<br \/>\nsentimiento-de-culpa-no, hab\u00eda olvidado cambiar mi reloj de hora en el<br \/>\nespacio insular.<\/p>\n<p>Las entregadas al an\u00e1lisis no estamos preparadas para la vida viajera,<br \/>\nme dije. Abr\u00ed la gu\u00eda. Las caras sonrientes de sus autores me<br \/>\nespolearon. En aquellos a\u00f1os de juventud, espera, pesar y fiestas, \u00bfpor<br \/>\nqu\u00e9 no me prepar\u00e9 para un destino viajero?<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Esperar cosas contradictorias paga peaje, dec\u00eda Jean-Claude Kaufmann, soci\u00f3logo de las relaciones de pareja en &#8216;La Vanguardia&#8217;. &#8220;Esperas sentirte plenamente libre y autorrealizado como individuo, pero a la vez quieres sentirte en comuni\u00f3n c\u00f3mplice con tu pareja&#8221;. Estudiar ingles fuera durante una semana acarrea, seguro, alguna marejada, deb\u00ed de decirme. M\u00e1s val\u00eda aceptarlo. Asum\u00ed los [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[4],"class_list":["post-128","post","type-post","status-publish","format-standard","hentry","category-2","tag-1599_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/comments?post=128"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/128\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/media?parent=128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/categories?post=128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/tags?post=128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}