{"id":130,"date":"2009-09-09T11:57:35","date_gmt":"2009-09-09T11:57:35","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/masqueactualidad\/?p=130"},"modified":"2009-09-09T11:57:35","modified_gmt":"2009-09-09T11:57:35","slug":"aqui_no_hay_quien_viva","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/2009\/09\/09\/aqui_no_hay_quien_viva\/","title":{"rendered":"Aqu\u00ed no hay quien viva"},"content":{"rendered":"<p>Hab\u00eda que compartir casa. No resultaba apetecible pero era la \u00fanica forma de alojamiento que me ofrec\u00eda la universidad, as\u00ed que, una vez que llegu\u00e9 a Galway en aquel avi\u00f3n de juguete a aquel aeropuerto de juguete, me dirig\u00ed en taxi hacia mi nuevo destino. Qu\u00e9 fr\u00edo hac\u00eda en Irlanda.<\/p>\n<p>-Estamos teniendo un verano especialmente lluvioso.<\/p>\n<p>El taxista hab\u00eda pronunciado una de las frases menos esperadas cuando uno visita por primera vez un pa\u00eds. Y lo de la frase es una forma de adornar la redacci\u00f3n porque mi ingl\u00e9s consiste en&nbsp; ir pescando palabras sueltas hasta lograr situarme.<\/p>\n<p>El taxista me dej\u00f3 en la recepci\u00f3n y yo llegu\u00e9 arrastrando mi maleta por caminos de gravilla hasta una zona de casas de colores llena de entrantes y salientes. El trazado urban\u00edstico de aquel conjunto de viviendas de materiales humildes me result\u00f3 laber\u00edntico a pesar del plano. \u00bfPor qu\u00e9 todas las casas estaban torcidas? La sensaci\u00f3n de estar perdida se agravaba por la oscuridad de la noche. O eso me dije.<\/p>\n<p>Tras varias idas y venidas encontr\u00e9 mi portal. Sub\u00ed al primer piso golpeando las escaleras con mi maleta de ruedas.<\/p>\n<p><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Hab\u00eda que compartir casa. No resultaba apetecible pero era la \u00fanica forma de alojamiento que me ofrec\u00eda la universidad, as\u00ed que, una vez que llegu\u00e9 a Galway en aquel avi\u00f3n de juguete a aquel aeropuerto de juguete, me dirig\u00ed en taxi hacia mi nuevo destino. Qu\u00e9 fr\u00edo hac\u00eda en Irlanda. -Estamos teniendo un verano especialmente [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[4],"class_list":["post-130","post","type-post","status-publish","format-standard","hentry","category-2","tag-1599_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/comments?post=130"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/130\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/media?parent=130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/categories?post=130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/tags?post=130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}