{"id":135,"date":"2009-09-19T20:32:53","date_gmt":"2009-09-19T20:32:53","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/masqueactualidad\/?p=135"},"modified":"2009-09-19T20:32:53","modified_gmt":"2009-09-19T20:32:53","slug":"la_ventana_indiscreta","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/2009\/09\/19\/la_ventana_indiscreta\/","title":{"rendered":"La ventana indiscreta"},"content":{"rendered":"<p>A m\u00ed Brad Pitt me recuerda a mi t\u00edo Manolo cuando se dej\u00f3 aquella barba de chivo. Con esos pelos encrespados que ped\u00edan a gritos &#8216;producto&#8217;, que dir\u00eda una peluquera. Me lo digo detr\u00e1s de mi ventana indiscreta, asomada a internet y al festival. Con mi bufanda y mis clinex, que no con el aperitivo que me trae la asistenta. Esto ya no es lo que fue.<\/p>\n<p>S\u00f3lo en estas circunstancias se entiende que lea al se\u00f1or de los ri\u00f1ones. Ciudad de cotillas, eso era Dubl\u00edn o eso eran los amigos del escritor. No me extra\u00f1a que pidiera a su ciudad que le olvidara. Y ellos, venga poner estatuas de bronce. C\u00f3mo son.<\/p>\n<p>Felicito a M. y le digo que ya falta poco para nuestro viaje. Me asomo al tendedero a por el balde. \u00bfQu\u00e9 es lo que cocinar\u00e1 esta vecina? Las sandalias en el cuarto del ni\u00f1o. Guardar la ropa de verano. Cosa de mujeres. Mujer. Que me den ya mis menudillos.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>A m\u00ed Brad Pitt me recuerda a mi t\u00edo Manolo cuando se dej\u00f3 aquella barba de chivo. Con esos pelos encrespados que ped\u00edan a gritos &#8216;producto&#8217;, que dir\u00eda una peluquera. Me lo digo detr\u00e1s de mi ventana indiscreta, asomada a internet y al festival. Con mi bufanda y mis clinex, que no con el aperitivo [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[4],"class_list":["post-135","post","type-post","status-publish","format-standard","hentry","category-2","tag-1599_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/comments?post=135"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/135\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/media?parent=135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/categories?post=135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/tags?post=135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}