{"id":138,"date":"2009-09-28T11:49:56","date_gmt":"2009-09-28T11:49:56","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/masqueactualidad\/?p=138"},"modified":"2009-09-28T11:49:56","modified_gmt":"2009-09-28T11:49:56","slug":"el_niqui","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/2009\/09\/28\/el_niqui\/","title":{"rendered":"El niqui"},"content":{"rendered":"<p>Pocos lo entender\u00e1n pero ocurri\u00f3. Y fue en Edimburgo, tierra de episodios misteriosos. No hace falta ser la mujer del primer ministro japon\u00e9s para que te ocurran fen\u00f3menos extra\u00f1os. Caminaba sola por las animadas calles del Edimburgo prefestivalero cuando lo v\u00ed. Estaba apoyado en el escaparate de una tienda de moda de invierno para mujeres. \u00bfQu\u00e9 hac\u00eda ah\u00ed?<\/p>\n<p>Los avisos de que est\u00e1s viviendo algo importante tardan en llegar al cerebro. Pero en aquella ocasi\u00f3n recib\u00ed un peque\u00f1o rel\u00e1mpago de luz. Y admir\u00e9 el giro que el dise\u00f1ador de aquellas prendas hab\u00eda sabido dar al tradicional estampado escoc\u00e9s. <\/p>\n<p>Al d\u00eda siguiente volv\u00ed por casualidad. La tienda estaba cerrada. Regres\u00e9 la otra ma\u00f1ana pero hab\u00edan vaciado el local.&nbsp; Descubr\u00ed con pesar que lo que yo quer\u00eda era aquel niqui de verano en tonos pastel. Lo \u00fanico que no vend\u00edan en las otras dos tiendas como aquella que descubr\u00ed en la capital escocesa. &#8216;Se lo han llevado a Glasgow&#8217;, lleg\u00f3 a decirme una dependienta. Consult\u00e9 los horarios de trenes pero la raz\u00f3n me asisti\u00f3 a tiempo. Y fren\u00e9.<\/p>\n<p>Consegu\u00ed el niqui por correo. Hoy lo he visto en el armario. No lo hab\u00eda usado en todo el verano. No tiene bolsillos pero lleva oculto alg\u00fan mensaje. Ahora intento descifrarlo.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Pocos lo entender\u00e1n pero ocurri\u00f3. Y fue en Edimburgo, tierra de episodios misteriosos. No hace falta ser la mujer del primer ministro japon\u00e9s para que te ocurran fen\u00f3menos extra\u00f1os. Caminaba sola por las animadas calles del Edimburgo prefestivalero cuando lo v\u00ed. Estaba apoyado en el escaparate de una tienda de moda de invierno para mujeres. [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[4],"class_list":["post-138","post","type-post","status-publish","format-standard","hentry","category-2","tag-1599_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/comments?post=138"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/138\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/media?parent=138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/categories?post=138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/tags?post=138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}