{"id":145,"date":"2009-10-06T11:59:06","date_gmt":"2009-10-06T11:59:06","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/masqueactualidad\/?p=145"},"modified":"2009-10-06T11:59:06","modified_gmt":"2009-10-06T11:59:06","slug":"nina_bonita","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/2009\/10\/06\/nina_bonita\/","title":{"rendered":"Ni\u00f1a bonita"},"content":{"rendered":"<p>Aquel d\u00eda decid\u00ed que quer\u00eda comer coles de Bruselas y pescado. Regresaba del mercado de San Mart\u00edn y repar\u00e9 en lo poco amigable del saludo de la vecina. Y yo que hab\u00eda pensado que me preguntar\u00eda por mi salud. La escaleras de la casa sin ascensor en que viv\u00edamos me resultaron m\u00e1s empinadas que nunca. Despu\u00e9s del almuerzo hice una llamada lac\u00f3nica.<\/p>\n<p>-Tenemos una cita.<\/p>\n<p>No recuerdo qui\u00e9n me recibi\u00f3. Qu\u00e9 costumbres. Empezar por la depilaci\u00f3n. Sexy hasta el&nbsp; final, me dije. Y encima te animan a leer para distraer la larga espera. &#8216;\u00bfQu\u00e9 he hecho de malo?&#8217; me pregunt\u00e9 al ver la sala donde se producir\u00eda el encuentro. Nunca me han gustado los potros. Cuesti\u00f3n de agilidad.<\/p>\n<p>Los caminos nunca son f\u00e1ciles, dijo el sabio. Pero recoger\u00e1s tus&nbsp; frutos. El m\u00edo lleg\u00f3 envuelto en una toalla de colores. Inuit.<\/p>\n<p>Las habitaciones, despu\u00e9s del evento, eran compartidas. Mi compa\u00f1era fue paciente con mi sobreestimulaci\u00f3n y mi alegr\u00eda.<\/p>\n<p>De aquel d\u00eda se cumplen hoy 15 a\u00f1os. Ni\u00f1a bonita.<\/p>\n<p><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Aquel d\u00eda decid\u00ed que quer\u00eda comer coles de Bruselas y pescado. Regresaba del mercado de San Mart\u00edn y repar\u00e9 en lo poco amigable del saludo de la vecina. Y yo que hab\u00eda pensado que me preguntar\u00eda por mi salud. La escaleras de la casa sin ascensor en que viv\u00edamos me resultaron m\u00e1s empinadas que nunca. [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[4],"class_list":["post-145","post","type-post","status-publish","format-standard","hentry","category-2","tag-1599_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/comments?post=145"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/145\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/media?parent=145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/categories?post=145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/tags?post=145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}