{"id":154,"date":"2009-10-20T13:36:24","date_gmt":"2009-10-20T13:36:24","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/masqueactualidad\/?p=154"},"modified":"2009-10-20T13:36:24","modified_gmt":"2009-10-20T13:36:24","slug":"zonas_bajas","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/2009\/10\/20\/zonas_bajas\/","title":{"rendered":"Zonas bajas"},"content":{"rendered":"<p>Estoy a la cola para leer el libro revelaci\u00f3n en Alemania. Una joven<br \/>\nhabla de sus almorranas y c\u00f3mo le llevaron a la pr\u00e1ctica del sexo anal,<br \/>\nasunto de moda en estos blogs. Ah\u00ed est\u00e1n los detalles y secretillos<br \/>\nrelatados en &#8216;Euskolovers&#8217;. La temperatura ha seguido aumentando<br \/>\ngracias a la secci\u00f3n &#8216;No Diva&#8217;. Que no decaiga.<\/p>\n<p>Pues bien. Si la escritora alemana habla a calz\u00f3n quitado de los<br \/>\nproblemas en sus zonas bajas, he decidido hablar sin tapujos de los<br \/>\nm\u00edos en las altas.<\/p>\n<p>Se trata de encontrar la&nbsp; f\u00f3rmula de la satisfacci\u00f3n. \u00bfSatisfacci\u00f3n? Aquietar-y-sosegar-las-pasiones&nbsp; <span class=\"eAcep\">Aquietar y sosegar las pasiones-del-\u00e1nimo (dice la RAE). Saciar-un-apetito-una-pasi\u00f3n (a\u00f1ade). <\/span>Yo la reconoc\u00ed en aquel paseo en tierras escocesas.<br \/>\nPrimero lo atribu\u00ed al idioma. Al tener que hablar en ingl\u00e9s la atenci\u00f3n era mayor. El car\u00e1cter insular no parec\u00eda motivo suficiente para sentir m\u00e1s intensamente. Y<br \/>\npor \u00faltimo, el estar sola, sin mi familia y sin ni\u00f1os, esa excusa que<br \/>\nnos permitimos los padres para perder el control o dar rienda suelta a nuestro mal humor.<\/p>\n<p>Y si se busca la satisfacci\u00f3n es porque se viene de la insatisfacci\u00f3n.<\/p>\n<p>Algo as\u00ed dir\u00eda Descartes. O, si no, el viejo Spinoza. <\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Estoy a la cola para leer el libro revelaci\u00f3n en Alemania. Una joven habla de sus almorranas y c\u00f3mo le llevaron a la pr\u00e1ctica del sexo anal, asunto de moda en estos blogs. Ah\u00ed est\u00e1n los detalles y secretillos relatados en &#8216;Euskolovers&#8217;. La temperatura ha seguido aumentando gracias a la secci\u00f3n &#8216;No Diva&#8217;. Que no [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[4],"class_list":["post-154","post","type-post","status-publish","format-standard","hentry","category-2","tag-1599_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/comments?post=154"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/154\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/media?parent=154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/categories?post=154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/tags?post=154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}