{"id":161,"date":"2010-01-22T21:24:30","date_gmt":"2010-01-22T21:24:30","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/masqueactualidad\/?p=161"},"modified":"2010-01-22T21:24:30","modified_gmt":"2010-01-22T21:24:30","slug":"explorando_el_kilimanjaro","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/2010\/01\/22\/explorando_el_kilimanjaro\/","title":{"rendered":"Explorando el Kilimanjaro"},"content":{"rendered":"<p>Hay un blog que sigo con inter\u00e9s, aunque estos d\u00edas est\u00e1 parado. Se llama <a href=\"javascript:void(0);\/*1264267237405*\/\">Explorando el Kilimanjaro <\/a>y lo escribe Guzm\u00e1n L\u00f3pez Bayarri, autor de la obra &#8216;Serendipity&#8217;. El monte m\u00e1s alto de \u00c1frica, un misterioso volc\u00e1n con nieve, ha inspirado a muchos, incluido el escritor Ernest Hemingwuay autor del relato, llevado despu\u00e9s al cine, &#8216;Las nieves del Kilimanjaro&#8217;. Estos d\u00edas se ha contado que el patr\u00f3n del &#8216;Alakrana&#8217;, Kepa Etxebarria, hab\u00eda embarcado a su gente y se encontraba en Tanzania, a punto de comenzar una escalada a este literario monte, cuando le avisaron del secuestro del barco. <\/p>\n<p>Uno nunca sabe d\u00f3nde va a estar su Kilimanjaro.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Hay un blog que sigo con inter\u00e9s, aunque estos d\u00edas est\u00e1 parado. Se llama Explorando el Kilimanjaro y lo escribe Guzm\u00e1n L\u00f3pez Bayarri, autor de la obra &#8216;Serendipity&#8217;. El monte m\u00e1s alto de \u00c1frica, un misterioso volc\u00e1n con nieve, ha inspirado a muchos, incluido el escritor Ernest Hemingwuay autor del relato, llevado despu\u00e9s al cine, [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[4],"class_list":["post-161","post","type-post","status-publish","format-standard","hentry","category-2","tag-1599_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/comments?post=161"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/161\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/media?parent=161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/categories?post=161"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/tags?post=161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}