{"id":171,"date":"2009-11-21T18:21:59","date_gmt":"2009-11-21T18:21:59","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/masqueactualidad\/?p=171"},"modified":"2009-11-21T18:21:59","modified_gmt":"2009-11-21T18:21:59","slug":"una_extrana_noticia_que_si_que_si","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/2009\/11\/21\/una_extrana_noticia_que_si_que_si\/","title":{"rendered":"Una extra\u00f1a noticia. Que s\u00ed, que s\u00ed."},"content":{"rendered":"<p>Era una noticia extra\u00f1a. Por lo menos<br \/>\n&#8216;La Vanguardia&#8217; hab\u00eda tenido el detalle de publicarla. Ocupaba un m\u00ednimo espacio en el peri\u00f3dico del jueves. Un breve, que decimos los periodistas. Aparec\u00eda, eso s\u00ed, en una p\u00e1gina impar. Las m\u00e1s elegantes.<\/p>\n<p>La noticia estaba datada en Somalia y no ten\u00eda nada que ver con el Alakrana. Informaba de que una joven de 20 a\u00f1os, acusada de adulterio, hab\u00eda muerto lapidada en p\u00fablico. La chica, divorciada, &nbsp; hab\u00eda dado a luz a un beb\u00e9 muerto. Hab\u00eda sido acusada de mantener relaciones sexuales con un soltero de 29 a\u00f1os, castigado, a su vez, con 100 latigazos. La milicia radical isl\u00e1mica Al Shabab, af\u00edn a Al Qaeda, hab\u00eda decidido. Poco dados a la&nbsp; compasi\u00f3n, hab\u00edan enterrado a la chica hasta la cintura y la hab\u00edan&nbsp; apedreado hasta la muerte. Ni en los tiempos de Goya, oiga.<\/p>\n<p>Estoy con Innerarity. Dice el fil\u00f3sofo que la globalizaci\u00f3n nos ha&nbsp; hecho l\u00edquidos, hemos dejado de ser terrestres. La justicia ha de buscar, como el agua, cauces universales. Lo que pasa en Somalia nos compete a todos. Alg\u00fan d\u00eda una noticia as\u00ed se leer\u00e1 en primera p\u00e1gina del peri\u00f3dico.<\/p>\n<p>El agua siempre encuentra su cauce. Es un consuelo.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Era una noticia extra\u00f1a. Por lo menos &#8216;La Vanguardia&#8217; hab\u00eda tenido el detalle de publicarla. Ocupaba un m\u00ednimo espacio en el peri\u00f3dico del jueves. Un breve, que decimos los periodistas. Aparec\u00eda, eso s\u00ed, en una p\u00e1gina impar. Las m\u00e1s elegantes. La noticia estaba datada en Somalia y no ten\u00eda nada que ver con el Alakrana. [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[4],"class_list":["post-171","post","type-post","status-publish","format-standard","hentry","category-2","tag-1599_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/comments?post=171"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/171\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/media?parent=171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/categories?post=171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/tags?post=171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}