{"id":172,"date":"2009-11-24T12:59:40","date_gmt":"2009-11-24T12:59:40","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/masqueactualidad\/?p=172"},"modified":"2009-11-24T12:59:40","modified_gmt":"2009-11-24T12:59:40","slug":"el_diana_las_mujeres_y_los_ninos_primero","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/2009\/11\/24\/el_diana_las_mujeres_y_los_ninos_primero\/","title":{"rendered":"El Diana. Las mujeres y los ni\u00f1os primero"},"content":{"rendered":"<p>Cuando el secuestro del Alakrana nos enteramos de que en el \u00cfndico hab\u00eda otros 9 barcos retenidos por piratas. Uno de ellos es el Diana, un buque de bandera ucraniana. El barco lleva seis meses secuestrado. Y en \u00e9l hay dos mujeres y una ni\u00f1a.<\/p>\n<p>Una de las mujeres es la cocinera. Se ha quedado embarazada por violaci\u00f3n de los piratas y necesitaba medicinas. Las hab\u00edan preparado para ella los tripulantes del Alakrana pero los corsarios las tiraron por la borda.<\/p>\n<p>En el Diana est\u00e1 embarcada la mujer del jefe de m\u00e1quinas con la hija de ambos, una ni\u00f1a de unos doce a\u00f1os. La madre le suplic\u00f3 al patr\u00f3n del Alakrana, Ricardo Blach, que se la llevara con ellos. Pero no pudo ser.<\/p>\n<p>\u00bfQui\u00e9n se preocupa de esta ni\u00f1a?<\/p>\n<p>Ahora muchos conocemos esta historia. \u00bfEs un caso que s\u00f3lo compete a Ucrania? Dice Innerarity que el mundo ha dejado de estar regido por poderes delimitados, vinculados a los Estados nacionales. No es terrestre. Se ha hecho l\u00edquido.<\/p>\n<p>Por una justicia l\u00edquida. \u00bfD\u00f3nde hay que apuntarse?<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Cuando el secuestro del Alakrana nos enteramos de que en el \u00cfndico hab\u00eda otros 9 barcos retenidos por piratas. Uno de ellos es el Diana, un buque de bandera ucraniana. El barco lleva seis meses secuestrado. Y en \u00e9l hay dos mujeres y una ni\u00f1a. Una de las mujeres es la cocinera. Se ha quedado [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[4],"class_list":["post-172","post","type-post","status-publish","format-standard","hentry","category-2","tag-1599_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/comments?post=172"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/172\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/media?parent=172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/categories?post=172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/tags?post=172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}