{"id":173,"date":"2009-11-25T11:21:56","date_gmt":"2009-11-25T11:21:56","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/masqueactualidad\/?p=173"},"modified":"2009-11-25T11:21:56","modified_gmt":"2009-11-25T11:21:56","slug":"casualidades_de_la_vida_icomo_dices","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/2009\/11\/25\/casualidades_de_la_vida_icomo_dices\/","title":{"rendered":"Casualidades de la vida. \u00bfC\u00f3mo dices?"},"content":{"rendered":"<p>Es este blog nos interesa el tema de la casualidad. Un terreno para investigar que ya ha llamado la atenci\u00f3n a otros. Dec\u00eda Freud que cuando alcanzaba alguna conclusi\u00f3n descubr\u00eda que un poeta hab\u00eda llegado all\u00ed antes. Yo tambi\u00e9n encuentro a mis poetas.<\/p>\n<p>Aqu\u00ed tienen mi pen\u00faltima casualidad. Estaba en un corrillo esperando a un conferenciante en Nazaret cuando alguien nos interrumpi\u00f3. Era una persona que ped\u00eda a mi contertulia&nbsp; que le recomendara alguna lectura. Me acerqu\u00e9 con ellos a la biblioteca y all\u00ed estaba. Un libro me esperaba. S\u00ed, s\u00ed. No es lenguaje po\u00e9tico. Es la realidad. No hab\u00eda dudas. Nada que decidir ni que pensar. Yo hab\u00eda llegado a Nazaret. Aquel libro tambi\u00e9n. El destino nos hab\u00eda juntado en lo que parec\u00eda un final feliz. \u00bfSu t\u00edtulo? &#8216;<a href=\"http:\/\/www.serendipityweb.es\/\" rel=\"external nofollow\">Serendipity&#8217;.<\/a><\/p>\n<p>Nuestra historia de amor dur\u00f3 una noche. Devor\u00e9 aquel libro con pasi\u00f3n de investigadora y al d\u00eda siguiente devolv\u00ed la publicaci\u00f3n&nbsp; a su anaquel. Dec\u00eda su autor que el tipo de episodios que dan t\u00edtulo a su libro nacen de un error. Tal vez sea \u00e9ste un buen punto de partida.<\/p>\n<p><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Es este blog nos interesa el tema de la casualidad. Un terreno para investigar que ya ha llamado la atenci\u00f3n a otros. Dec\u00eda Freud que cuando alcanzaba alguna conclusi\u00f3n descubr\u00eda que un poeta hab\u00eda llegado all\u00ed antes. Yo tambi\u00e9n encuentro a mis poetas. Aqu\u00ed tienen mi pen\u00faltima casualidad. Estaba en un corrillo esperando a un [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[4],"class_list":["post-173","post","type-post","status-publish","format-standard","hentry","category-2","tag-1599_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/comments?post=173"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/173\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/media?parent=173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/categories?post=173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/tags?post=173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}