{"id":232,"date":"2010-02-28T18:50:30","date_gmt":"2010-02-28T18:50:30","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/masqueactualidad\/?p=232"},"modified":"2010-02-28T18:50:30","modified_gmt":"2010-02-28T18:50:30","slug":"la_presentacion","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/2010\/02\/28\/la_presentacion\/","title":{"rendered":"La presentaci\u00f3n"},"content":{"rendered":"<p>Hablemos de bolos, que se lleva mucho en los blogs. &#8216;Present\u00e9 mi libro aqu\u00ed&#8217;. &#8216;Me entrevistaron all\u00e1&#8217;. &#8216;Particip\u00e9 en una tertulia radiof\u00f3nica acull\u00e1&#8217;&#8230;. Pues s\u00ed, una tambi\u00e9n tuvo su bolito. Ten\u00eda que presentar al psiquiatra Luis Rojas Marcos en la conferencia que daba en Donostia. Pertenezco al velado mundo del papel y estoy poco acostumbrada a los focos. Todo es comunicaci\u00f3n, pero hay diferencias. Tengo excusa para mi timidez: &#8216;La escuela nos machaca. No nos ense\u00f1a a hablar en p\u00fablico. Teme a la gente libre&#8217;. Lo aprend\u00ed del profesor de oratoria \u00c1ngel Lafuente.<\/p>\n<p>Una vez que di el s\u00ed refren\u00e9 un poco mi alegr\u00eda:<\/p>\n<p>-Mam\u00e1. Voy a presentar a Luis Rojas Marcos.<br \/>-\u00bfYa te atreves, hija (tono monocorde)? <br \/>-(brrrrrrrrrr)<\/p>\n<p>A los d\u00edas se lo cont\u00e9 a mi hermana. Levant\u00e9 un poco el tono.<br \/>-Presento a LRM<br \/>-\u00a1\u00a1\u00a1Qu\u00e9 viene LRM!!!! Y yo me lo voy a perder. \u00a1\u00a1Mierda!!<\/p>\n<p>Una amiga vino a casa cuando yo preparaba mis 5 minutos de gloria. \u00a1Ah! -dijo- y se march\u00f3 a tomar un vino con su novio.<\/p>\n<p>Mundo cruel.&nbsp; <\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Hablemos de bolos, que se lleva mucho en los blogs. &#8216;Present\u00e9 mi libro aqu\u00ed&#8217;. &#8216;Me entrevistaron all\u00e1&#8217;. &#8216;Particip\u00e9 en una tertulia radiof\u00f3nica acull\u00e1&#8217;&#8230;. Pues s\u00ed, una tambi\u00e9n tuvo su bolito. Ten\u00eda que presentar al psiquiatra Luis Rojas Marcos en la conferencia que daba en Donostia. Pertenezco al velado mundo del papel y estoy poco acostumbrada [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[4],"class_list":["post-232","post","type-post","status-publish","format-standard","hentry","category-2","tag-1599_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/comments?post=232"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/232\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/media?parent=232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/categories?post=232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/tags?post=232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}