{"id":239,"date":"2010-03-24T00:13:51","date_gmt":"2010-03-24T00:13:51","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/masqueactualidad\/?p=239"},"modified":"2010-03-24T00:13:51","modified_gmt":"2010-03-24T00:13:51","slug":"como_mujer_del_tiempo_no_tengo_futuro","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/2010\/03\/24\/como_mujer_del_tiempo_no_tengo_futuro\/","title":{"rendered":"Como mujer del tiempo no tengo futuro"},"content":{"rendered":"<p>Uno de los grandes momentos de una hija con una madre es el de salir de compras. La crianza y la mera existencia de la familia resultan tan absorbentes que aunque seas hija mayor, mediana o peque\u00f1a, una madre nunca tiene el tiempo suficiente para t\u00ed. Quiz\u00e1s a estos dramas (peque\u00f1os) se refer\u00eda hoy el escritor israel\u00ed David Grossman en La Contra de La Vanguardia. El autor, que perdi\u00f3 un hijo en la guerra del L\u00edbano, que defiende la paz y que critica el ambiente de hostilidad que se siembra en su pa\u00eds, asegura haber descubierto el heroismo en los detalles banales: llevar<br \/>\na tu hijo al dentista, ayudarle en los deberes. &#8220;Todo eso que damos por<br \/>\nsentado es, en el fondo, heroico&#8221;, dice <\/p>\n<p><strong><\/strong>El s\u00e1bado Berska estaba lleno de madres heroicas con sus hijas adolescentes. Yo recorr\u00ed con la m\u00eda unas cuantas tiendas y com\u00ed en un chino. No le dio tiempo a probarse unas sandalias. Hoy se las he traido a casa, previo pacto con las dependientas. A la ma\u00f1ana le hab\u00eda reprendido por salir con poca ropa &#8216;porque bajan las temperaturas&#8217;. Pero el term\u00f3metro ha subido y mucho.<\/p>\n<p>-Creo que tengo m\u00e1s futuro como compradora de sandalias que como mujer del tiempo -le he soltado cuando la he visto entrar-.<\/p>\n<p>Ella ha corrido a su cuarto a ver si yo ten\u00eda raz\u00f3n.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Uno de los grandes momentos de una hija con una madre es el de salir de compras. La crianza y la mera existencia de la familia resultan tan absorbentes que aunque seas hija mayor, mediana o peque\u00f1a, una madre nunca tiene el tiempo suficiente para t\u00ed. Quiz\u00e1s a estos dramas (peque\u00f1os) se refer\u00eda hoy el [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[4],"class_list":["post-239","post","type-post","status-publish","format-standard","hentry","category-2","tag-1599_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/comments?post=239"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/239\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/media?parent=239"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/categories?post=239"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/tags?post=239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}