{"id":259,"date":"2010-05-04T18:00:35","date_gmt":"2010-05-04T18:00:35","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/masqueactualidad\/?p=259"},"modified":"2010-05-04T18:00:35","modified_gmt":"2010-05-04T18:00:35","slug":"desayuno_buffet_en_canarias","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/2010\/05\/04\/desayuno_buffet_en_canarias\/","title":{"rendered":"Desayuno buffet en Canarias"},"content":{"rendered":"<p><P>Ocurri\u00f3 en un desayuno &#8216;s\u00edrvase usted mismo&#8217; en Tenerife Sur, como dicen los prospectos, o en Maspalomas. Ya no s\u00e9. Una se\u00f1ora -o tal vez era yo misma- esperaba con manifiesto mal humor en la cola de los huevos fritos. Y me dije: Si pasas el invierno esperando el buen tiempo y pierdes tu temple a la menor contrariedad, algo falla. Ni vives&nbsp;el invierno, ni el verano.<\/P><br \/>\n<P>As\u00ed que empec\u00e9 a&nbsp;buscar la magia&nbsp;en las cosas sencillas, el Dios de las cazuelas, el viaje interior. Pero a veces vienen d\u00edas de viento Norte como \u00e9ste, de cierzo, que dir\u00edan los oscenses. Y&nbsp;se a\u00f1oran las sandalias y las cabinas de Ondarreta, como si el sol fuera a traernos la felicidad. Y un poco es as\u00ed. En \u00c1frica, dicen, la gente vive contenta.<\/P><br \/>\n<P>Se trata de estar donde tienes que estar. Pero no siempre es f\u00e1cil. Miren a los koalas. Me remito a la 2. &#8216;Animales carism\u00e1ticos&#8217;, dec\u00eda un entrevistado en uno de esos rigurosos documentales de sobremesa. De la protecci\u00f3n han pasado a la superpoblaci\u00f3n.&nbsp;Los \u00e1rboles mueren por su apetito.&nbsp;Los atrapan y los cambian de sitio. Ha nacido el personaje &#8216;ciudador de koala&#8217;. Hay quien pide muertes selectivas, un tab\u00fa.&nbsp;As\u00ed que no nos quejemos. En todos los continentes cuecen habas. Y por cierto, bien ricas que est\u00e1n esta primavera.<\/P><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Ocurri\u00f3 en un desayuno &#8216;s\u00edrvase usted mismo&#8217; en Tenerife Sur, como dicen los prospectos, o en Maspalomas. Ya no s\u00e9. Una se\u00f1ora -o tal vez era yo misma- esperaba con manifiesto mal humor en la cola de los huevos fritos. Y me dije: Si pasas el invierno esperando el buen tiempo y pierdes tu temple [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[4],"class_list":["post-259","post","type-post","status-publish","format-standard","hentry","category-2","tag-1599_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/comments?post=259"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/259\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/media?parent=259"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/categories?post=259"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/tags?post=259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}