{"id":264,"date":"2010-05-10T20:28:30","date_gmt":"2010-05-10T20:28:30","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/masqueactualidad\/?p=264"},"modified":"2010-05-10T20:28:30","modified_gmt":"2010-05-10T20:28:30","slug":"la_musica_del_azar","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/2010\/05\/10\/la_musica_del_azar\/","title":{"rendered":"La m\u00fasica del azar"},"content":{"rendered":"<p><P>Hab\u00eda ido a Decathlon&nbsp;a comprar unas zapatillas para su hijo. Pero se le ocurri\u00f3 que bien pod\u00eda aprovechar aquella oportunidad para hacerse con un nuevo hula hop. Recordaba aquella entrevista&nbsp;de Victoria Abril: &#8216;unas semanas de hula hop y el vientre como tableta de chocolate&#8217;. En la secci\u00f3n de danza&nbsp; eligi\u00f3 el aro m\u00e1s grande. Era de color verde hospital. Hubiera preferido un contundente naranja o un favorecedor rosa. Pero eran m\u00e1s peque\u00f1os y el color no era lo importante, pens\u00f3.<\/P><br \/>\n<P>El hula hop verde comenz\u00f3 a dar resultados extraordinarios desde el primer d\u00eda. Para el s\u00e1bado se sentia como una hawaiana. Pero lleg\u00f3 el domingo. Al&nbsp;principio s\u00f3lo not\u00f3 un ligero&nbsp;malestar. \u00a1Qu\u00e9 raro!&nbsp;Este tipo de molestias hab\u00edan&nbsp;desaparecido con sus ejercicios de espalda. Pens\u00f3 en&nbsp;aquel paseo tirando de su hijo. &#8216;Nunca mais&#8217;, se dijo. Por la tarde el dolor de ri\u00f1ones presagiaba una severa lumbalgia. Y entonces relacion\u00f3. En google tecle\u00f3 &#8216;hula hop y lesi\u00f3n de espalda&#8217;. Y obtuvo la respuesta.<\/P><br \/>\n<P>El dolor era intenso cuando&nbsp;entr\u00f3 en el ba\u00f1o ansiando la posici\u00f3n horizontal. S\u00f3lo tirar de la bomba. Y a la cama. Pero, espera. \u00bfQu\u00e9 era aquello?<\/P><br \/>\n<P>Le hab\u00eda bajado la regla.<\/P><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Hab\u00eda ido a Decathlon&nbsp;a comprar unas zapatillas para su hijo. Pero se le ocurri\u00f3 que bien pod\u00eda aprovechar aquella oportunidad para hacerse con un nuevo hula hop. Recordaba aquella entrevista&nbsp;de Victoria Abril: &#8216;unas semanas de hula hop y el vientre como tableta de chocolate&#8217;. En la secci\u00f3n de danza&nbsp; eligi\u00f3 el aro m\u00e1s grande. Era [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[4],"class_list":["post-264","post","type-post","status-publish","format-standard","hentry","category-2","tag-1599_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/comments?post=264"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/264\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/media?parent=264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/categories?post=264"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/tags?post=264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}