{"id":265,"date":"2010-05-13T00:09:12","date_gmt":"2010-05-13T00:09:12","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/masqueactualidad\/?p=265"},"modified":"2010-05-13T00:09:12","modified_gmt":"2010-05-13T00:09:12","slug":"sexy_con_mi_vestido_nuevo","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/2010\/05\/13\/sexy_con_mi_vestido_nuevo\/","title":{"rendered":"Sexy con mi vestido nuevo"},"content":{"rendered":"<p><P>Lleg\u00f3 acelerada al restaurante. &#8216;P\u00eddeme una cerveza&#8217;, hab\u00eda dicho a su marido. Y la cerveza estaba en la mesa. Enseguida llegaron el sushi, las gambas al curry, la ternera agridulce y los sorbetes. Hubo que pasar la&nbsp;Concha de forma acelerada porque hab\u00eda que recoger a los ni\u00f1os. Por fin en casa. El d\u00eda del cumplea\u00f1os&nbsp;alcanzaba por fin un momento de paz. Dej\u00f3 el bolso sobre el sof\u00e1. Pero, espera. \u00bfQu\u00e9 era aquello? Una bolsa de regalo con un vestido. Su hermana hab\u00eda pasado por all\u00ed. \u00a1Qu\u00e9 detalle! \u00a1Qu\u00e9 forma tan callada de dar una alegr\u00eda! Y un vestido blanco. Ella ten\u00eda que ser. Siempre arriesgando y proponiendo. Y qu\u00e9 corto. Y qu\u00e9 ajustado. Un vestido sexy. Y ella que se hab\u00eda deprimido por el peso de los a\u00f1os. Corri\u00f3 al espejo de su cuarto.<\/P><br \/>\n<P>-\u00bfCu\u00e1ndo lo habr\u00e1 dejado? -dijo mientras se quitaba la ropa-<\/P><br \/>\n<P>Entonces escuch\u00f3 la voz de \u00e9l.<\/P><br \/>\n<P>-\u00bfY por qu\u00e9 est\u00e1s tan segura de que es de tu hermana?<\/P><br \/>\n<P>&nbsp;<\/P><br \/>\n<P>Blog escrito escuchando: &#8216;Un ramito de violetas&#8217;.<\/P><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Lleg\u00f3 acelerada al restaurante. &#8216;P\u00eddeme una cerveza&#8217;, hab\u00eda dicho a su marido. Y la cerveza estaba en la mesa. Enseguida llegaron el sushi, las gambas al curry, la ternera agridulce y los sorbetes. Hubo que pasar la&nbsp;Concha de forma acelerada porque hab\u00eda que recoger a los ni\u00f1os. Por fin en casa. El d\u00eda del cumplea\u00f1os&nbsp;alcanzaba [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[4],"class_list":["post-265","post","type-post","status-publish","format-standard","hentry","category-2","tag-1599_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/comments?post=265"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/265\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/media?parent=265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/categories?post=265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/tags?post=265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}