{"id":280,"date":"2010-06-09T10:04:12","date_gmt":"2010-06-09T10:04:12","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/masqueactualidad\/?p=280"},"modified":"2010-06-09T10:04:12","modified_gmt":"2010-06-09T10:04:12","slug":"una_pareja_se_besa_en_holland_park","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/2010\/06\/09\/una_pareja_se_besa_en_holland_park\/","title":{"rendered":"Una pareja se besa en Holland Park"},"content":{"rendered":"<p><P>Ayer recib\u00ed un regalo. Yo andaba por la casa poniendo lavadoras (destendiendo-emparejando calcetines-recogiendo ropa-vaciando el carrito de la compra-preparando mochilas-ay-la-vida-dom\u00e9stica) cuando mi hija &#8216;teen&#8217; me llam\u00f3 a su cuarto. Las madres siempre acudimos al&nbsp;cuarto de los hijos hasta que un rayo de lucidez nos invita un d\u00eda a contestar: &#8216;\u00bfY por qu\u00e9 no vienes t\u00fa?&#8217;. Ella me esperaba&nbsp;en el umbral de puerta, como para parar un gol. No se trata de desperdiciar los raros momentos de intimidad que la vida moderna nos depara-. Bland\u00eda un libro.<\/P><br \/>\n<P>-Toma. Es tu diccionario. No me cabe en la balda.<\/P><br \/>\n<P>Babuc\u00ed algo. &#8216;Es el mejor de los diccionarios de ingl\u00e9s. Sin traducci\u00f3n. Lleva un poco m\u00e1s de&nbsp;tiempo pero merece la pena&#8217;.<\/P><br \/>\n<P>-Yo ya tengo mi favorito -dijo se\u00f1alando la versi\u00f3n espa\u00f1ol\/ingl\u00e9s, ingl\u00e9s\/espa\u00f1ol que yo misma hab\u00eda comprado-.<\/P><br \/>\n<P>No quise insistir. Acarici\u00e9 el diccionario, mi Longman Dictionary of English Languaje and Culture. &#8216;London, July 2004&#8217;, hab\u00eda escrito en su primera p\u00e1gina. Vida entusiasta y esforzada. Aquellos deberes de ingl\u00e9s con las neuronas apaleadas&nbsp;por las clases de la jornada. Peque\u00f1o tesoro.<\/P><br \/>\n<P>&nbsp;<\/P><br \/>\n<P>&nbsp;<\/P><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Ayer recib\u00ed un regalo. Yo andaba por la casa poniendo lavadoras (destendiendo-emparejando calcetines-recogiendo ropa-vaciando el carrito de la compra-preparando mochilas-ay-la-vida-dom\u00e9stica) cuando mi hija &#8216;teen&#8217; me llam\u00f3 a su cuarto. Las madres siempre acudimos al&nbsp;cuarto de los hijos hasta que un rayo de lucidez nos invita un d\u00eda a contestar: &#8216;\u00bfY por qu\u00e9 no vienes t\u00fa?&#8217;. [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[4],"class_list":["post-280","post","type-post","status-publish","format-standard","hentry","category-2","tag-1599_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/comments?post=280"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/280\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/media?parent=280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/categories?post=280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/tags?post=280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}