{"id":334,"date":"2011-01-17T07:19:52","date_gmt":"2011-01-17T07:19:52","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/masqueactualidad\/?p=334"},"modified":"2011-01-17T07:19:52","modified_gmt":"2011-01-17T07:19:52","slug":"que_ganen_los_nuestros_oe","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/2011\/01\/17\/que_ganen_los_nuestros_oe\/","title":{"rendered":"Que ganen los nuestros, o\u00e9"},"content":{"rendered":"<p><IMG src=\"\/masqueactualidad\/wp-content\/uploads\/sites\/4\" width=\"200\" height=\"NaN\">Nunca he tenido esp\u00edritu deportivo. Pero casi todo lo que no tuve lo<br \/>\nquiero ahora. En el colegio, con una profesora de gimnasia que manten\u00eda su &#8216;look&#8217; de&nbsp; peluquer\u00eda, nos apuntamos a una competici\u00f3n femenina de voleibol. Acud\u00edamos con m\u00e1s verg\u00fcenza que af\u00e1n de competici\u00f3n. El bal\u00f3n siempre se iba hacia el lugar contrario y d\u00e1bamos buena cuenta, al menos yo, de la teor\u00eda de las profec\u00edas autocumplidas: cada d\u00eda nos sal\u00eda peor. <\/p>\n<p>Recuerdo tambi\u00e9n una carrera sobre patines de hielo en la que part\u00ed con buenas posibilidades. En los \u00faltimos metros s\u00f3lo qued\u00e1bamos mi mejor amiga y yo. El p\u00fablico me aclamaba pero antes de llegar a la meta algo me fren\u00f3. Mi mente informaba de que no pod\u00eda ganar a mi querida colega. Pero por detr\u00e1s de aquella voz pude percibir que lo que me retuvo fue el miedo al fracaso.<\/p>\n<p>Observo ahora que los grandes partidos son aquellos que no se dan por perdidos. Que aunque duela, es mejor perder luchando. Y lo bueno que es ganar, sobre todo si te lo has peleado.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Nunca he tenido esp\u00edritu deportivo. Pero casi todo lo que no tuve lo quiero ahora. En el colegio, con una profesora de gimnasia que manten\u00eda su &#8216;look&#8217; de&nbsp; peluquer\u00eda, nos apuntamos a una competici\u00f3n femenina de voleibol. Acud\u00edamos con m\u00e1s verg\u00fcenza que af\u00e1n de competici\u00f3n. El bal\u00f3n siempre se iba hacia el lugar contrario y [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[4],"class_list":["post-334","post","type-post","status-publish","format-standard","hentry","category-2","tag-1599_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/comments?post=334"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/334\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/media?parent=334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/categories?post=334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/tags?post=334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}