{"id":346,"date":"2011-01-30T19:17:07","date_gmt":"2011-01-30T19:17:07","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/masqueactualidad\/?p=346"},"modified":"2011-01-30T19:17:07","modified_gmt":"2011-01-30T19:17:07","slug":"brindar_con_un_alma","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/2011\/01\/30\/brindar_con_un_alma\/","title":{"rendered":"Brindar con un alma"},"content":{"rendered":"<p><IMG src=\"\/masqueactualidad\/wp-content\/uploads\/sites\/4\" width=\"150\">Le tomo prestado el t\u00edtulo a Jon Sistiaga, un t\u00edtulo como de &#8216;Ghost&#8217; que us\u00f3 ayer en &#8216;El Pa\u00eds&#8217; para narrar sus impresiones en la reconstrucci\u00f3n del crimen de Jos\u00e9 Couso, 8 a\u00f1os despu\u00e9s. De la muerte de Juantxu Rodr\u00edguez en la invasi\u00f3n estadounidense de Panam\u00e1 se han cumplido 20 y nunca hubo reconstrucci\u00f3n. Faltaron los papeles &#8216;Wikileaks&#8217; de todo aquello.<\/p>\n<p>De las guerras no sale nada bueno. Yo iba a hablar de las guerras interiores aunque en todas ellas prefiero los tiempos de paz. Estos d\u00edas narraba un desaire telef\u00f3nico que me llev\u00f3 a imaginar&nbsp; respuestas airadas para restituir el honor perdido. Dice la RAE que el honor es la cualidad moral que lleva a cumplir los prop\u00ecos deberes respecto de uno mismo. Me debo una. Y no deber\u00eda olvidarlo. Pero&#8230; \u00a1qu\u00e9 buenos son los tiempos de paz!<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Le tomo prestado el t\u00edtulo a Jon Sistiaga, un t\u00edtulo como de &#8216;Ghost&#8217; que us\u00f3 ayer en &#8216;El Pa\u00eds&#8217; para narrar sus impresiones en la reconstrucci\u00f3n del crimen de Jos\u00e9 Couso, 8 a\u00f1os despu\u00e9s. De la muerte de Juantxu Rodr\u00edguez en la invasi\u00f3n estadounidense de Panam\u00e1 se han cumplido 20 y nunca hubo reconstrucci\u00f3n. Faltaron [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[4],"class_list":["post-346","post","type-post","status-publish","format-standard","hentry","category-2","tag-1599_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/comments?post=346"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/346\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/media?parent=346"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/categories?post=346"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/tags?post=346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}