{"id":35,"date":"2009-04-18T17:09:19","date_gmt":"2009-04-18T17:09:19","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/masqueactualidad\/?p=35"},"modified":"2009-04-18T17:09:19","modified_gmt":"2009-04-18T17:09:19","slug":"abuela_corin","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/2009\/04\/18\/abuela_corin\/","title":{"rendered":"Abuela Cor\u00edn"},"content":{"rendered":"<p>Es una lata que todo el mundo cite a Shakespeare o a Ch\u00e9jov. Ahora que se ha muerto, tendr\u00edamos que hacer de Cor\u00edn Tellado un cl\u00e1sico. Si hasta escribi\u00f3 novelas er\u00f3ticas. Y mira qu\u00e9 lejos lleg\u00f3 Henry Miller con la historia de una erecci\u00f3n.<\/p>\n<p>Me parece que las madres de familia que rompen moldes merecen otro tratamiento. La abuela Cor\u00edn con su pelo de peluquer\u00eda ha resultado tan le\u00edda como Cervantes. \u00bfQu\u00e9 siempre escrib\u00eda sobre el amor? \u00bfQue no cuidaba mucho las formas ling\u00fc\u00edsticas? A otros se les perdonan estas minucias. Hay escritores a los que ni siquiera se les entiende, como ella sol\u00eda destacar.<\/p>\n<p>Yo suelo acordarme del caso de Mar\u00eda Moliner. Cuando no le admitieron en la RAE respir\u00f3 tranquila. &#8220;S\u00f3lo soy una se\u00f1ora que remienda calcetines&#8221;, dijo.<\/p>\n<p><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Es una lata que todo el mundo cite a Shakespeare o a Ch\u00e9jov. Ahora que se ha muerto, tendr\u00edamos que hacer de Cor\u00edn Tellado un cl\u00e1sico. Si hasta escribi\u00f3 novelas er\u00f3ticas. Y mira qu\u00e9 lejos lleg\u00f3 Henry Miller con la historia de una erecci\u00f3n. Me parece que las madres de familia que rompen moldes merecen [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[4],"class_list":["post-35","post","type-post","status-publish","format-standard","hentry","category-2","tag-1599_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/35","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/comments?post=35"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/35\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/media?parent=35"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/categories?post=35"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/tags?post=35"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}