{"id":350,"date":"2011-02-03T07:48:59","date_gmt":"2011-02-03T07:48:59","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/masqueactualidad\/?p=350"},"modified":"2011-02-03T07:48:59","modified_gmt":"2011-02-03T07:48:59","slug":"y_mi_lugar_favorito_de_san_sebastian_es","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/2011\/02\/03\/y_mi_lugar_favorito_de_san_sebastian_es\/","title":{"rendered":"Y mi lugar favorito de San Sebasti\u00e1n es&#8230;"},"content":{"rendered":"<p><IMG src=\"\/masqueactualidad\/wp-content\/uploads\/sites\/4\" width=\"150\">El martes en el programa &#8216;Keridos monstruos&#8217; del colega bloguero Mitxel Ezquiaga se hac\u00eda una encuesta de mucho fuste. &#8216;\u00bfCu\u00e1l es su lugar favorito de San Sebasti\u00e1n?&#8217;, preguntaba la reportera Estrella Inchausti a los viandantes. La cuesti\u00f3n me la vengo planteando desde hace&nbsp; tiempo. Y soy fiel a una escena de la adolescencia, o as\u00ed. A pesar de que la ciudad y yo tanto hemos cambiado. \u00bfMi lugar? Los jardines de Ondarreta. Mira que han puesto barreras naturales contra la arena invasora. Mira que las especies de los parterres son como las del desierto, resistentes a los elementos. Me veo con mi uniforme y los calcetines al tobillo, una tarde de septiembre postveraniega descubriendo que la vida no se acaba con la vuelta al cole.<\/p>\n<p>Ayer acud\u00ed a la gasolinera modernista de Zurriola y, aunque estaba en obras, \u00a1oh, maravilla! El escenario de la playa abierta al mar con las enormes olas pis\u00f3 fuerte en mi r\u00e1nking. Otro regalo, esta vez en febrero.<\/p>\n<p>Que me llamen \u00f1o\u00f1ostiarra. \u00bfCu\u00e1l es tu sitio?<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El martes en el programa &#8216;Keridos monstruos&#8217; del colega bloguero Mitxel Ezquiaga se hac\u00eda una encuesta de mucho fuste. &#8216;\u00bfCu\u00e1l es su lugar favorito de San Sebasti\u00e1n?&#8217;, preguntaba la reportera Estrella Inchausti a los viandantes. La cuesti\u00f3n me la vengo planteando desde hace&nbsp; tiempo. Y soy fiel a una escena de la adolescencia, o as\u00ed. [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[4],"class_list":["post-350","post","type-post","status-publish","format-standard","hentry","category-2","tag-1599_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/comments?post=350"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/350\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/media?parent=350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/categories?post=350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/tags?post=350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}