{"id":358,"date":"2011-02-15T08:15:52","date_gmt":"2011-02-15T08:15:52","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/masqueactualidad\/?p=358"},"modified":"2011-02-15T08:15:52","modified_gmt":"2011-02-15T08:15:52","slug":"cambio_vestido_minifaldero_por_relatos_d","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/2011\/02\/15\/cambio_vestido_minifaldero_por_relatos_d\/","title":{"rendered":"Cambio vestido minifaldero por relatos de Roald Dahl"},"content":{"rendered":"<p><IMG src=\"\/masqueactualidad\/wp-content\/uploads\/sites\/4\" vspace=\"3\" width=\"150\" align=\"left\" hspace=\"3\">Una profesora australiana de ingl\u00e9s nos reparti\u00f3 un d\u00eda un cuento a cada uno de la clase. A m\u00ed me toc\u00f3 &#8216;La se\u00f1ora Bixby y el coronel&#8217;, un relato de Roald Dahl, el autor de &#8216;Charly y la f\u00e1brica de chocolate&#8217;.<\/p>\n<p>Me he acordado mucho de aquel cuento. Su factor inesperado me conmovi\u00f3. Ten\u00eda una cuenta pendiente con el escritor gal\u00e9s, que leg\u00f3 derechos de autor a proyectos de ayuda a ni\u00f1os enfermos. El otro d\u00eda la sald\u00e9.<\/p>\n<p>Mi hija llevaba tiempo pidi\u00e9ndome un vestido minifaldero que vio en su d\u00eda en el ba\u00fal vintage de recuerdos del pasado. Yo sol\u00eda decirle que me gustar\u00eda tener alguno de los libros de Dahl que ley\u00f3 en clase.<\/p>\n<p>Este fin de semana se produjo el intercambio.<\/p>\n<p>Estoy leyendo &#8216;Tatuaje&#8217;. La historia me resulta misteriosamente cercana. Llego al final. Terreno conocido.<\/p>\n<p>Mi hija, tambi\u00e9n impresionada, me lo hab\u00eda contado.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Una profesora australiana de ingl\u00e9s nos reparti\u00f3 un d\u00eda un cuento a cada uno de la clase. A m\u00ed me toc\u00f3 &#8216;La se\u00f1ora Bixby y el coronel&#8217;, un relato de Roald Dahl, el autor de &#8216;Charly y la f\u00e1brica de chocolate&#8217;. Me he acordado mucho de aquel cuento. Su factor inesperado me conmovi\u00f3. Ten\u00eda una [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[4],"class_list":["post-358","post","type-post","status-publish","format-standard","hentry","category-2","tag-1599_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/comments?post=358"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/358\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/media?parent=358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/categories?post=358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/tags?post=358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}