{"id":376,"date":"2011-03-28T08:01:15","date_gmt":"2011-03-28T08:01:15","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/masqueactualidad\/?p=376"},"modified":"2011-03-28T08:01:15","modified_gmt":"2011-03-28T08:01:15","slug":"blanco_terso_y_sensual","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/2011\/03\/28\/blanco_terso_y_sensual\/","title":{"rendered":"Blanco, terso y sensual"},"content":{"rendered":"<p><IMG src=\"\/masqueactualidad\/wp-content\/uploads\/sites\/4\" vspace=\"3\" width=\"150\" align=\"left\" hspace=\"3\">Iba de paso. No era mi intenci\u00f3n. \u00c9l llam\u00f3 mi atenci\u00f3n. Casi paso de largo pero me di la vuelta. Ah\u00ed estaba con unos compa\u00f1eros. Hab\u00edan venido de distintos pa\u00edses y nacionalidades. La primavera les impulsaba. Y me los llev\u00e9.<\/p>\n<p>Fornidos y entrados en carnes, respond\u00edan a modas del pasado: Kate Moss no reinar\u00eda entre ellos. Los dej\u00e9 reposar durante unos d\u00edas. Encontrarse con ellos era alegrar la vista: prodigio de la naturaleza. Hube de escuchar alguna burla, tan singulares.<\/p>\n<p>Y por fin lleg\u00f3 el d\u00eda. Aqu\u00ed los ten\u00eda, cerca de mi mano. Tom\u00e9 con cuidado a aquel que tanto me hab\u00eda gustado. Y comenc\u00e9 por \u00e9l. Apenas se necesitaron pre\u00e1mbulos, sabia naturaleza. En un momento estuvo listo. Me atrev\u00ed en seguida con sus semejantes, ocho, diez, el recuerdo es caprichoso. Ya estaban preparados, el ritual no consumi\u00f3 tiempo.<\/p>\n<p>Y por fin se produjo el encuentro. Levant\u00e9 al rey de reyes y lo introduje en mi boca. Qu\u00e9 sabor. Delicado e intenso. La primavera, chica, la sangre altera.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Iba de paso. No era mi intenci\u00f3n. \u00c9l llam\u00f3 mi atenci\u00f3n. Casi paso de largo pero me di la vuelta. Ah\u00ed estaba con unos compa\u00f1eros. Hab\u00edan venido de distintos pa\u00edses y nacionalidades. La primavera les impulsaba. Y me los llev\u00e9. Fornidos y entrados en carnes, respond\u00edan a modas del pasado: Kate Moss no reinar\u00eda entre [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[4],"class_list":["post-376","post","type-post","status-publish","format-standard","hentry","category-2","tag-1599_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/comments?post=376"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/376\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/media?parent=376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/categories?post=376"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/tags?post=376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}