{"id":379,"date":"2011-04-05T09:38:08","date_gmt":"2011-04-05T09:38:08","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/masqueactualidad\/?p=379"},"modified":"2011-04-05T09:38:08","modified_gmt":"2011-04-05T09:38:08","slug":"unas_vainas_en_version_rapida","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/2011\/04\/05\/unas_vainas_en_version_rapida\/","title":{"rendered":"Unas vainas en versi\u00f3n r\u00e1pida"},"content":{"rendered":"<p><IMG src=\"\/masqueactualidad\/wp-content\/uploads\/sites\/4\" vspace=\"3\" width=\"150\" align=\"left\" hspace=\"3\">Ya voy por mi segunda lectura. No me pasa con ning\u00fan otro libro. Y menos mal que ayer tropec\u00e9 con &#8216;Historias de Londres&#8217;, de Enric Gonz\u00e1lez, en una balda de casa y dej\u00e9 a un lado la segunda vuelta de mi libro favorito. Este respiro me sirvi\u00f3 para recordar qu\u00e9 feliz fui en Holland Park. \u00a1Qu\u00e9 \u00e1rboles, chica!.<\/p>\n<p>\u00bfMi libro favorito? Perdamos lectores: hablemos de Blay Fontcuberta. &#8216;Cart\u00f3grafo de la conciencia&#8217;, dicen unos. &#8216;Simplezas&#8217;, &#8216;cosas que todos sabemos&#8217;, &#8216;un catecismo bien intencionado&#8217;, responden otros. Por no hablar de sus titulares: &#8216;Despertar y sendero de realizaci\u00f3n. Una trayectoria personal&#8217;. (\u00cdndigo). Jo. <\/p>\n<p>Para m\u00ed Blay combina con todo. Hasta con las vainas. La conciencia aplicada a la jud\u00eda verde. Ayer me lo propuse. Cocinar llevando las riendas. Ten\u00eda mis bolsas de verdura troceada: madre trabajadora, al fin. Cayeron en la olla con el piloto autom\u00e1tico. \u00bfQui\u00e9n dijo &#8216;f\u00e1cil&#8217;?<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Ya voy por mi segunda lectura. No me pasa con ning\u00fan otro libro. Y menos mal que ayer tropec\u00e9 con &#8216;Historias de Londres&#8217;, de Enric Gonz\u00e1lez, en una balda de casa y dej\u00e9 a un lado la segunda vuelta de mi libro favorito. Este respiro me sirvi\u00f3 para recordar qu\u00e9 feliz fui en Holland Park. [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[4],"class_list":["post-379","post","type-post","status-publish","format-standard","hentry","category-2","tag-1599_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/comments?post=379"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/379\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/media?parent=379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/categories?post=379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/tags?post=379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}