{"id":384,"date":"2011-04-12T09:44:07","date_gmt":"2011-04-12T09:44:07","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/masqueactualidad\/?p=384"},"modified":"2011-04-12T09:44:07","modified_gmt":"2011-04-12T09:44:07","slug":"ibasura_a_mi_que_me_registren","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/2011\/04\/12\/ibasura_a_mi_que_me_registren\/","title":{"rendered":"&#039;\u00bfBasura? A m\u00ed que me registren&#039;"},"content":{"rendered":"<p><IMG src=\"\/masqueactualidad\/wp-content\/uploads\/sites\/4\" vspace=\"3\" width=\"150\" align=\"right\" hspace=\"3\">Este verano en la playa de La Barceloneta asist\u00ed a la estampa del ocaso de una civilizaci\u00f3n: ah\u00ed hab\u00eda m\u00e1s basura que personas. Colillas, bolsas de pl\u00e1stico, latas de Coca-cola, botellas de agua&#8230;. Seguramente los efectivos de limpieza habr\u00edan hecho su trabajo y aquella muestra eran los desechos del d\u00eda. Pens\u00e9: &#8216;Yo soy Hereu y hago algo&#8217;. Campa\u00f1as imaginativas, llamadas al arrojo ciudadano, las cl\u00e1sicas multas o las sanciones tecnol\u00f3gicas (b\u00fasqueda de adn, tipo Hernani). Cualquier cosa menos eso. Ni yo misma pod\u00eda desarrollar una de mis man\u00edas m\u00e1s incomprendidas tipo boy scout: retirar la lata que otro dej\u00f3.<\/p>\n<p>No s\u00e9 por qu\u00e9 relaciono esto con la pel\u00edcula &#8216;Inside job&#8217;, que vi en versi\u00f3n original (gracias, Sade) en el Trueba. Una peli de buenos y malos. Los malos, ya se sabe, los financieros sin escr\u00fapulos. Y los profesores de Econom\u00eda de las Universidades de Harvard y Columbia que ampararon con sus teor\u00edas la deshonesta rapi\u00f1a: hasta daban pena tartamudeando frente a periodistas agresivos al estilo Michael Moore. <\/p>\n<p>Basura abandonada y patios de casa con siete avionetas (las de los financieros). A\u00fan me pregunto qu\u00e9 tendr\u00e1n que ver.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Este verano en la playa de La Barceloneta asist\u00ed a la estampa del ocaso de una civilizaci\u00f3n: ah\u00ed hab\u00eda m\u00e1s basura que personas. Colillas, bolsas de pl\u00e1stico, latas de Coca-cola, botellas de agua&#8230;. Seguramente los efectivos de limpieza habr\u00edan hecho su trabajo y aquella muestra eran los desechos del d\u00eda. Pens\u00e9: &#8216;Yo soy Hereu y [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[4],"class_list":["post-384","post","type-post","status-publish","format-standard","hentry","category-2","tag-1599_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/comments?post=384"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/384\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/media?parent=384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/categories?post=384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/tags?post=384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}