{"id":409,"date":"2011-06-13T07:24:37","date_gmt":"2011-06-13T07:24:37","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/masqueactualidad\/?p=409"},"modified":"2011-06-13T07:24:37","modified_gmt":"2011-06-13T07:24:37","slug":"de_bastones_de_mando_y_otras_historias","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/2011\/06\/13\/de_bastones_de_mando_y_otras_historias\/","title":{"rendered":"De bastones de mando y otras historias"},"content":{"rendered":"<p><IMG src=\"\/masqueactualidad\/wp-content\/uploads\/sites\/4\" align=\"left\" vspace=\"3\" width=\"250\" hspace=\"3\">Dec\u00eda Mario Vargas Llosa que lo que menos le gusta de los indignados es que pongan en cuesti\u00f3n la democracia en Espa\u00f1a: un bien logrado despu\u00e9s de 40 a\u00f1os de franquismo. Pues bien, el s\u00e1bado a las 9 de la ma\u00f1ana, con toda la ret\u00f3rica institucional de las grandes ocasiones, en el Ayuntamiento de Donostia se asisti\u00f3 a un momento cumbre dentro de la cosa democr\u00e1tica, la elecci\u00f3n del nuevo alcalde de la ciudad. Nuevos tiempos para una ciudad que fue azotada por ETA y a los que el alcalde saliente, Od\u00f3n Elorza, contribuy\u00f3 hablando de paz y enfrent\u00e1ndose a los violentos. Cuando esos tiempos llegan, la tarea de administrar los resultados suele tocar a otros.<\/p>\n<p>Estamos en el d\u00eda &#8216;0&#8217; de los nuevos tiempos. Que sea para bien.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Dec\u00eda Mario Vargas Llosa que lo que menos le gusta de los indignados es que pongan en cuesti\u00f3n la democracia en Espa\u00f1a: un bien logrado despu\u00e9s de 40 a\u00f1os de franquismo. Pues bien, el s\u00e1bado a las 9 de la ma\u00f1ana, con toda la ret\u00f3rica institucional de las grandes ocasiones, en el Ayuntamiento de Donostia [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[4],"class_list":["post-409","post","type-post","status-publish","format-standard","hentry","category-2","tag-1599_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/comments?post=409"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/409\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/media?parent=409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/categories?post=409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/tags?post=409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}