{"id":416,"date":"2011-06-27T10:05:02","date_gmt":"2011-06-27T10:05:02","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/masqueactualidad\/?p=416"},"modified":"2011-06-27T10:05:02","modified_gmt":"2011-06-27T10:05:02","slug":"desde_la_pasarela_de_mompas_al_infinito_","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/2011\/06\/27\/desde_la_pasarela_de_mompas_al_infinito_\/","title":{"rendered":"Desde la pasarela de Momp\u00e1s al infinito y mucho m\u00e1s"},"content":{"rendered":"<p><IMG src=\"\/masqueactualidad\/wp-content\/uploads\/sites\/4\" vspace=\"3\" width=\"200\" align=\"right\" hspace=\"3\">El tema est\u00e1 candente. \u00bfS\u00ed o no a la pasarela de Momp\u00e1s? La obra est\u00e1 adjudicada y tiene financiaci\u00f3n y s\u00f3lo necesita el pl\u00e1cet del nuevo gobierno municipal. Si no se ejecuta, la empresa adjudicataria tendr\u00e1 que ser indemnizada. <\/p>\n<p>Es raro que un donostiarra no tenga opini\u00f3n sobre alguno de los proyectos que afectan a la ciudad, sea la elecci\u00f3n de una nueva baldosa para las aceras o una ambiciosa actuaci\u00f3n como la de Momp\u00e1s. Ser\u00e1 que a la ciudad se le quiere mucho. Otros dir\u00e1n que los guipuzcoanos somos m\u00e1s de pensar que de hacer.<\/p>\n<p>Como con otros tantos temas, empec\u00e9 a mirar el proyecto friamente y con distancia. Con el tiempo pens\u00e9 que una actuaci\u00f3n as\u00ed -un lujo para una ciudad- puede entenderse como un rasgo de humildad y de homenaje a la madre naturaleza por parte de una sociedad devoradora. Supongo que la obra del paseo Nuevo tendr\u00eda sus detractores y la del peine de los Vientos, tambi\u00e9n. El debate est\u00e1 abierto. Que sea para bien.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El tema est\u00e1 candente. \u00bfS\u00ed o no a la pasarela de Momp\u00e1s? La obra est\u00e1 adjudicada y tiene financiaci\u00f3n y s\u00f3lo necesita el pl\u00e1cet del nuevo gobierno municipal. Si no se ejecuta, la empresa adjudicataria tendr\u00e1 que ser indemnizada. Es raro que un donostiarra no tenga opini\u00f3n sobre alguno de los proyectos que afectan a [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[4],"class_list":["post-416","post","type-post","status-publish","format-standard","hentry","category-2","tag-1599_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/comments?post=416"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/416\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/media?parent=416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/categories?post=416"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/tags?post=416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}