{"id":55,"date":"2008-10-27T13:53:11","date_gmt":"2008-10-27T13:53:11","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/masqueactualidad\/?p=55"},"modified":"2008-10-27T13:53:11","modified_gmt":"2008-10-27T13:53:11","slug":"el_pancreas_de_chavela_vargas","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/2008\/10\/27\/el_pancreas_de_chavela_vargas\/","title":{"rendered":"El p\u00e1ncreas de Chavela Vargas"},"content":{"rendered":"<p>&#8220;No lloro porque soy muy mujer&#8221;. <font color=\"#ff6600\">Chavela Vargas<\/p>\n<p><\/font>El viaje al otro lado del Atl\u00e1ntico ofreci\u00f3 unos cuantos frutos. Y no me refiero a la estancia en aquella ciudad del sur de los Estados Unidos no apta para turistas. Sino al desplazamiento en s\u00ed.<\/p>\n<p>Cuando a las 6 de la ma\u00f1ana Julia y yo nos instalamos en el taxi que nos llevar\u00eda a Bilbao, sonaba el disco de Chavela Vargas que llevaba tiempo buscando. Lo hab\u00eda regalado o as\u00ed El Pa\u00eds y a m\u00ed me quedaba s\u00f3lo la caja y el recuerdo de una punzada al aparato digestivo o reproductor. Canta con los ovarios, dec\u00edan de Mar\u00eda&nbsp; Jim\u00e9nez.  Si esto era as\u00ed, Vargas cantar\u00eda con el est\u00f3mago. O con alg\u00fan \u00f3rgano menos conocido y m\u00e1s poderoso. El p\u00e1ncreas tal vez.<\/p>\n<p>La RAE dice del p\u00e1ncreas que se trata de una gl\u00e1ndula. Y, como tal, produce una secreci\u00f3n. Nuestro \u00f3rgano realiza un doble trabajo. Una parte de sus jugos van al intestino y contribuyen a la digesti\u00f3n. Con los otros produce una hormona, la insulina, cuya funci\u00f3n es impedir que aumente la cantidad de glucosa en la sangre.<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&#8220;No lloro porque soy muy mujer&#8221;. Chavela Vargas El viaje al otro lado del Atl\u00e1ntico ofreci\u00f3 unos cuantos frutos. Y no me refiero a la estancia en aquella ciudad del sur de los Estados Unidos no apta para turistas. Sino al desplazamiento en s\u00ed. Cuando a las 6 de la ma\u00f1ana Julia y yo nos [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[4],"class_list":["post-55","post","type-post","status-publish","format-standard","hentry","category-2","tag-1599_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/55","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/comments?post=55"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/55\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/media?parent=55"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/categories?post=55"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/tags?post=55"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}