{"id":56,"date":"2008-11-20T12:22:57","date_gmt":"2008-11-20T12:22:57","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/masqueactualidad\/?p=56"},"modified":"2008-11-20T12:22:57","modified_gmt":"2008-11-20T12:22:57","slug":"la_solitaria_era_yo","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/2008\/11\/20\/la_solitaria_era_yo\/","title":{"rendered":"La solitaria era yo"},"content":{"rendered":"<p>\u2018He fracasado muchas veces, es cierto, pero no me da miedo volver a equivocarme; con el miedo no se puede vivir. Vivir es enfrentarse al riesgo y asumir los fracasos\u2019. <font color=\"#ff6600\">Francis Ford Coppola<\/font><\/p>\n<p>El desperador son\u00f3 a las 5 de la ma\u00f1ana. Me hab\u00eda costado quedarme dormida. La habitaci\u00f3n ten\u00eda vistas a un parking desierto con las farolas encendidas en horas de luz y un gran vaso de cart\u00f3n de alguna empresa de comida r\u00e1pida tirado en el centro. Ya no pude&nbsp; conciliar el sue\u00f1o.<\/p>\n<p>Como esos hombres amanerados que ven gays por todas partes, le\u00eda continuamente libros sobre la felicidad y mi habitual estado era el del estr\u00e9s y la negatividad. Hab\u00eda recibido una beca de Oil of Ulay para escribir sobre la alegr\u00eda. Abr\u00ed el libro de K al azar. Con \u00e9l me pasaba como con la revista Elle, nunca sab\u00eda si la hab\u00eda le\u00eddo antes. <\/p>\n<p>-Cuando realmente quieres hacer algo y lo persigues, encontrar\u00e1s que ocurre algo milagroso. En el momento en que te aventuras, la vida viene en tu ayuda de varias maneras.<\/p>\n<p>Mir\u00e9 a Julia. Y despu\u00e9s, al vaso abandonado en el parking.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>\u2018He fracasado muchas veces, es cierto, pero no me da miedo volver a equivocarme; con el miedo no se puede vivir. Vivir es enfrentarse al riesgo y asumir los fracasos\u2019. Francis Ford Coppola El desperador son\u00f3 a las 5 de la ma\u00f1ana. Me hab\u00eda costado quedarme dormida. La habitaci\u00f3n ten\u00eda vistas a un parking desierto [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[4],"class_list":["post-56","post","type-post","status-publish","format-standard","hentry","category-2","tag-1599_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/56","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/comments?post=56"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/56\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/media?parent=56"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/categories?post=56"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/tags?post=56"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}