{"id":74,"date":"2009-03-03T13:36:28","date_gmt":"2009-03-03T13:36:28","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/masqueactualidad\/?p=74"},"modified":"2009-03-03T13:36:28","modified_gmt":"2009-03-03T13:36:28","slug":"atapuerca","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/2009\/03\/03\/atapuerca\/","title":{"rendered":"Atapuerca"},"content":{"rendered":"<p>\u00abEra una pose; lo que yo sab\u00eda y no dec\u00eda a nadie, era que alg\u00fan d\u00eda me casar\u00eda y mi marido se ocupar\u00eda de velar por mi porvenir y asegurar mi bienestar econ\u00f3mico\u00bb. <font color=\"#ff6600\">Clara Us\u00f3n<\/font>. \u2018Coraz\u00f3n de napalm\u2019<\/p>\n<p>Me lo dijo un psiquiatra que investigaba las causas del autismo. Para entonces yo hab\u00eda dejado apartados mis convencimientos feministas en busca de la s\u00edntesis. El hacha de guerra desenterrada pesaba demasiado. <\/p>\n<p>\u2013Ellas \u2013me dijo este hombre eminente\u2013 llevan&nbsp; en los genes desde Atapuerca su pasado en la cueva criando a los hijos y conversando con gru\u00f1idos. Ellos, tienen grabado en sus c\u00e9lulas los mapas de situaci\u00f3n para evitar que les diera caza un mamut.<\/p>\n<p>\u2013 Mum&#8230;.<\/p>\n<p>\u2013Por eso ellas son buenas en comunicaci\u00f3n y cuidados y ellos son excelentes ingenieros.<\/p>\n<p>Llegaba el D\u00eda de la Mujer. Ten\u00eda que ocuparme del tradicional reportaje. Record\u00e9 una reflexi\u00f3n de un darwiniano: &#8216;Lo que nos une a una mosca es realmente sorprendente&#8217;. \u00bfC\u00f3mo pod\u00eda ser entonces que aquella cueva de Atapuerca siguiera separ\u00e1ndonos?<\/p>\n<p><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>\u00abEra una pose; lo que yo sab\u00eda y no dec\u00eda a nadie, era que alg\u00fan d\u00eda me casar\u00eda y mi marido se ocupar\u00eda de velar por mi porvenir y asegurar mi bienestar econ\u00f3mico\u00bb. Clara Us\u00f3n. \u2018Coraz\u00f3n de napalm\u2019 Me lo dijo un psiquiatra que investigaba las causas del autismo. Para entonces yo hab\u00eda dejado apartados [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[4],"class_list":["post-74","post","type-post","status-publish","format-standard","hentry","category-2","tag-1599_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/74","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/comments?post=74"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/74\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/media?parent=74"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/categories?post=74"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/tags?post=74"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}