{"id":85,"date":"2009-05-25T13:24:53","date_gmt":"2009-05-25T13:24:53","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/masqueactualidad\/?p=85"},"modified":"2009-05-25T13:24:53","modified_gmt":"2009-05-25T13:24:53","slug":"summertime","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/2009\/05\/25\/summertime\/","title":{"rendered":"Summertime"},"content":{"rendered":"<p>Qu\u00e9 verde que est\u00e1 Gipuzkoa. No pido el calor de los campos del algod\u00f3n al que cantaba Ella Fitzgerald pero s\u00ed un poco de sol. Y eso que el sonido de la lluvia es relajante. \u00bfQu\u00e9 me dicen del del granizo? La naturaleza&nbsp; tiene la \u00faltima palabra, aunque nos solemos olvidar.<\/p>\n<p>Lo dijo Andoni Luis Aduriz recientemente. Que vuelvan las anchoas al Cant\u00e1brico -pidi\u00f3- Y que la naturaleza se convierta en una compa\u00f1era en el camino. No en el cofre del tesoro que hay que explotar.<\/p>\n<p>Compa\u00f1era h\u00fameda.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Qu\u00e9 verde que est\u00e1 Gipuzkoa. No pido el calor de los campos del algod\u00f3n al que cantaba Ella Fitzgerald pero s\u00ed un poco de sol. Y eso que el sonido de la lluvia es relajante. \u00bfQu\u00e9 me dicen del del granizo? La naturaleza&nbsp; tiene la \u00faltima palabra, aunque nos solemos olvidar. Lo dijo Andoni Luis [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[4],"class_list":["post-85","post","type-post","status-publish","format-standard","hentry","category-2","tag-1599_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/comments?post=85"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/posts\/85\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/media?parent=85"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/categories?post=85"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/masqueactualidad\/wp-json\/wp\/v2\/tags?post=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}