{"id":1073,"date":"2014-03-10T20:15:25","date_gmt":"2014-03-10T18:15:25","guid":{"rendered":"http:\/\/blogs.grada360.com\/rodrierrasti\/?p=1073"},"modified":"2014-03-10T20:15:25","modified_gmt":"2014-03-10T18:15:25","slug":"porteros-palos-y-futuro","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/2014\/03\/10\/porteros-palos-y-futuro\/","title":{"rendered":"Porteros, palos y futuro"},"content":{"rendered":"<p><!--:es-->La verdad es que de un tiempo a esta parte, esa <a href=\"http:\/\/blogs.grada360.com\/rodrierrasti\/2012\/12\/17\/la-importancia-del-portero\/\" target=\"_blank\" rel=\"external nofollow\">&#8220;profesi\u00f3n de riesgo&#8221; en el f\u00fatbol<\/a> parece haber cobrado a\u00fan un mayor protagonismo. En algunos medios, no hay d\u00eda en el que no se loe a alguno de los dos porteros del Real Madrid. A uno porque cuando juega lo hace bien y al otro porque ese d\u00eda no le ha tocado ponerse bajo palos. Si uno de ellos falla, le caen unos palos a veces exagerados. Lo mismo sucede cuando acierta. Es tan recurrente el tema que uno est\u00e1 empezando a perder el inter\u00e9s con el asunto. Por si toda esta pol\u00e9mica no era suficiente, ahora se suma el inter\u00e9s -real- del club blanco por fichar al guardameta que ahora mismo juega en el equipo rival. <a title=\"Courtois en Grada360\" href=\"http:\/\/www.grada360.com\/hemeroteca\/Courtois.html\" target=\"_blank\" rel=\"external nofollow\"><strong>Thibaut Courtois<\/strong><\/a> es el nombre que agita los palos de las principales porter\u00edas de Europa.\u00a0<!--:--><!--:en--><\/p>\n<p>\n<!--:--><!--more--><!--:es--><\/p>\n<p>El contacto con <strong>Christophe Henrotay<\/strong>,\u00a0el agente de <strong>Courtois<\/strong>, es real y se produjo hace semanas, <a title=\"El Real Madrid est\u00e1 sondeando el fichaje de Thibaut Courtois\" href=\"http:\/\/futbol.as.com\/futbol\/2014\/02\/21\/primera\/1392940997_133846.html\" target=\"_blank\" rel=\"external nofollow\">el diario AS inform\u00f3 de ello<\/a>\u00a0y <a title=\"Cerezo: \u00abEl Real Madrid considera a Courtois el mejor portero del mundo\u00bb\" href=\"http:\/\/www.grada360.com\/futbol\/equipos\/atletico-de-madrid\/20140224\/cerezo-real-madrid-tambien-201402241154-ag.html\" target=\"_blank\" rel=\"external nofollow\">hasta Cerezo lo reconoci\u00f3,<\/a> pero no hay nada cerrado. Y menos a dos a\u00f1os vista. Legalmente no puede hacerlo -FIFA podr\u00eda sancionarle- y esas promesas, al margen de documentos privados, parecen complicadas de mantener en el futuro cercano. El meta belga sabe que <a href=\"http:\/\/www.grada360.com\/futbol\/equipos\/atletico-de-madrid\/20130519\/thibaut-courtois-samuel-lionel-201305191754-g3.html\" target=\"_blank\" rel=\"external nofollow\">los vecinos, esos de los que se acord\u00f3 tras la Copa,<\/a> le quieren pero no se plantea aterrizar en Chamartin bajo ning\u00fan concepto si all\u00ed sigue<strong> Iker Casillas<\/strong>. <a title=\"Casillas se plantear\u00e1 si sigue en el Real Madrid al finalizar su contrato\" href=\"http:\/\/www.grada360.com\/futbol\/equipos\/real-madrid-cf\/20140303\/casillas-confia-jugar-hasta-201403031246-ag.html\" target=\"_blank\" rel=\"external nofollow\">El capit\u00e1n dijo tener intenci\u00f3n de cumplir su contrato hasta 2017<\/a> -que podr\u00eda renovarse si juega 30 partidos. algo que ahora no est\u00e1 haciendo-, aunque la realidad es que si se mantiene la situaci\u00f3n actual desea cambiar de club. As\u00ed se lo ha comunicado a sus \u00edntimos. En principio no quiere estar a la sombra de <a title=\"Noticias de Diego L\u00f3pez\" href=\"http:\/\/www.grada360.com\/hemeroteca\/diego%20lopez.html\" target=\"_blank\" rel=\"external nofollow\"><strong>Diego L\u00f3pez<\/strong><\/a> y su relaci\u00f3n con una peque\u00f1a parte de la hinchada se le est\u00e1 haciendo complicada. A Casillas le agrada la idea de jugar en la Premier y sabe que en algunas ciudades como Londres o Manchester podr\u00eda tener alguna opci\u00f3n. Por tanto, el que puede elegir es Courtois que ya ha advertido en Stamford Bridge: no tiene intenci\u00f3n de ir a\u00a0<em>chupar<\/em>\u00a0banquillo porque tiene grandes clubes a elegir en los que puede ser titular. <a title=\"El gran dilema del Chelsea\" href=\"http:\/\/blogs.grada360.com\/tacklewithheels\/2014\/02\/17\/el-gran-dilema-del-chelsea\/\" target=\"_blank\" rel=\"external nofollow\"><strong>El Chelsea, como contaba Eva Mar\u00eda Prieto, tiene un serio problema ya que debe decidir si vender al posible mejor portero del futuro, y un top5 del presente, o mantener a una leyenda que est\u00e1 en ese mismo grupo y con 31 a\u00f1os.<\/strong><\/a><\/p>\n<p><a href=\"\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2014\/03\/porteros.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1079\" src=\"\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2014\/03\/porteros.jpg\" alt=\"\" width=\"675\" height=\"445\" \/><\/a><\/p>\n<p>Gracias a ese soberbio nivel es pretendido por los grandes europeos. No por todos, ya que la salida m\u00e1s l\u00f3gica no ha tenido recorrido. Hablo del<a title=\"Goalkeeper Thibaut Courtois' father rubbishes claims of deal with Barcelona\" href=\"http:\/\/www1.skysports.com\/football\/news\/11668\/8420991\/goalkeeper-thibaut-courtois-father-rubbishes-claims-of-deal-with-barcelona\" target=\"_blank\" rel=\"external nofollow\"><strong> Barcelona, que seg\u00fan confirm\u00f3 Henrotay\u00a0no estaba interesado en el belga<\/strong><\/a>. Algo sorprendente, <a title=\"Un veintea\u00f1ero para suplir a Vald\u00e9s\" href=\"http:\/\/www.grada360.com\/futbol\/equipos\/fc-barcelona\/20130214\/marc-andre-stegen-cerca-201302141217-g3.html\" target=\"_blank\" rel=\"external nofollow\">ya que ha optado por el joven <strong>Ter Stegen<\/strong>\u00a0<\/a>&#8211;<a title=\"El Borussia M\u00f6nchengladbach ficha a Yann Sommer como sucesor de ter Stegen\" href=\"http:\/\/www.grada360.com\/futbol\/liga-alemana\/20140310\/sommer-para-sustituir-stegen-201403101620-ag.html\" target=\"_blank\" rel=\"external nofollow\">al que ya dan por traspasado en su club<\/a>&#8211; como sustituto de una leyenda como <a title=\"Noticias de V\u00edctor Vald\u00e9s \" href=\"http:\/\/www.grada360.com\/futbol\/jugadores\/victor-valdes-310\/\" target=\"_blank\" rel=\"external nofollow\"><strong>V\u00edctor Vald\u00e9s<\/strong><\/a>. Parece una apuesta algo arriesgada, sobre todo teniendo en cuenta que <strong>Pinto<\/strong> ya no seguir\u00e1. Habr\u00e1 que ver si finalmente es un portero o dos los que llegan a Can Bar\u00e7a. <strong>Pepe Reina<\/strong> puede ser una opci\u00f3n aunque su futuro dependa de <strong>Rodgers<\/strong>. En N\u00e1poles\u00a0<strong>Ben\u00edtez<\/strong> le quiere retener pero el internacional espa\u00f1ol debe seguir a la espera. Triunfar en Barcelona es una revancha especial para \u00e9l. Mucho se especul\u00f3 que <a title=\"Vald\u00e9s analiza la derrota ante el Valladolid? en el vestuario\" href=\"http:\/\/www.grada360.com\/futbol\/jugadores\/victor-valdes-310\/20140308\/video-valdes-analiza-derrota-201403081955-g3.html\" target=\"_blank\" rel=\"external nofollow\"><strong>Vald\u00e9s<\/strong>, ahora recibiendo palos por su <em>selfie<\/em> explicativo en v\u00eddeo tras la derrota en Pucela<\/a>, puede ir a M\u00f3naco pero Txiki y Pellegrini le quieren para suplir a <strong>Hart<\/strong>. Lo cierto es que <a href=\"http:\/\/blogs.grada360.com\/rodrierrasti\/2012\/12\/17\/la-importancia-del-portero\/\" target=\"_blank\" rel=\"external nofollow\">los porteros, esa raza especial de futbolista<\/a> que evita la alegr\u00eda ajena acaparan m\u00e1s que nunca el mercado internacional.<!--:--><!--:en--><\/p>\n<p><!--:--><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La verdad es que de un tiempo a esta parte, esa &#8220;profesi\u00f3n de riesgo&#8221; en el f\u00fatbol parece haber cobrado a\u00fan un mayor protagonismo. En algunos medios, no hay d\u00eda en el que no se loe a alguno de los dos porteros del Real Madrid. A uno porque cuando juega lo hace bien y al [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":159,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[71,93,116,174,185,199,201,211],"class_list":["post-1073","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","tag-cech","tag-diego-lopez","tag-iker-casillas","tag-pinto","tag-reina","tag-ter-stegen","tag-thibaut-courtois","tag-victor-valdes"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/posts\/1073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/users\/159"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/comments?post=1073"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/posts\/1073\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/media?parent=1073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/categories?post=1073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/tags?post=1073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}