{"id":1214,"date":"2015-02-08T18:39:47","date_gmt":"2015-02-08T17:39:47","guid":{"rendered":"http:\/\/blogs.vocento.com\/rodrierrasti\/?p=1214"},"modified":"2015-02-08T18:39:47","modified_gmt":"2015-02-08T17:39:47","slug":"fiesta-rojiblanca","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/2015\/02\/08\/fiesta-rojiblanca\/","title":{"rendered":"La fiesta es rojiblanca desde Lisboa"},"content":{"rendered":"<p><a href=\"\/rodrierrasti\/wp-content\/uploads\/sites\/96\/2015\/02\/A1-1819942906.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1216\" title=\"ATL\u00c9TICO MADRID REAL MADRID\" src=\"\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2015\/02\/A1-1819942906-e1423651614409.jpg\" alt=\"\" width=\"535\" height=\"352\" srcset=\"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2015\/02\/A1-1819942906-e1423651614409.jpg 535w, https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2015\/02\/A1-1819942906-e1423651614409-300x197.jpg 300w\" sizes=\"auto, (max-width: 535px) 100vw, 535px\" \/><\/a>Cambio de tendencia. El recordado gol de Sergio Ramos en Lisboa supuso un punto de inflexi\u00f3n&#8230; para el Atl\u00e9tico. Perder una final de la &#8216;Champions&#8217; en la \u00faltima jugada ante el eterno rival parec\u00eda que iba a conceder una ventaja moral para los madridistas, pero ha sido justo al rev\u00e9s. \u00abEl f\u00fatbol te da revancha, hay que ganarles cada partido\u00bb, reconocen en un vestuario rojiblanco que tiene marcada a fuego aquella cita en Portugal y se conjur\u00f3 despu\u00e9s de ella tanto que desde entonces no ha cedido en ninguno de sus partidos ante el Real Madrid: seis encuentros, con cuatro triunfos y dos empates que sirvieron para decidir dos eliminatorias a doble partido, una de ellas la Supercopa de Espa\u00f1a. \u00abFue un momento bonito porque estuvimos a punto de conseguir algo grande pero muy triste por c\u00f3mo termin\u00f3\u00bb, reconoc\u00eda esta semana Koke, lesionado el s\u00e1bado y que estar\u00e1 de baja un par de semanas por una rotura muscular.<\/p>\n<p>Gabi, el capit\u00e1n del Atl\u00e9tico, jug\u00f3 aquel partido dolorido por una fisura en la costilla, no saca pecho aunque s\u00ed reconoce tener claro c\u00f3mo actuar ante el vecino. \u00abLa medida no est\u00e1 cogida pero s\u00ed es verdad que sabemos jugar contra los grandes, somos fuertes, mentalmente siempre sabemos lo que hacer y eso se ve en el campo. El m\u00edster nos ha dado las claves del partido, la intensidad ha sido la clave. Nos sentimos orgullosos de esa intensidad, en esa faceta hemos sido los mejores\u00bb, explica el &#8217;14&#8217; rojiblanco que recuper\u00f3 18 balones en el derbi mientras que Khedira e Illarramendi ninguno. As\u00ed tambi\u00e9n lo cre\u00eda Siquiera, que recordaba lo \u00abdif\u00edcil que es jugar contra un Atleti tan intenso en el Calder\u00f3n\u00bb. \u00abHay que dar m\u00e1s m\u00e9rito al Atl\u00e9tico que dem\u00e9rito al Madrid\u00bb, aseguraba el brasile\u00f1o.<\/p>\n<p class=\"compLadillo\"><strong>Nuevo dominados<\/strong><\/p>\n<p>Tiago, que le ha marcado dos goles al Madrid en los dos duelos ligueros desde Lisboa, reconoc\u00eda: \u00abhe vivido el momento en que no se ganaba y este, en el que parece que todo sale bien\u00bb. \u00abEl equipo no ha cambiado mucho; s\u00ed la seguridad en nosotros mismos. Tenemos las cosas muy claras, somos muy fuertes y tenemos una identidad. Si vamos por ese camino, la victoria es posible\u00bb, se\u00f1alaba antes de reconocer que en los \u00faltimos partidos el Atl\u00e9tico manda en la capital. \u00abEsta \u00faltimas veces hemos mandado nosotros\u00bb, apunt\u00f3 en los micr\u00f3fonos de Canal Plus.<\/p>\n<p>El portugu\u00e9s indicaba la clave de los \u00faltimos triunfos rojiblancos: \u00abLa intensidad, desde el primer minuto. Con nuestro p\u00fablico somos fuertes y lo hemos demostrado\u00bb. \u00abNuestro m\u00edster sale reforzado, todo lo que nos ha dicho sucedi\u00f3 en el campo\u00bb, alababa.<\/p>\n<p>En el bando madridista hay preocupaci\u00f3n por la racha desde aquel 24 de mayo. Dani Carvajal no ocultana la necesidad de \u00abintentar revertir esta situaci\u00f3n ante el Atl\u00e9tico\u00bb. \u00abEsta derrota duele. Aun as\u00ed, seguimos un punto por encima de nuestros rivales y a seguir. El Atl\u00e9tico nos ha ganado los \u00faltimos derbis pero a final de temporada se ver\u00e1 qui\u00e9n gana m\u00e1s t\u00edtulos. El equipo es fuerte mentalmente para superar estas situaciones y ahora veremos qui\u00e9n es fuerte de cabeza y qui\u00e9n sabe levantarse ante esta dificultad\u00bb, explicaba.<\/p>\n<p>Por su parte, Carlo Ancelotti, aunque estaba preocupado porque en 2015 marca la mitad de goles y encaja el doble que en el hist\u00f3rico 2014, tambi\u00e9n pidi\u00f3 hacer \u00abcuentas al final de la Liga\u00bb. \u00abFueron mejores en todo en este partido y lo normal es que ganaran, pero la temporada es muy larga. Esto no se decidir\u00e1 hasta el final\u00bb, avisaba. Butrague\u00f1o tambi\u00e9n analiz\u00f3 la mala racha blanca desde la &#8216;d\u00e9cima&#8217; en estos duelos: \u00abDefienden muy bien, con gran convicci\u00f3n. Han crecido en los \u00faltimos a\u00f1os y son muy competitivos\u00bb.<\/p>\n<p class=\"compLadillo\"><strong>&#8220;Poco inteligente&#8221;<\/strong><\/p>\n<p><a href=\"\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2015\/02\/captura-Cristiano.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1215 alignright\" title=\"captura-Cristiano\" src=\"\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2015\/02\/captura-Cristiano.jpg\" alt=\"\" width=\"300\" height=\"181\" srcset=\"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2015\/02\/captura-Cristiano.jpg 1029w, https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2015\/02\/captura-Cristiano-300x181.jpg 300w, https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2015\/02\/captura-Cristiano-768x463.jpg 768w, https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2015\/02\/captura-Cristiano-1024x618.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>\u00abLos \u00faltimos partidos no hemos podido ganar al Atl\u00e9tico. Antes el Atl\u00e9tico le costaba mucho ganarnos. Las cosas cambian y tienen ciclos. En mi opini\u00f3n somos mejores pero eso lo tenemos que demostrar en el campo. No s\u00e9 por qu\u00e9 salimos as\u00ed. Hace tres a\u00f1os perdimos 5-0 ante el Bar\u00e7a y fueron d\u00edas complicados. Vamos a ganar la Liga otra vez\u00bb, afirmaba con cierto optimismo Cristiano Ronaldo. El portugu\u00e9s no estuvo nada acertado el s\u00e1bado, ni en el campo ni fuera del mismo. En el c\u00e9sped no aport\u00f3 nada, ni siquiera lleg\u00f3 a rematar a puerta y aunque sali\u00f3 a dar la cara ante la prensa tampoco estuvo afortunado. Tras reconocer el mal juego se encar\u00f3 con un periodista, que le pregunt\u00f3 por el gesto con el escudo cuando fue expulsado -simul\u00f3 limpiar el s\u00edmbolo de campeones del mundo de clubs- en C\u00f3rdoba, le llam\u00f3 \u00abpoco inteligente\u00bb por no preguntarle por el derbi y s\u00ed por algo ocurrido \u00abtres meses antes\u00bb [en realidad ocurri\u00f3 hace dos semanas]. \u00abEl Madrid no puede perder contra ning\u00fan equipo del mundo por 4-0\u00bb, a\u00f1adi\u00f3, aunque busc\u00f3 \u00abcosas positivas\u00bb en la goleada. \u00abDebe servir de aprendizaje para el futuro. Seguimos l\u00edderes, pero sabemos que tenemos que pelear hasta al final. Es poca diferencia. Hoy es un d\u00eda jodido porque el vestuario est\u00e1 fastidiado, pero hay que pensar en positivo porque seguimos primeros\u00bb, dec\u00eda el portugu\u00e9s.<\/p>\n<p>Y as\u00ed lo hizo al abandonar el estadio. La derrota 4-0 del Calder\u00f3n no evit\u00f3 que Cristiano Ronaldo celebrase su trig\u00e9simo cumplea\u00f1os en una fiesta en el In Zalaca\u00edn de La Finca con 150 invitados, entre ellos compa\u00f1eros como Marcelo, Pepe, James, Keylor Navas, Modric (que no jugaron el derbi capitalino) Coentrao o Khedira. Los aficionados madridistas no entendieron que, apenas tres horas despu\u00e9s de una derrota as\u00ed saliesen de fiesta y mucho menos que <a href=\"http:\/\/instagram.com\/kevinroldankr\/\" target=\"_blank\" rel=\"external nofollow\">posaran alegres en las redes sociales junto al cantante Kevin Rold\u00e1n<\/a>, que mostr\u00f3 v\u00eddeos y fotos de una fiesta en la que el homenajeado, que luc\u00eda un gorro carnavalero, subi\u00f3 al escenario a cantar uno de los temas del artista colombiano. El m\u00fasico colg\u00f3 en su cuenta de Instagram una fotograf\u00eda junto a Cristiano en la que pod\u00eda leerse el siguiente mensaje: \u00abEs un honor para m\u00ed que te guste mi m\u00fasica. Esta noche va a ser especial. Espero que disfrutes nuestro show. Hoy rompemos tarima en Madrid\u00bb. No era el d\u00eda para ello&#8230;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Cambio de tendencia. El recordado gol de Sergio Ramos en Lisboa supuso un punto de inflexi\u00f3n&#8230; para el Atl\u00e9tico. Perder una final de la &#8216;Champions&#8217; en la \u00faltima jugada ante el eterno rival parec\u00eda que iba a conceder una ventaja moral para los madridistas, pero ha sido justo al rev\u00e9s. \u00abEl f\u00fatbol te da revancha, [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":159,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,26],"tags":[],"class_list":["post-1214","post","type-post","status-publish","format-standard","hentry","category-futbol","category-real-madrid"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/posts\/1214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/users\/159"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/comments?post=1214"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/posts\/1214\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/media?parent=1214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/categories?post=1214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/tags?post=1214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}