{"id":1218,"date":"2015-01-29T19:26:02","date_gmt":"2015-01-29T18:26:02","guid":{"rendered":"http:\/\/blogs.vocento.com\/rodrierrasti\/?p=1218"},"modified":"2015-01-29T19:26:02","modified_gmt":"2015-01-29T18:26:02","slug":"la-gestion-de-los-nervios-y-las-pausas","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/2015\/01\/29\/la-gestion-de-los-nervios-y-las-pausas\/","title":{"rendered":"La gesti\u00f3n de los nervios y las pausas"},"content":{"rendered":"<p>Otra vez no supo mantener la eliminatoria igualada y volvi\u00f3 a perder los nervios cuando estuvo por debajo en el marcador. El Atl\u00e9tico, pese a su inicio trepidante con el enchufado Fernando Torres que sale a gol por remate a puerta desde que volvi\u00f3, se qued\u00f3 sin el pase a semifinales de la Copa del Rey tras un tenso encuentro del Vicente Calder\u00f3n. \u00abHa habido muchos accidentes. Ocurren dentro del terreno de juego. La segunda parte ha sido m\u00e1s tranquila. Mejor que no pasen esas cosas pero as\u00ed es la Copa\u00bb. As\u00ed defini\u00f3 el partido el presidente del Barcelona, Josep Mar\u00eda Bartomeu. Lo cierto es que el Bar\u00e7a tuvo la sensaci\u00f3n de que Atl\u00e9tico se peg\u00f3 un tiro en el pie tras verse por delante, entr\u00f3 en un duelo de golpes del que sali\u00f3 perdedor.<\/p>\n<p>Despu\u00e9s del partido, el bloque rojiblanco se centr\u00f3 en hablar de la jugada del posible penalti de Jordi Alba, momento en el que se esfum\u00f3 la opci\u00f3n de remontada y comenz\u00f3 una actitud demasiado agresiva con el rival. El \u20185\u2019 explic\u00f3 que el \u00e1rbitro \u00abse ha equivocado para los dos equipos, puede que fuera penalti (Jordi Alba lo cometi\u00f3 por manos, pero no se pit\u00f3 y tras seguir la jugada asisti\u00f3 a Neymar en el 2-3) pero tambi\u00e9n ha habido otras muchas jugadas que no tienen en cuenta\u00bb.<\/p>\n<p>Con el 2-3, se incrementaron las protestas al colegiado y se perdieron las formas tras la celebraci\u00f3n de Neymar, con baile inclu\u00eddo. Hubo todo tipo de reproches al brasile\u00f1o, al punto que se gener\u00f3 una tangana al filo del descanso. Empujones, intercambio de desafios y amenazas que siguieron hasta la caseta, donde el Atl\u00e9tico se qued\u00f3 sin Gabi. \u00abEn la segunda parte hicimos el juego que m\u00e1s nos conven\u00eda\u00bb, dijo un Cholo Simeone que debi\u00f3 llegar a esa conclusi\u00f3n en su caseta.<\/p>\n<p><strong>Tangana al descanso<\/strong><\/p>\n<p>Y es que justo al se\u00f1alar Gil Manzano el descanso protest\u00f3 el penalti de Jordi Alba al colegiado, y viendo que no le hac\u00eda caso termin\u00f3, seg\u00fan han mostrado im\u00e1genes de Deportes Cuatro, aprovech\u00f3 que el \u00e1rbitro extreme\u00f1o enfilaba el tunel de vestuarios para realizarle un corte de mangas sin ser visto. Quiz\u00e1 asumi\u00f3 que todo estaba decidido al saber que se hab\u00eda quedado sin Gabi.<\/p>\n<p>El capit\u00e1n explic\u00f3 en Canal + su expulsi\u00f3n negando que le faltase el respeto a Gil Manzano y le achac\u00f3 ser un \u00e1rbitro al que le falta personalidad. \u00abLe dije: \u2018Jes\u00fas, ha sido penalti y expulsi\u00f3n\u2019. Esa fue mi falta de respeto seg\u00fan \u00e9l. Lo siento por el equipo. Creo que un \u00e1rbitro deber\u00eda tener mucha m\u00e1s personalidad y m\u00e1s respeto por el jugador. Todos nos equivocamos. Hay que ser justo, reconocer tus errores y no querer ser protagonista\u00bb. El centrocampista se mostr\u00f3 especialmente molesto con la actitud de Neymar en el Calder\u00f3n. \u00abTiene una forma de jugar un poco peculiar, sobre todo cuando va ganando. Siempre hace gestos en el campo, sobre todo cuando gana. A nadie le gusta perder y, con esas pulsaciones, te molestan las cosas\u00bb.<\/p>\n<p><strong>Competitivos, no violentos<\/strong><\/p>\n<p>Hasta Cani, reci\u00e9n llegado, explic\u00f3 que \u00aba veces te entra un poco de impotencia con sus gestos. Alg\u00fan d\u00eda va a tener alg\u00fan problema, pero bueno, si es su forma de jugar&#8230;\u00bb. Uno con los que s\u00ed tuvo un encontronazo el &#8217;11&#8217; cul\u00e9 fue con Juanfran, que no quiso explicar si hizo un gesto recordando el 1-7 entre brasile\u00f1os y alemanes del Mundial, y dijo no tener \u00abnada en su contra. No puedo opinar sobre su persona. Lo que pasa, se queda en el campo y no voy a hablar mal de nadie\u00bb, aclar\u00f3 antes de reconocer que el calificativo de \u00abviolentos ya cansa\u00bb en el vestuario rojiblanco. \u00abSomos competitivos. Es una de nuestras se\u00f1as de identidad. Quien habla mal de nosotros y dice que somos agresivos es porque nos tienen envidia\u00bb.<\/p>\n<p><a href=\"\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2015\/01\/torres-neymar.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1220\" title=\"torres-neymar\" src=\"\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2015\/01\/torres-neymar.jpg\" alt=\"\" width=\"575\" height=\"323\" srcset=\"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2015\/01\/torres-neymar.jpg 575w, https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2015\/01\/torres-neymar-300x169.jpg 300w\" sizes=\"auto, (max-width: 575px) 100vw, 575px\" \/><\/a><\/p>\n<p>Lo cierto es que en la segunda mitad, con diez, el Atl\u00e9tico mostr\u00f3 su cara menos deportiva. Al parecer todo ven\u00eda generado por la celebraci\u00f3n del 2-3 del brasile\u00f1o. Sergio Busquets, tras el partido, tambi\u00e9n se refiri\u00f3 a lo sucedido y neg\u00f3 que todo fuera culpa de Neymar. \u00abEsto es f\u00fatbol, el f\u00fatbol es imaginaci\u00f3n y \u00e9l tiene mucha. Hay que saber ganar y hay que saber perder\u00bb, reconociendo que tras un gran primera mitad la roja a Gabi dej\u00f3 \u00abuna segunda parte descafeinada. A partir del 2-2 ha sido m\u00e1s f\u00e1cil para nosotros\u00bb.<\/p>\n<p>Simeone explic\u00f3 que su equipo jug\u00f3 \u00absin aspiraciones por orden m\u00eda. Con la intenci\u00f3n de no encajar y sin la intenci\u00f3n de marcar\u00bb, dijo ante la sorpresa general antes de mandar un dardo al rival. \u00abS\u00f3lo hubo partido en la primera parte, y jugamos casi siempre en campo rival, aunque dijeron que el bal\u00f3n era un conejo, \u00bfno?\u00bb.<\/p>\n<p><strong>La bota de Arda<\/strong><\/p>\n<p>El ataque de ira de Arda Turan fue quiz\u00e1 el reflejo de que el Atl\u00e9tico estaba fustrado al verse por detr\u00e1s en el marcador. Sucedi\u00f3 nada m\u00e1s comenzar la segunda parte, cuando en un bal\u00f3n dividido cogi\u00f3 su bota izquierda y la lanz\u00f3 al \u00e1rbitro asistente, que estaba tan concentrado que ni se enter\u00f3. Le pas\u00f3 por encima de la cabeza y golpea en Pedro Pablo, el delegado del Atl\u00e9tico, que estaba hablando con el \u2018profe\u2019 Ortega que charlaba con Ra\u00fal Jim\u00e9nez. El asunto termin\u00f3 en amarilla al turco, que recuper\u00f3 el borcegu\u00ed gracias a su compa\u00f1ero el mexicano.<\/p>\n<p>No tendr\u00e1 sanci\u00f3n porque el acta de Gil Manzano no refleja que fuera un intento de agresi\u00f3n, aunque una acci\u00f3n similar (redactada de otro modo) le cost\u00f3 a Dani Ben\u00edtez, del Granada, tres meses de castigo. Iv\u00e1n Rakitic explic\u00f3 la situaci\u00f3n m\u00e1s curiosa del partido. \u00abNo sab\u00eda si re\u00edrme o qu\u00e9 hacer. Mejor preguntarle a \u00e9l. Estaba sorprendido\u00bb, reconoci\u00f3. Por su parte, Alba explic\u00f3 que \u00ablo de Arda lo han visto todos, pero quien decide es el \u00e1rbitro. No hay que darle m\u00e1s vueltas\u00bb.<\/p>\n<p>Luis Enrique dej\u00f3 en el campo a Neymar tras el descanso, pero explic\u00f3 que al final lo quit\u00f3 \u00abporque el partido se pon\u00eda feo\u00bb. En plena indignaci\u00f3n local, el Calder\u00f3n rug\u00eda al un\u00edsono con un \u00abotra, otra\u00bb, que no qued\u00f3 muy claro si se refer\u00edan a las tarjetas o a las patadas. Javier Mascherano, neg\u00f3 que el partido violento si bien reconoci\u00f3 que \u00aben alg\u00fan momento pudo haber una pierna fuerte, pero no creo en la mala intenci\u00f3n de los jugadores del Atl\u00e9tico\u00bb. Rakitic quiso normalizar lo sucedido en la segunda parte cuando hubo muchas faltas e interrupciones, explicando que \u00abse calienten los dos equipos es normal, es un t\u00edtulo. En general ha sido un partido muy caliente, como casi todos con el Atl\u00e9tico pero estamos contentos con lo que hemos hecho\u00bb, recordando que \u00abel a\u00f1o pasado no pudimos ganar al Atl\u00e9tico y este a\u00f1o hacerlo tres veces significa que vamos por buen camino\u00bb, sentenci\u00f3 el croata.<\/p>\n<p><strong>Y Ansaldi, en comisaria<\/strong><\/p>\n<p>Alba tambi\u00e9n se mostr\u00f3 \u00abmuy satisfecho por el comportamiento del equipo, por la intensidad que hemos puesto tras el 1-0 y muy feliz de pasar a semifinales\u00bb. El lateral, al que se llamar \u2018gordo\u2019 a Gim\u00e9nez, dio una clave para el cambio del equipo desde Anoeta: \u00abLa din\u00e1mica desde hace un mes distinta, desde fuera con m\u00e1s tranquilidad en el vestuario, unidos, ahora mismo somos un equipazo\u00bb. Y es que est\u00e1n tan de dulce que son capaces de llegar de un \u00e1rea a otra sprintando pese a que el bal\u00f3n \u00abbote como un conejo, pero somos especialistas en ver botar balones como conejos, porque nos pasa en todos los partidos que jugamos fuera\u00bb, dijo el asturiano.<\/p>\n<p>Todo eso sin contar que antes del partido Cristian Ansaldi, que estaba lesionado, ni siquiera pudo presenciar el duelo en el estadio, ya que fue retenido por la polic\u00eda en la comisar\u00eda del distrito de Arganzuela cuando se dirig\u00eda hacia el coliseo rojiblanco acusado de un delito de resistencia y desobediencia por parte de la Polic\u00eda Municipal de Madrid.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Otra vez no supo mantener la eliminatoria igualada y volvi\u00f3 a perder los nervios cuando estuvo por debajo en el marcador. El Atl\u00e9tico, pese a su inicio trepidante con el enchufado Fernando Torres que sale a gol por remate a puerta desde que volvi\u00f3, se qued\u00f3 sin el pase a semifinales de la Copa del [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":159,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,15],"tags":[],"class_list":["post-1218","post","type-post","status-publish","format-standard","hentry","category-copa","category-futbol"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/posts\/1218","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/users\/159"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/comments?post=1218"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/posts\/1218\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/media?parent=1218"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/categories?post=1218"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/tags?post=1218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}