{"id":1251,"date":"2015-04-14T23:21:32","date_gmt":"2015-04-14T21:21:32","guid":{"rendered":"http:\/\/blogs.vocento.com\/rodrierrasti\/?p=1251"},"modified":"2015-04-14T23:21:32","modified_gmt":"2015-04-14T21:21:32","slug":"oblak-consigue-que-el-mejor-madrid-solo-iguale-al-atletico-mas-racano","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/2015\/04\/14\/oblak-consigue-que-el-mejor-madrid-solo-iguale-al-atletico-mas-racano\/","title":{"rendered":"Oblak consigue que el mejor Madrid s\u00f3lo iguale al Atl\u00e9tico m\u00e1s r\u00e1cano"},"content":{"rendered":"<p>El Real Madrid ofreci\u00f3 su mejor versi\u00f3n en el Calder\u00f3n, pero ni siquiera eso le sirvi\u00f3 para vencer a un plomizo y gris Atl\u00e9tico, que sujetado por los guantes de Jan Oblak se presentar\u00e1 en el Santiago Bernab\u00e9u con un 0-0 que le deja en la situaci\u00f3n deseada por su t\u00e9cnico: un gol en campo ajeno, manteniendo el habitual buen hacer defensivo, puede ser suficiente para colarse en semifinales. Esta vez Simeone result\u00f3 perdedor en el duelo t\u00e1ctico. El Cholo apost\u00f3 por Mario Su\u00e1rez y Gabi en el centro y Siqueira en el lateral. Lo del defensa, en principio, parec\u00eda m\u00e1s l\u00f3gico, porque aunque no ha rendido como esperaba al menos era un especialista para la zona y pod\u00eda aprovechar espacios si Bale no cumpl\u00eda con la tarea encomendaba. Fracas\u00f3 de modo grosero y fue un aliado blanco. Pese a todo, sorprendi\u00f3 m\u00e1s la decisi\u00f3n del argentino de dejar a Tiago en el banquillo, por su aplomo, sentido t\u00e1ctico y experiencia en este tipo de duelos. Enfrente, Ancelotti fue fiel a sus ideas y apost\u00f3 por el equipo de gala con Bale replegado en las acciones defensivas. El once preferido del presidente, colocado en un 4-4-2 como el que se vio en el Camp Nou. Mismos hombres pero otro equipo, ya que sobre todo el Real Madrid mostr\u00f3 una enorme actitud de funcionar como bloque. A diferencia de los otros tres encuentros jugados ante el mismo rival en el mismo estadio demostr\u00f3 argumentos de vigente campe\u00f3n europeo. S\u00f3lo le falt\u00f3 la definici\u00f3n para haber roto con la mala racha tras Lisboa.<\/p>\n<p><a href=\"\/rodrierrasti\/wp-content\/uploads\/sites\/96\/2015\/04\/oblak-bale-vicente-calderon.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1253\" title=\"oblak-bale-vicente-calderon\" src=\"\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2015\/04\/oblak-bale-vicente-calderon-e1429898737902.jpg\" alt=\"\" width=\"540\" height=\"300\" srcset=\"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2015\/04\/oblak-bale-vicente-calderon-e1429898737902.jpg 540w, https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2015\/04\/oblak-bale-vicente-calderon-e1429898737902-300x167.jpg 300w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><\/a>El Madrid super\u00f3 el temido arranque local moviendo r\u00e1pido el bal\u00f3n y siendo efectivo con \u00e9l, con intensidad, anticip\u00e1ndose ante un Atl\u00e9tico en el que Koke no aparec\u00eda. Mala se\u00f1al para el Atl\u00e9tico, que apenas sal\u00eda de su campo y se refugi\u00f3 en el buen hacer de Oblak. S\u00f3lo las protestas de sus hinchas tuvieron ese grado de intensidad imaginado antes del pitido inicial. Cada acci\u00f3n a bal\u00f3n parado era jaleada como si el duelo se estuviese disputando en Ibrox Park. En ese arranque tuvo las mejores opciones, si bien la m\u00e1s clara lleg\u00f3 por un error ajeno. Oblak se hizo gigante ante Bale despu\u00e9s de que God\u00edn, el mariscal del juego \u00e1rero, errase en el despeje al tratar de despejar. De cabeza dej\u00f3, sin desearlo, la bola muerta al gal\u00e9s, que centrado, como si fuese un penalti, apost\u00f3 por la potencia y el esloveno repeli\u00f3 para alivio rojiblanco.<\/p>\n<p><strong>Modric, br\u00fajula blanca<\/strong><\/p>\n<p>Asentado en el equipo tras ser h\u00e9roe en octavos el esloveno sac\u00f3 buenas manos, no dud\u00f3 por alto y sobre todo demostr\u00f3 cuajo para una cita as\u00ed en la que alguno de sus colegas menguaron en esa porter\u00eda. A la media hora, mostr\u00f3 concentraci\u00f3n al repeler un zurdazo lejano de Bale raso. Y despu\u00e9s tambi\u00e9n despej\u00f3 otro zurdazo de James, al que tambi\u00e9n le rob\u00f3 un gol con una mano m\u00e1gica en un zurdazo cercano. La din\u00e1mica era bien distinta a la vivida en los precedentes m\u00e1s cercanos. De hecho, recordaba a alg\u00fan duelo de la era pre-Simeone. El recuerdo m\u00e1s cercano con el Cholo era la primera mitad del Camp Nou. A merced del rival, que llegaba por la banda diestra como autopista. Siqueira sufr\u00eda y sufr\u00eda, Bale llegaba y Carvajal doblaba. Parec\u00eda el momento ideal para que el Real Madrid golpeara primero a su rival, pero le concedi\u00f3 aire por su falta de punter\u00eda. Al punto de que un mal despeje de Ramos gener\u00f3 la primera ilusi\u00f3n local. Griezmann golpe\u00f3 r\u00e1pido desde la media luna a la media vuelta, pero Casillas no le hab\u00eda perdido ojo a la acci\u00f3n y resolvi\u00f3 sin problemas.<\/p>\n<blockquote><p>El esloveno hizo seis paradas de m\u00e9rito para mantener el empate contra un rival que fue superior en todo durante la primera mitad<\/p><\/blockquote>\n<p>El descanso parec\u00eda el oasis que deb\u00eda alcanzar el Atl\u00e9tico, que pese a estar plomizo y ausente del encuentro alcanz\u00f3 el primero de los cuatro cuartos de la doble cita a salvo. Desdibujado, llorando la ausencia de Tiago y queriendo salir a la contra olvidando que ya no est\u00e1 Diego Costa, sino Mandzukic, que apenas pudo ganar una carrera a un Varane que dej\u00f3 la boca abierta a todos con un sprint ofensivo de 70 metros. El galo fue otro de los que brill\u00f3 en un Real Madrid al que s\u00f3lo le falt\u00f3 la punter\u00eda para pasar del notable al sobresaliente. Dispar\u00f3 diez veces, pero se fue de vac\u00edo por Oblak, que demostr\u00f3 las razones por las que est\u00e1 en el \u2018top 10\u2019 de los porteros m\u00e1s caros de la historia. Hizo seis paradas decisivas para que en la caseta el Cholo apretase a los suyos con todo por disputar.<\/p>\n<p>La duda radicaba en si el Real Madrid mantendr\u00eda el ritmo que marcaba el certero Modric, el diapas\u00f3n del juego blanco. No pudo lograrlo y a medida que pasaban los minutos el combate se igual\u00f3. El Atl\u00e9tico, que hab\u00eda imaginado un duelo cerrado como el de la Juventus, se estir\u00f3 y una cabalgada por banda de Juanfran termin\u00f3 con un cabezazo de Arda que al menos mantuvo a la afici\u00f3n local metida en el duelo. Luego lleg\u00f3 el codazo de Ramos a Mandzukic, que m\u00e1s all\u00e1 del penalti provoc\u00f3 que los locales tuviesen que jugar varios minutos con uno menos mientras se atend\u00eda al croata. Su regreso fue alocado, al punto de que su ansia por forzar una tarjeta casi le cuesta irse expulsado. Cierto es que recibi\u00f3 un pu\u00f1etazo en la tripa de Carvajal que pudo ser penalti, pero parec\u00eda pasado de revoluciones con poco positivo que aportar a los suyos. Cada vez que se acercaba al banquillo a que le cortasen la sangre, regresaba m\u00e1s enfadado. Kroos prob\u00f3 desde lejos mientras el Atl\u00e9tico buscaba los dos contra uno en banda a Marcelo con Juanfran, Arda y la ayuda de Koke.<\/p>\n<p>Ancelotti opt\u00f3 por la calidad de Isco y meti\u00f3 arriba a Bale, mientras Simeone optaba por la fuerza de Ra\u00fal Garc\u00eda en lugar de Griezmann. En teor\u00eda, eso significaba m\u00e1s gente en el centro que podr\u00eda atascar el juego. Y pol\u00e9mica. Por fuerza y en barullo accedi\u00f3 el Atl\u00e9tico a la fase final del encuentro con opciones reales de llev\u00e1rselo. Simeone crey\u00f3 en ello y pese a meter a Torres dej\u00f3 a su guerrero serbio.<\/p>\n<blockquote><p>El Atl\u00e9tico apenas cre\u00f3 peligro pero reclam\u00f3 dos penaltis por agresiones a Mandzukic de Carvajal y Ramos<\/p><\/blockquote>\n<p>En los minutos finales hasta se not\u00f3 que Casillas estaba presente. Fall\u00f3 en una salida y tap\u00f3 sobre la l\u00ednea un remate de Ra\u00fal Garc\u00eda tras una mel\u00e9. El 0-0 deja satisfecho al Atl\u00e9tico, que a\u00fan recuerda que fue su renta para viajar a Londres, y contenta a medias al Real Madrid, que ni en uno de sus mejores d\u00edas fue capaz de superar al vecino, que cada vez es m\u00e1s molesto.<\/p>\n<p><strong>0-Atl\u00e9tico de Madrid:<\/strong>\u00a0Oblak, Juanfran, Miranda, God\u00edn, Siqueira, Arda Turan, Gabi, Mario Su\u00e1rez, Koke (Torres, min. 82), Griezmann (Ra\u00fal Garc\u00eda, min. 76) y Mandzukic.<br \/>\n<strong>0-Real Madrid:<\/strong>\u00a0Casillas, Carvajal (Arbeloa, min. 82), Varane, Sergio Ramos, Marcelo, Kroos, Modric, James, Bale, Benzema (Isco, min. 75) y Cristiano Ronaldo.<br \/>\n\u00c1RBITRO:\u00a0Mirolad Mazic (Serbia). Amonest\u00f3 a Mandzukic, Ra\u00fal Garc\u00eda, Marcelo, Sergio Ramos y Mario Su\u00e1rez.<br \/>\nINCIDENCIAS: \u00a0Partido de ida de cuartos de final de la Liga de Campeones. 54.000 espectadores en el Vicente Calder\u00f3n. Unos 2.500 aficionados del Real Madrid ocuparon uno de los fondos del estadio. Mario Su\u00e1rez y Marcelo se perder\u00e1n el duelo de vuelta por sanci\u00f3n.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El Real Madrid ofreci\u00f3 su mejor versi\u00f3n en el Calder\u00f3n, pero ni siquiera eso le sirvi\u00f3 para vencer a un plomizo y gris Atl\u00e9tico, que sujetado por los guantes de Jan Oblak se presentar\u00e1 en el Santiago Bernab\u00e9u con un 0-0 que le deja en la situaci\u00f3n deseada por su t\u00e9cnico: un gol en campo [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":159,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[54,167],"class_list":["post-1251","post","type-post","status-publish","format-standard","hentry","category-champions-league","tag-bale","tag-oblak"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/posts\/1251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/users\/159"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/comments?post=1251"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/posts\/1251\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/media?parent=1251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/categories?post=1251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/tags?post=1251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}