{"id":133,"date":"2012-09-17T03:11:17","date_gmt":"2012-09-17T01:11:17","guid":{"rendered":"http:\/\/blogs.grada360.com\/rodrierrasti\/?p=133"},"modified":"2012-09-17T03:11:17","modified_gmt":"2012-09-17T01:11:17","slug":"tener-equipo-o-esforzarse-en-crearlo","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/2012\/09\/17\/tener-equipo-o-esforzarse-en-crearlo\/","title":{"rendered":"Tener equipo o esforzarse en crearlo"},"content":{"rendered":"<p><!--:es-->Una persona, de esas que te marcan\u00a0para siempre, me explic\u00f3\u00a0un teor\u00eda sobre el deporte,\u00a0el trabajo y la vida basada en muchos a\u00f1os habitando en distintos lugares de\u00a0Europa.\u00a0Este buen hombre considera que las personas se comportan en su puesto laboral del mismo modo que lo hacen cuando practican un deporte colectivo.\u00a0Un par de partidos son efectivos para catalogar el tipo de trabajador.<\/p>\n<p>Su modelo ideal\u00a0para explicarlo\u00a0es el rugby, en el que participan quince deportistas de todos las condiciones f\u00edsicas, pero explica que vale cualquiera superior a cinco.\u00a0Intenta desarrollar su profesi\u00f3n junto a ese tipo\u00a0jugador que acepta con una sonrisa\u00a0colocarse en varios puestos que no son el suyo por las\u00a0necesidades del gui\u00f3n y encaja comprensivo una suplencia por el bien del grupo.\u00a0Por contra, recela de los que siempre tienen puesto fijo en el terreno de juego, consideran que defender es una perdida de energ\u00eda teniendo en cuenta su calidad aunque nunca sienten fatiga a la hora de protestar las actuaciones ajenas, sean del colegiado, rivales o incluso\u00a0de sus compa\u00f1eros.\u00a0Su brillo personal, y el de sus medallas,\u00a0es prioritario.<!--:--><!--:en--><\/p>\n<p>Una persona, de esas que te marcan\u00a0para siempre, me explic\u00f3\u00a0un teor\u00eda sobre el deporte,\u00a0el trabajo y la vida basada en muchos a\u00f1os habitando en distintos lugares de\u00a0Europa.\u00a0Este buen hombre considera que las personas se comportan en su puesto laboral del mismo modo que lo hacen cuando practican un deporte colectivo.\u00a0Un par de partidos son efectivos para catalogar el tipo de trabajador.<\/p>\n<p>Su modelo ideal\u00a0para explicarlo\u00a0es el rugby, en el que participan quince deportistas de todos las condiciones f\u00edsicas, pero explica que vale cualquiera superior a cinco.\u00a0Intenta desarrollar su profesi\u00f3n junto a ese tipo\u00a0jugador que acepta con una sonrisa\u00a0colocarse en varios puestos que no son el suyo por las\u00a0necesidades del gui\u00f3n y encaja comprensivo una suplencia por el bien del grupo.\u00a0Por contra, recela de los que siempre tienen puesto fijo en el terreno de juego, consideran que defender es una perdida de energ\u00eda teniendo en cuenta su calidad aunque nunca sienten fatiga a la hora de protestar las actuaciones ajenas, sean del colegiado, rivales o incluso\u00a0de sus compa\u00f1eros.\u00a0Su brillo personal, y el de sus medallas,\u00a0es prioritario.<!--:--><!--more--><!--:es--><\/p>\n<p>Llevo viviendo en Madrid todo este siglo y desde entonces no he visto a mis vecinos rojiblancos irse a casa contentos tras un duelo con los madridistas. Estas semanas, est\u00e1n m\u00e1s felices que los segundos. Y es que, despu\u00e9s de sufrir su segunda derrota liguera en cuatro jornadas, Mourinho solt\u00f3 una frase impactante para justificar lo sucedido en Sevilla:<strong> <a title=\"Mourinho en Sevilla\" href=\"http:\/\/www.grada360.com\/futbol\/equipos\/real-madrid-cf\/20120916\/mourinho-este-momento-tengo-201209160027-g3.html\" target=\"_blank\" rel=\"external nofollow\">&#8220;En estos momentos no tengo equipo&#8221;.<\/a>\u00a0<\/strong>Tras recitar todos los errores que sus jugadores cometieron en el Pizju\u00e1n, algunos de ellos\u00a0en varias ocasiones, y recriminar\u00a0el\u00a0escaso compromiso de su grupo tuvo claro el an\u00e1lisis.\u00a0C\u00f3modo bajo el foco que le ilumina siempre como principal protagonista, Mourinho\u00a0no siente como un lastre la etiqueta\u00a0&#8216;The Special One&#8217; heredada en Inglaterra. Es ahora, en su peor momento como t\u00e9cnico\u00a0blanco, cuando debe demostrar por qu\u00e9\u00a0es el entrenador mejor pagado del mundo y puede\u00a0disponer de fichajes con los que otros clubes de la Liga ajustan un presupuesto anual.<\/p>\n<p><a href=\"\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2012\/09\/cholo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-140\" src=\"\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2012\/09\/cholo.jpg\" alt=\"\" width=\"635\" height=\"422\" srcset=\"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2012\/09\/cholo.jpg 635w, https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2012\/09\/cholo-300x199.jpg 300w\" sizes=\"auto, (max-width: 635px) 100vw, 635px\" \/><\/a><\/p>\n<p>Necesita un reacci\u00f3n en la Champions y\u00a0pondr\u00e1 todo el empe\u00f1o en lograr que el City sea el rival\u00a0adecuado para sacarse los miedos del cuerpo.\u00a0La \u00faltima vez que vivi\u00f3 algo similar, un empate europeo ante el\u00a0modesto\u00a0Rosenborg\u00a0acab\u00f3 perdiendo su plaza en el\u00a0banquillo. <strong><a title=\"Mou deja el Chelsea\" href=\"http:\/\/news.bbc.co.uk\/hi\/spanish\/deportes\/newsid_7003000\/7003915.stm\" target=\"_blank\" rel=\"external nofollow\">Dej\u00f3 de entrenar a un Chelsea que posteriomente llegar\u00eda a una final de la Champions que\u00a0\u00e9l no pudo alcanzar como blue<\/a>.<\/strong> Queda por ver si\u00a0su speech ha servido de revulsivo o\u00a0s\u00f3lo ha avivado el sentimiento interno actual de la caseta: los triunfos tienen un solo padre y la derrota siempre las mismas caras.\u00a0 Antes de volver a pisar\u00a0el c\u00e9sped,\u00a0parece que ha conseguido <strong><a title=\"Mourinho incendia el vestuario\" href=\"http:\/\/www.grada360.com\/futbol\/20120916\/mourinho-incendia-vestuario-201209161923-rc.html\" target=\"_blank\" rel=\"external nofollow\">abrir un poco m\u00e1s la brecha entre los\u00a0espa\u00f1oles y el\u00a0grupo\u00a0que habla portugu\u00e9s<\/a>.\u00a0<\/strong><\/p>\n<p><strong><a title=\"Simeone: \" href=\"http:\/\/www.grada360.com\/futbol\/equipos\/atletico-de-madrid\/20120917\/simeone-apure-cambios-responsabilidad-201209170004-ag.html\" target=\"_blank\" rel=\"external nofollow\">&#8220;El culpable soy yo por errar con los cambios&#8221;.<\/a> <\/strong>Las palabras son de Diego Pablo Simeone para explicar lo sucedido en los apenas <a title=\"Atl\u00e9tico 4-3 Rayo\" href=\"http:\/\/www.grada360.com\/futbol\/liga-primera\/20120916\/goleada-atletico-antes-caraja-201209162343-g3.html\" target=\"_blank\" rel=\"external nofollow\">seis minutos que fueron desde el 4-0 al 4-3 entre Atl\u00e9tico y Rayo<\/a>. Desde que lleg\u00f3 al club, supo que ten\u00eda tarea entre manos.\u00a0La afici\u00f3n no cre\u00eda en el proyecto, tampoco\u00a0unos jugadores que fueron incapaces de\u00a0remontar una eliminatoria ante el Albacete pese a saber que Manzano ya no seguir\u00eda en el campo.\u00a0Cholo tuvo que armar la t\u00e1ctica, recuperar psicol\u00f3gicamente al grupo,\u00a0alentar a la afici\u00f3n para que\u00a0no decayera animando a los suyos, aleccionar a los recogepelotas sobre los tempos\u00a0a la hora de\u00a0devolver los\u00a0balones\u00a0y apagar varios incendios ante\u00a0la prensa. Todo\u00a0lo\u00a0que fuera necesario por el bien del equipo.<\/p>\n<p>Su objetivo era devolver la gloria al Atl\u00e9tico y\u00a0se esforz\u00f3 en encontrar aliados para\u00a0completar la misi\u00f3n.\u00a0Los encontr\u00f3 y\u00a0los atl\u00e9ticos tocaron el cielo en Bucarest y<strong> <a title=\"Supercopa Europa\" href=\"http:\/\/blogs.grada360.com\/rodrierrasti\/2012\/08\/31\/el-tigre-los-leones-y-el-calor\/\" target=\"_blank\" rel=\"external nofollow\">hace solo unos d\u00edas en M\u00f3naco<\/a>.\u00a0<\/strong>Durante su etapa de jugador, determinados comportamientos afearon la carrera de un futbolista de esos que todo el mundo prefer\u00eda tener a su lado a verlo en la escuadra contraria. Ahora como t\u00e9cnico ha logrado aplacar esa parte visceral que le hac\u00eda perder puntos como futbolista.<\/p>\n<p>La pregunta es: \u00bfA qui\u00e9n se llevar\u00edan ustedes de los dos&#8230; para\u00a0su trabajo? Mi amigo, el que siente la pasi\u00f3n por el rugby, lo tiene claro: Cholo.<\/p>\n<p>PD: <strong><a title=\"Viggo sobre Morunho y Simeone\" href=\"http:\/\/www.republica.com\/2012\/09\/06\/viggo-mortensen-simeone-le-rompe-el-culo-a-patadas-a-mourinho_544337\/\" target=\"_blank\" rel=\"external nofollow\">Pese a todo lo explicado y, aunque el viernes me encontr\u00e9 con \u00e9l por Madrid, no hablo de Viggo Mortensen<\/a>.<\/strong><!--:--><!--:en--><\/p>\n<p>Llevo viviendo en Madrid todo este siglo y desde entonces no he visto a mis vecinos rojiblancos irse a casa contentos tras un duelo con los madridistas. Estas semanas, est\u00e1n m\u00e1s felices que los segundos. Y es que, despu\u00e9s de sufrir su segunda derrota liguera en cuatro jornadas, Mourinho solt\u00f3 una frase impactante para justificar lo sucedido en Sevilla:<strong> <a title=\"Mourinho en Sevilla\" href=\"http:\/\/www.grada360.com\/futbol\/equipos\/real-madrid-cf\/20120916\/mourinho-este-momento-tengo-201209160027-g3.html\" target=\"_blank\" rel=\"external nofollow\">&#8220;En estos momentos no tengo equipo&#8221;.<\/a>\u00a0<\/strong>Tras recitar todos los errores que sus jugadores cometieron en el Pizju\u00e1n, algunos de ellos\u00a0en varias ocasiones, y recriminar\u00a0el\u00a0escaso compromiso de su grupo tuvo claro el an\u00e1lisis.\u00a0C\u00f3modo bajo el foco que le ilumina siempre como principal protagonista, Mourinho\u00a0no siente como un lastre la etiqueta\u00a0&#8216;The Special One&#8217; heredada en Inglaterra. Es ahora, en su peor momento como t\u00e9cnico\u00a0blanco, cuando debe demostrar por qu\u00e9\u00a0es el entrenador mejor pagado del mundo y puede\u00a0disponer de fichajes con los que otros clubes de la Liga ajustan un presupuesto anual.<\/p>\n<p><a href=\"\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2012\/09\/cholo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-140\" src=\"\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2012\/09\/cholo.jpg\" alt=\"\" width=\"635\" height=\"422\" srcset=\"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2012\/09\/cholo.jpg 635w, https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2012\/09\/cholo-300x199.jpg 300w\" sizes=\"auto, (max-width: 635px) 100vw, 635px\" \/><\/a><\/p>\n<p>Necesita un reacci\u00f3n en la Champions y\u00a0pondr\u00e1 todo el empe\u00f1o en lograr que el City sea el rival\u00a0adecuado para sacarse los miedos del cuerpo.\u00a0La \u00faltima vez que vivi\u00f3 algo similar, un empate europeo ante el\u00a0modesto\u00a0Rosenborg\u00a0acab\u00f3 perdiendo su plaza en el\u00a0banquillo. <strong><a title=\"Mou deja el Chelsea\" href=\"http:\/\/news.bbc.co.uk\/hi\/spanish\/deportes\/newsid_7003000\/7003915.stm\" target=\"_blank\" rel=\"external nofollow\">Dej\u00f3 de entrenar a un Chelsea que posteriomente llegar\u00eda a una final de la Champions que\u00a0\u00e9l no pudo alcanzar como blue<\/a>.<\/strong> Queda por ver si\u00a0su speech ha servido de revulsivo o\u00a0s\u00f3lo ha avivado el sentimiento interno actual de la caseta: los triunfos tienen un solo padre y la derrota siempre las mismas caras.\u00a0 Antes de volver a pisar\u00a0el c\u00e9sped,\u00a0parece que ha conseguido <strong><a title=\"Mourinho incendia el vestuario\" href=\"http:\/\/www.grada360.com\/futbol\/20120916\/mourinho-incendia-vestuario-201209161923-rc.html\" target=\"_blank\" rel=\"external nofollow\">abrir un poco m\u00e1s la brecha entre los\u00a0espa\u00f1oles y el\u00a0grupo\u00a0que habla portugu\u00e9s<\/a>.\u00a0<\/strong><\/p>\n<p><strong><a href=\"http:\/\/www.grada360.com\/futbol\/equipos\/atletico-de-madrid\/20120917\/simeone-apure-cambios-responsabilidad-201209170004-ag.html\" target=\"_blank\" rel=\"external nofollow\">&#8220;El culpable soy yo por errar con los cambios&#8221;.<\/a> <\/strong>Las palabras son de Diego Pablo Simeone para explicar lo sucedido en los apenas <a title=\"Atl\u00e9tico 4-3 Rayo\" href=\"http:\/\/www.grada360.com\/futbol\/liga-primera\/20120916\/goleada-atletico-antes-caraja-201209162343-g3.html\" target=\"_blank\" rel=\"external nofollow\">seis minutos que fueron desde el 4-0 al 4-3 entre Atl\u00e9tico y Rayo<\/a>. Desde que lleg\u00f3 al club, supo que ten\u00eda tarea entre manos.\u00a0La afici\u00f3n no cre\u00eda en el proyecto, tampoco\u00a0unos jugadores que fueron incapaces de\u00a0remontar una eliminatoria ante el Albacete pese a saber que Manzano ya no seguir\u00eda en el campo.\u00a0Cholo tuvo que armar la t\u00e1ctica, recuperar psicol\u00f3gicamente al grupo,\u00a0alentar a la afici\u00f3n para que\u00a0no decayera animando a los suyos, aleccionar a los recogepelotas sobre los tempos\u00a0a la hora de\u00a0devolver los\u00a0balones\u00a0y apagar varios incendios ante\u00a0la prensa. Todo\u00a0lo\u00a0que fuera necesario por el bien del equipo.<\/p>\n<p>Su objetivo era devolver la gloria al Atl\u00e9tico y\u00a0se esforz\u00f3 en encontrar aliados para\u00a0completar la misi\u00f3n.\u00a0Los encontr\u00f3 y\u00a0los atl\u00e9ticos tocaron el cielo en Bucarest y<strong> <a title=\"Supercopa Europa\" href=\"http:\/\/blogs.grada360.com\/rodrierrasti\/2012\/08\/31\/el-tigre-los-leones-y-el-calor\/\" target=\"_blank\" rel=\"external nofollow\">hace solo unos d\u00edas en M\u00f3naco<\/a>.\u00a0<\/strong>Durante su etapa de jugador, determinados comportamientos afearon la carrera de un futbolista de esos que todo el mundo prefer\u00eda tener a su lado a verlo en la escuadra contraria. Ahora como t\u00e9cnico ha logrado aplacar esa parte visceral que le hac\u00eda perder puntos como futbolista.<\/p>\n<p>La pregunta es: \u00bfA qui\u00e9n se llevar\u00edan ustedes de los dos&#8230; para\u00a0su trabajo? Mi amigo, el que siente la pasi\u00f3n por el rugby, lo tiene claro: Cholo.<\/p>\n<p>PD: <strong><a title=\"Viggo sobre Morunho y Simeone\" href=\"http:\/\/www.republica.com\/2012\/09\/06\/viggo-mortensen-simeone-le-rompe-el-culo-a-patadas-a-mourinho_544337\/\" target=\"_blank\" rel=\"external nofollow\">Pese a todo lo explicado y, aunque el viernes me encontr\u00e9 con \u00e9l por Madrid, no hablo de Viggo Mortensen<\/a>.<\/strong><\/p>\n<p><!--:--><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Una persona, de esas que te marcan\u00a0para siempre, me explic\u00f3\u00a0un teor\u00eda sobre el deporte,\u00a0el trabajo y la vida basada en muchos a\u00f1os habitando en distintos lugares de\u00a0Europa.\u00a0Este buen hombre considera que las personas se comportan en su puesto laboral del mismo modo que lo hacen cuando practican un deporte colectivo.\u00a0Un par de partidos son efectivos [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":159,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[158,196],"class_list":["post-133","post","type-post","status-publish","format-standard","hentry","category-liga","tag-mourinho-2","tag-simeone"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/posts\/133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/users\/159"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/comments?post=133"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/posts\/133\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/media?parent=133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/categories?post=133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/tags?post=133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}