{"id":211,"date":"2012-10-31T14:14:21","date_gmt":"2012-10-31T12:14:21","guid":{"rendered":"http:\/\/blogs.grada360.com\/rodrierrasti\/?p=211"},"modified":"2012-10-31T14:14:21","modified_gmt":"2012-10-31T12:14:21","slug":"la-memoria-de-mourinho","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/2012\/10\/31\/la-memoria-de-mourinho\/","title":{"rendered":"La memoria de Mourinho"},"content":{"rendered":"<p><!--:es-->Estoy preocupado por Jos\u00e9 Mourinho. M\u00e1s en concreto por su memoria. Muchos se han sorprendido de que, pese a sacar una lista (algo que ya hizo un d\u00eda para denunciar lo que a su juicio eran 13 errores arbitrales) <strong><a title=\"\" href=\"http:\/\/www.grada360.com\/futbol\/equipos\/real-madrid-cf\/20121030\/mourinho-vuelve-criticar-toril-20121030-g3.html\" target=\"_blank\" rel=\"external nofollow\">se olvidara de canteranos madridistas como Diego L\u00f3pez, De la Red, Granero, Soldado, Javi Garcia, Miguel Torres, Jurado<\/a>.<\/strong>.. sin mencionar a internacionales e incluso campeones de Europa como Mata o Negredo que pasaron por el filial blanco.<\/p>\n<p>A m\u00ed no me extra\u00f1an estos olvidos. Desde hace un tiempo para esta parte me parece que ha perdido algo capacidad de retentiva. Conoc\u00ed sus primeros s\u00edntomas en 2007, cuando en una reuni\u00f3n de entrenadores en Nyon me respondi\u00f3 a una sencilla pregunta que\u00a0hab\u00eda\u00a0olvidado su castellano&#8230; y luego que no sab\u00eda hablar ingl\u00e9s. Curioso, porque a\u00fan era t\u00e9cnico del Chelsea. Deb\u00eda ser la humedad que provoca el lago Leman, el m\u00e1s grande de Suiza, junto a la sede de la UEFA. <!--:--><!--:en--><\/p>\n<p><!--:--><!--more--><!--:es--><\/p>\n<p><a href=\"\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2012\/10\/Jose_Mourinho.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-225\" src=\"\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2012\/10\/Jose_Mourinho.jpg\" alt=\"\" width=\"500\" height=\"270\" srcset=\"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2012\/10\/Jose_Mourinho.jpg 500w, https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2012\/10\/Jose_Mourinho-300x162.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a>En su primer a\u00f1o en el Real Madrid hubo varias situaciones que me hicieron pensar en esos olvidos.<strong> <a title=\"Rueda de prensa de Mourinho tras 0-2 con el Barcelona\" href=\"https:\/\/www.youtube.com\/watch?v=owirZzy0Qag\" target=\"_blank\" rel=\"external nofollow\">La noche que habl\u00f3 del supuesto complot arbitral para favorecer al Barcelona. Ese d\u00eda dej\u00f3 claro que ten\u00eda interiorizado el nombre de algunos \u00e1rbitros:\u00a0De Bleeckere, Frisk, Busacca\u00a0y sobre todo Ovrebo<\/a><\/strong>. Parec\u00eda tener muy fresco lo que defini\u00f3 como &#8220;el esc\u00e1ndalo de Stamford Bridge&#8221; pese a que \u00e9l no era el entrenador del Chelsea, ya que sali\u00f3 al inicio de la campa\u00f1a anterior en la que Avram Grant finalmente meti\u00f3 al equipo en la final de Mosc\u00fa ante el Manchester United.<\/p>\n<p>Por contra,<a title=\"Olegario Benquerenca, Inter-Barcelona\" href=\"http:\/\/www.elmundo.es\/elmundodeporte\/2010\/04\/21\/futbol\/1271838461.html\" target=\"_blank\" rel=\"external nofollow\"><strong> no se acord\u00f3 de lo sucedido un a\u00f1o antes con Oleg\u00e1rio Benqueren\u00e7a\u00a0en el partido del\u00a0Giuseppe Meazza<\/strong><\/a>\u00a0ante ese mismo rival, ni tampoco de la eliminatoria contra el Deportivo en 2004 en la que fue favorecido por Merk con una <strong><a title=\"Andrade habl\u00f3 con Deco que era una broma\" href=\"http:\/\/deportesar.terra.com.ar\/mundialdeclubes2008\/interna\/0,,OI297308-EI4402,00.html\" target=\"_blank\" rel=\"external nofollow\">expulsi\u00f3n incre\u00edble de Andrade al hacer una &#8220;brincadeira&#8221;<\/a>\u00a0<\/strong>a su amigo Deco en Do Dragao.<\/p>\n<p><strong><\/strong>En los \u00faltimos meses est\u00e1 en plena b\u00fasqueda de &#8220;madridistas disfrazados&#8221;, esos que<a title=\"Xabi Alonso\" href=\"http:\/\/www.grada360.com\/futbol\/equipos\/real-madrid-cf\/20121017\/xabi-alonso-calendario-apretado-201210171448-ag.html\" target=\"_blank\" rel=\"external nofollow\"> Xabi Alonso dijo no conocer d\u00edas despu\u00e9s<\/a>, despu\u00e9s de que hubiese localizado a algunos &#8220;pseudomadridistas&#8221;. A muchos les choca que Mourinho sea ahora el que catalogue la intensidad del madridismo, a\u00f1os despu\u00e9s de que en un balc\u00f3n de la plaza de Sant Jordi dijera que &#8220;siempre llevar\u00eda al Bar\u00e7a en el coraz\u00f3n&#8221;.<\/p>\n<p>En las redacciones siempre hay uno que tiene mucha memoria, alguno hasta presume de tener memoria fotogr\u00e1fica, pero al final siempre es m\u00e1s efectivo tirar de archivo documental. Por eso, ante la falta de memoria, hemeroteca.<!--:--><!--:en--><\/p>\n<p><!--:--><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Estoy preocupado por Jos\u00e9 Mourinho. M\u00e1s en concreto por su memoria. Muchos se han sorprendido de que, pese a sacar una lista (algo que ya hizo un d\u00eda para denunciar lo que a su juicio eran 13 errores arbitrales) se olvidara de canteranos madridistas como Diego L\u00f3pez, De la Red, Granero, Soldado, Javi Garcia, Miguel [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":159,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,26],"tags":[],"class_list":["post-211","post","type-post","status-publish","format-standard","hentry","category-mourinho","category-real-madrid"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/posts\/211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/users\/159"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/comments?post=211"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/posts\/211\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/media?parent=211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/categories?post=211"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/tags?post=211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}