{"id":341,"date":"2013-01-17T03:41:01","date_gmt":"2013-01-17T01:41:01","guid":{"rendered":"http:\/\/blogs.grada360.com\/rodrierrasti\/?p=341"},"modified":"2013-01-17T03:41:01","modified_gmt":"2013-01-17T01:41:01","slug":"341","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/2013\/01\/17\/341\/","title":{"rendered":"Mod\u00e9licos entrenadores y t\u00e9cnicos modelo"},"content":{"rendered":"<p><!--:es-->Los torneos coperos siempre me han emocionado, quiz\u00e1 por la pasi\u00f3n que ve\u00eda a mi alrededor cuando era chico en mis vecinos vizcainos. Ahora sigo con adoraci\u00f3n desde la distancia la <a title=\"FA Cup\" href=\"http:\/\/blogs.grada360.com\/tacklewithheels\/2013\/01\/16\/la-copa-de-los-suenos\/\" rel=\"external nofollow\">FA Cup<\/a> y la cl\u00e1sica Carling, ahora rebautizada como Capital One League Cup. Asistir a una final en Wembley, aunque sea al nuevo, es algo que recomiendo a todo aficionado al deporte. Pese a que aqu\u00ed los grandes han conseguido comprar parte de la emoci\u00f3n de los peque\u00f1os, a base de una partida econ\u00f3mica, hemos viv\u00eddo unos cuartos de final realmente intensos. En ellos, los entrenadores han sido los protagonistas de los encuentros, por encima incluso de los verdaderos actores principales que son los futbolistas. El rol de secundario cada vez m\u00e1s lo tienen m\u00e1s asumido los aficionados, a los que se castiga con horarios imposibles que provocan hasta <a href=\"http:\/\/twitter.com\/anderherrera8\/status\/291615821745254400\" title=\"Ander Herrera se queja de los horarios\" target=\"_blank\" rel=\"external nofollow\">la indignaci\u00f3n de otros deportistas que asisten al espect\u00e1culo por la televisi\u00f3n<\/a>.<\/p>\n<p>A expensas de lo que nos deje el Atl\u00e9tico-Betis, varios son los nombres propios de estos cuartos que algunos hab\u00edan sentenciado antes de jugarse. El primero ha sido Ernesto Valverde, que ha llegado a Valencia para obtener resultados algo para lo cual antes era necesario poner orden y cordura. Por el momento ha conseguido lo segundo y fue el mejor representante de una entidad a la que acaba de llegar en la cl\u00e1sica crisis provocada por un arbitraje contrario en el Santiago Bernab\u00e9u. <a title=\"Valencia y el arbitraje\" href=\"http:\/\/www.grada360.com\/futbol\/liga-primera\/videos\/20130116\/valencia-clama-contra-arbitraje-santiago-bernabeu-qvjufvu5otmk1924yp7v61zdc-agen.html\" rel=\"external nofollow\"><strong>Otros optaron por llorar y patalear<\/strong><\/a>, pero Ernesto prefiri\u00f3 ser elegante como siempre. Pese a que hab\u00eda sufrido una expulsi\u00f3n rid\u00edcula (el acta confirma que su pecado fue lanzar los guantes al suelo tras no poder completar un cambio con uno menos al que estaba autorizado) mantuvo la calma y estuvo a la altura de su escudo. Aferrarse a errores ajenos cuando has cometido varios le parece una coartada de mediocres y no tiene por costumbre utilizarla.<\/p>\n<p><!--:--><!--:en--><\/p>\n<p>\n<!--:--><!--more--><!--:es--><a href=\"\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2013\/01\/valverde_mou-e1358387874272.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-346\" src=\"\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2013\/01\/valverde_mou-e1358387874272.jpg\" alt=\"\" width=\"562\" height=\"404\" srcset=\"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2013\/01\/valverde_mou-e1358387874272.jpg 562w, https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2013\/01\/valverde_mou-e1358387874272-300x216.jpg 300w\" sizes=\"auto, (max-width: 562px) 100vw, 562px\" \/><\/a>A muchos les llam\u00f3 la atenci\u00f3n porque apenas unas horas antes el jugador rival que sali\u00f3 a dar la cara por su t\u00e9cnico antes del choque s\u00ed que lo hizo. <strong><a title=\"Di Mar\u00eda insin\u00faa que los \u00e1rbitros se equivocan intencionadamente  \" href=\"http:\/\/www.grada360.com\/futbol\/liga-primera\/videos\/20130114\/maria-sobre-arbitros-ultimamente-madrid-estan-confundiendo-2092681190001-agen.html\" rel=\"external nofollow\">Di Mar\u00eda, en pobre estado de forma, tampoco estuvo a la altura frente a los micr\u00f3fonos y partin\u00f3 gravemente<\/a><\/strong>. Como ya lo hab\u00edan hecho otros compa\u00f1eros suyos que hab\u00edan deslizado con anterioridad una campa\u00f1a orquestada en contra del Real Madrid. Algo a lo que se ha aferrado siempre Jos\u00e9 Mourinho, ahora silbado por la parte de la grada que no sigue a pies juntillas su credo, cuando le han ido mal dadas. En Portugal, en Inglaterra, en Italia y en Espa\u00f1a. <strong>Lo curioso es que <a title=\"Hay soluci\u00f3n contra la persecuci\u00f3n a Mourinho\" href=\"http:\/\/blogs.grada360.com\/rodrierrasti\/2012\/11\/26\/la-solucion-contra-la-persecucion-a-mourinho\/\" rel=\"external nofollow\">siempre han perseguido a Mourinho, tanto cuando estaba en el Barcelona como ayudante como ahora<\/a><\/strong>. Demasiada fijaci\u00f3n. <strong><a title=\"Mu\u00f1iz y la teor\u00eda\" href=\"http:\/\/www.grada360.com\/futbol\/copa-del-rey\/20130115\/real-madrid-valencia-muniz-201301152341-g3.html\" rel=\"external nofollow\">Y no, no hablo de Mu\u00f1iz<\/a>.<\/strong> Prefiero obviarlo porque me parece demasiado recurrente centrar los errores siempre en el mismo, por muy mal que acostumbre a actuar.<\/p>\n<p>En Zaragoza vimos un duelo curioso, con un Emery reci\u00e9n llegado al banquillo del que sacaron a Manolo Jim\u00e9nez cuando hab\u00eda metido a su &#8216;Sevilla&#8217; en una final copera tras apear al mejor Bar\u00e7a de la historia. Fue raro, <strong><a title=\"Emery se estrena con 0-0\" href=\"http:\/\/www.grada360.com\/futbol\/copa-del-rey\/20130116\/zaragoza-sevilla-empatan-estreno-201301162303-g3.html\" rel=\"external nofollow\">y no hablo del 0-0 final<\/a><\/strong>, porque Emery ha vuelto tras arrancar este a\u00f1o en Mosc\u00fa poniendo en apuros al Barcelona en la Champions. Precisamente ante los azulgrana se enfrent\u00f3 el segundo t\u00e9cnico que quiero destacar: <a title=\"Analiza el 2-2\" href=\"http:\/\/www.grada360.com\/futbol\/copa-del-rey\/20130117\/pellegrini-segundo-tiempo-superamos-201301170009-ag.html\" rel=\"external nofollow\">Manuel Pellegrini<\/a>.<\/p>\n<p>Un se\u00f1or que siempre ha brillado en todos los equipos por lo que ha pasado y que en el Real Madrid recibi\u00f3 un juicio excesivo, especialmente el medi\u00e1tico, comparado con el jab\u00f3n que se han llevado otros en su cargo. En Chamart\u00edn pag\u00f3 muy caro un remate fallido a la madera de uno de sus delanteros y una vergonzosa actitud en Santo Domingo de su once, de garant\u00edas aunque fueran suplentes, plagado de una mayor\u00eda de internacionales. Ni tan siquiera un r\u00e9cord de puntos liguero le sirvi\u00f3 para ganarse el respeto de un sector del madridismo. Acudi\u00f3 al rescate del M\u00e1laga y pese a todos los problemas institucionales ha conseguido cerrar la boca con resultados a los que afearon su decisi\u00f3n de aterrizar en la Costa del sol.<\/p>\n<p>En esta ronda ante el Barcelona de Tito, el hombre que est\u00e1 siendo un ejemplo en la adversidad por su naturalidad y constancia en el trabajo, ha conseguido llegar en ventaja al duelo de vuelta en La Rosaleda. <a title=\"Bar\u00e7a 2-2 M\u00e1laga\" href=\"http:\/\/www.grada360.com\/futbol\/copa-del-rey\/20130116\/malaga-empata-ultimo-minuto-201301162347-g3.html\" rel=\"external nofollow\"><strong>Un 2-2 meritorio, sobre todo por lograrlo en inferioridad num\u00e9rica y tras sufrir un varapalo an\u00edmico liguero 72 horas antes<\/strong><\/a>.<\/p>\n<p><a href=\"\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2013\/01\/pellegrini-guardiola.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-345\" src=\"\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2013\/01\/pellegrini-guardiola.jpg\" alt=\"\" width=\"562\" height=\"386\" srcset=\"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2013\/01\/pellegrini-guardiola.jpg 562w, https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2013\/01\/pellegrini-guardiola-300x206.jpg 300w\" sizes=\"auto, (max-width: 562px) 100vw, 562px\" \/><\/a><\/p>\n<p>Por \u00faltimo, y antes de que <a href=\"http:\/\/www.grada360.com\/futbol\/copa-del-rey\/20130116\/simeone-cuartos-partido-empieza-201301161424-ag.html\" rel=\"external nofollow\">Simeone<\/a> y Mel vuelvan a sumar argumentos para que les lance flores, no quiero terminar sin desear suerte a <a title=\"Guardiola, al Bayern\" href=\"http:\/\/www.grada360.com\/futbol\/20130116\/oficial-guardiola-entrenador-bayern-201301161653-g3.html\" rel=\"external nofollow\"><strong>Pep Guardiola en su aventura b\u00e1vara<\/strong><\/a>. Su reto es enorme, a la altura de su incre\u00edble palmar\u00e9s y capacidad, pero no es hombre de arrugarse ante los retos. Siempre se ha gu\u00edado por su instinto y ha terminado acertando. <a title=\"Por encima\u2026 del bien y del mal\" href=\"http:\/\/blogs.grada360.com\/rodrierrasti\/2012\/12\/22\/por-encima-del-bien-y-del-mal\/\" rel=\"external nofollow\">A muchos su exceso respeto por el rival parece incluso molestarles, debe ser que es mejor insinuar tramas y ver conspiraciones para justificar los fracasos propios que ser capaz de valorar el m\u00e9rito rival<\/a>. Yo sin duda prefiero el respeto. Y la admiraci\u00f3n por el trabajo ajeno. \u00a1Suerte!<!--:--><!--:en--><\/p>\n<p><!--:--><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Los torneos coperos siempre me han emocionado, quiz\u00e1 por la pasi\u00f3n que ve\u00eda a mi alrededor cuando era chico en mis vecinos vizcainos. Ahora sigo con adoraci\u00f3n desde la distancia la FA Cup y la cl\u00e1sica Carling, ahora rebautizada como Capital One League Cup. Asistir a una final en Wembley, aunque sea al nuevo, es [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":159,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,15],"tags":[95,109,123,151,158,171,196,208,212],"class_list":["post-341","post","type-post","status-publish","format-standard","hentry","category-copa","category-futbol","tag-emery","tag-guardiola","tag-jimenez","tag-mel","tag-mourinho-2","tag-pellegrini","tag-simeone","tag-valverde","tag-vilanova-2"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/posts\/341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/users\/159"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/comments?post=341"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/posts\/341\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/media?parent=341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/categories?post=341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/tags?post=341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}