{"id":451,"date":"2013-04-08T20:15:35","date_gmt":"2013-04-08T18:15:35","guid":{"rendered":"http:\/\/blogs.grada360.com\/rodrierrasti\/?p=451"},"modified":"2013-04-08T20:15:35","modified_gmt":"2013-04-08T18:15:35","slug":"los-sonidos-del-futbol-mas-emocionante","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/2013\/04\/08\/los-sonidos-del-futbol-mas-emocionante\/","title":{"rendered":"Los sonidos del f\u00fatbol m\u00e1s emocionante"},"content":{"rendered":"<p><!--:es--><span style=\"font-size: 13px;line-height: 19px\">No hab\u00eda cumplido los cinco a\u00f1os cuando el f\u00fatbol brit\u00e1nico se cruz\u00f3 por primera vez en mi camino. Fue en 1982, cuando miles de ingleses colapsaron Bilbao para arropar a su selecci\u00f3n en el estreno del Mundial. Eran, por entonces, los dominadores del f\u00fatbol europeo. Todo equipo ingl\u00e9s que jugaba la Copa de Europa ganaba la competici\u00f3n, a\u00fan siendo su estreno en la misma (como el hist\u00f3rico Nottingham Forest que tiene m\u00e1s Copas de Europa que Ligas). <\/span><\/p>\n<p><span style=\"font-size: 13px;line-height: 19px\"><!--:--><!--:en--><\/p>\n<p>\n<!--:--><!--more--><!--:es-->Iban cantando, con sus camisetas blancas y con unas rayas rojas y azules en la zona pectoral (a m\u00ed me parec\u00eda lo m\u00e1s aquello de tener camisetas como la que realmente llevaba la selecci\u00f3n), pero tuvieron tiempo de beberse todo lo que serv\u00edan los taberneros bilba\u00ednos. Llegaron tan hidratados al estadio que destrozaron la nueva tienda del, por entonces, recien remodelado San Mam\u00e9s, que sobrevivi\u00f3 intacta apenas unos minutos. Muchos de ellos no llegaron a ver el primer tanto de Bryan Robson, que durante muchos a\u00f1os fue el m\u00e1s r\u00e1pido de los mundiales a los 27 segundos, de los dos que hizo ante Francia (de blanco y liderada por Platini) aquel d\u00eda en el triunfo por 3-1.<\/span><\/p>\n<p>A los aficionados ingleses no parec\u00ed\u00f3 importarles que Keegan, estrella mundial en aquel momento, iniciara en el banquillo. Impresionaban tanto, que mi padre nos mand\u00f3 a casa y se march\u00f3 con mi tio al f\u00fatbol&#8230; los tres partidos del grupo. Ese a\u00f1o el campe\u00f3n de Europa era el Aston Villa. En Bilbao vi muchos aficionados con el le\u00f3n villano en sus camisetas y sudaderas. Mi curiosa retentiva fotograf\u00edca (a veces s\u00ed es una virtud) hizo que ese equipo pasara a formar parte del grueso de mis preferidos, uno de esos al que siendo adulto uno le profesa algo m\u00e1s que simpat\u00eda. El primer partido de competici\u00f3n europea entre clubes que recuerdo por televisi\u00f3n tambi\u00e9n tuvo acento brit\u00e1nico: fue un empate sin goles entre Liverpool y Athletic, de la Copa de Europa de 1983, con un marcador de ne\u00f3n en Anfield que destacaba los ceros de aquel 0-0 . Unos vecinos tuvieron la suerte de viajar all\u00ed y me relataron lo distinto que era aquello. \u00a1Vaya sonidos! \u00a1Qu\u00e9 ambientazo! En la vuelta, ganaron los &#8216;reds&#8217; con un gol de Ian Rush y meses despu\u00e9s levantaron el t\u00edtulo tras tumbar a la Roma en los penaltis, un a\u00f1o antes del mal recuerdo de Heysel.<\/p>\n<p>Uno, que es tan curioso como hablador, so\u00f1\u00f3 que alg\u00fan d\u00eda acudir\u00eda a comprobar si aquellos sonidos eran tan distintos a los de San Mam\u00e9s. Yo pensaba que si Jos\u00e9 Mar\u00eda Garc\u00eda dec\u00eda que La Catedral era el campo m\u00e1s ingl\u00e9s de la Liga, la cosa tampoco variar\u00eda mucho. Recuerdo que a medida que fui conociendo gente en el f\u00fatbol preguntaba: \u201c\u00bfTanto cambia el ambiente?\u201d, La respuesta siempre era \u201cs\u00ed, pero t\u00fa has ido mucho a San Mam\u00e9s. Es parecido\u201d. Ten\u00eda la mosca detr\u00e1s de la oreja, porque no recuerdo una persona m\u00e1s entusiasta con el Athletic que Howard Kendall. Muchos no recordar\u00e1n a este entrenador, que lleg\u00f3 tras triunfar en el Everton y se fue con lagrimones diciendo que su carrera iba a ir a peor al salir del Athletic. Kendall viv\u00eda en Lezama, tomaba vinos con los vecinos del pueblo y hasta consigui\u00f3 que un combinado llevase su apellido. Eso s\u00ed, recuerdo que en una entrevista habl\u00f3 de las peque\u00f1as diferencias entre ambas ligas (no en cuanto al juego ya que optaba por el estilo m\u00e1s cl\u00e1sico del &#8216;kick and rush&#8217;) y cit\u00f3&#8230; \u00a1los sonidos! A\u00f1os despu\u00e9s pude comprobar que el afable Howard y, aquellos vecinos que envidi\u00e9, ten\u00eda raz\u00f3n.<\/p>\n<p><a href=\"http:\/\/t.co\/CWKqDfj46x\" rel=\"external nofollow\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-454\" src=\"\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2013\/04\/Lineker-Magazine-Firma-Numero-8-Rodrigo-Errasti-e1366222943237.jpg\" alt=\"\" width=\"670\" height=\"477\" srcset=\"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2013\/04\/Lineker-Magazine-Firma-Numero-8-Rodrigo-Errasti-e1366222943237.jpg 670w, https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2013\/04\/Lineker-Magazine-Firma-Numero-8-Rodrigo-Errasti-e1366222943237-300x214.jpg 300w\" sizes=\"auto, (max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p>Siempre pens\u00e9 que ser\u00eda Villa Park el escenario elegido, pero me qued\u00e9 sin ir al duelo de vuelta de segunda ronda de la UEFA entre leones villanos y rojiblancos con la radio vizca\u00edna en la que hac\u00eda mi estreno como periodista en 1997. Un azar del destino quiso que mi bautizo fuese en Ibrox Park, aunque no he visitado ning\u00fan otro estadio brit\u00e1nico tantas veces como el coliseo villano de Birmingham. Me alucin\u00f3 la emoci\u00f3n con la que se vive cada c\u00f3rner, con ruido creciente hasta que el hombre con m\u00e1s clase del equipo golpea la bola al \u00e1rea desde el bander\u00edn; el &#8216;uuuuuuh&#8217; con el que gritan una acci\u00f3n antideportiva, que puede ser o no amarilla; el redondo y prolongado &#8216;oooooooooooooooooooh&#8217; con el que se celebra una buena parada del portero, el m\u00edtico &#8216;shoot&#8217; que suena como un castizo &#8216;sut&#8217; cuando un centrocampista estilo Lampard se acerca a la media luna, la ovaci\u00f3n cerrada a un tackle de un defensa para cortar un acci\u00f3n peligrosa rival pero sobre todo la celebraci\u00f3n de los goles. Son los inventores del f\u00fatbol, pero no gritan la palabra &#8216;goal&#8217; cuando su equipo logra marcar. No, y eso es lo que m\u00e1s llama la atenci\u00f3n de todo.<\/p>\n<p>Recuerdo que la primera vez que mi santa y paciente novia me acompa\u00f1\u00f3 a un campo ingl\u00e9s -a Villa Park para variar- se lo expliqu\u00e9. Lleg\u00f3 emocionada y atenta, record\u00e1ndome que\u00a0<em>su<\/em>\u00a0Deportivo de La Coru\u00f1a hab\u00eda vencido en su \u00fanica visita a ese estadio, pero en la jugada del \u00fanico gol local (los villanos por entonces jugaban competici\u00f3n europea y habitaban lejos del descenso) hubo tres rebotes previos al tanto. Cuando sucedi\u00f3 Marta cant\u00f3 &#8216;gol&#8217; y no repar\u00f3 en c\u00f3mo la hinchada local se desga\u00f1itaba con un prolongado &#8216;yeeeeeeeeeeeeees&#8217;. El Villa no marc\u00f3 m\u00e1s aquel d\u00eda. La cosa no pod\u00eda quedar as\u00ed y lo solucion\u00e9 con una nueva visita; esta vez al nuevo Wembley. Hubo tres goles en aquella final de la Copa de la Liga, el primero nada m\u00e1s empezar y de penalti. Antes de que lo lanzara, Marta me gui\u00f1\u00f3 un ojo y solt\u00f3 un &#8216;yeeeees&#8217; a la vez que los animados aficionados del Villa que nos rodeaban. El duelo acab\u00f3 con decepci\u00f3n para ellos, pero pudimos comprobar el respeto por la competici\u00f3n y sus tradiciones, por el adversario y su triunfo. Despu\u00e9s de aquella han llegado muchas m\u00e1s visitas y de todos los campos que he visitado, ya fueran nuevos como el City of Manchester, c\u00e9ntricos como Stamford Bridge o legendarios como Old Trafford he vuelto enamorado. Me gustan sus normas, sus tradiciones y sus sonidos. Y su trepidante ritmo. Ya tengo ganas de coger un vuelvo y volver. Y hace apenas unas semanas que estuve all\u00ed.<\/p>\n<p>Art\u00edculo original en <a title=\"Lineker magazine 8\" href=\"http:\/\/www.linekermagazine.es\/lineker-magazine-8\/\" target=\"_blank\" rel=\"external nofollow\"><strong>Lineker Magazine<\/strong><\/a><!--:--><!--:en--><\/p>\n<p><!--:--><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>No hab\u00eda cumplido los cinco a\u00f1os cuando el f\u00fatbol brit\u00e1nico se cruz\u00f3 por primera vez en mi camino. Fue en 1982, cuando miles de ingleses colapsaron Bilbao para arropar a su selecci\u00f3n en el estreno del Mundial. Eran, por entonces, los dominadores del f\u00fatbol europeo. Todo equipo ingl\u00e9s que jugaba la Copa de Europa ganaba [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":159,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[],"class_list":["post-451","post","type-post","status-publish","format-standard","hentry","category-premier-league"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/posts\/451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/users\/159"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/comments?post=451"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/posts\/451\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/media?parent=451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/categories?post=451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/tags?post=451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}