{"id":683,"date":"2013-10-07T23:49:15","date_gmt":"2013-10-07T21:49:15","guid":{"rendered":"http:\/\/blogs.grada360.com\/rodrierrasti\/?p=683"},"modified":"2013-10-07T23:49:15","modified_gmt":"2013-10-07T21:49:15","slug":"la-liga-debe-evitar-acabar-siendo-la-acb","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/2013\/10\/07\/la-liga-debe-evitar-acabar-siendo-la-acb\/","title":{"rendered":"La Liga debe evitar acabar siendo la ACB"},"content":{"rendered":"<p><!--:es-->Ya sabemos <a title=\"El cl\u00e1sico se jugar\u00e1 el s\u00e1bado 26 a las 18.00 horas\" href=\"http:\/\/www.grada360.com\/futbol\/20131007\/clasico-jugara-sabado-horas-201310071820-rc.html\" target=\"_blank\" rel=\"external nofollow\"><strong>el horario de uno de los \u00fanicos dos partidos que, <\/strong>al parecer,<strong> tiene esta Liga<\/strong><\/a>. Hace nada, aqu\u00ed presum\u00edamos de <strong>Liga de las estrellas<\/strong>. Los mejores jugadores del mundo estaban en los clubes espa\u00f1oles. No s\u00f3lo en dos clubes, en varios de ella. En mi memoria reciente yo he visto jugar con el Valencia a <strong>Romario, Mijatovic, Villa, Mata, Silva<\/strong> o a los prometedores <strong>Aimar y Ortega<\/strong> en los 90. El Atl\u00e9tico, hasta hace dos d\u00edas, contaba con <strong>Forl\u00e1n <\/strong>y<strong> Kun<\/strong> que buscaban ocupar el hueco emocional de <strong>Torres<\/strong> que hered\u00f3 un &#8216;9&#8217; dejado por <strong>Vieri o Hasselbaink<\/strong>.<\/p>\n<p>No hace tanto, cuando uno acud\u00eda a ver f\u00fatbol en cualquier campo de Espa\u00f1a pod\u00eda encontrarse, si por ejemplo iba a Galicia, con <strong>Mazinho<\/strong> en el Celta y a s\u00f3lo unos kil\u00f3metros estaban otros dos campeones del mundo como <strong>Mauro Silva y Bebeto<\/strong> junto a un Bota de Oro como <strong>Roy Makaay<\/strong>.<\/p>\n<p><strong><a href=\"\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2013\/10\/mazinho-bebeto-romario-e1381186203978.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-701\" src=\"\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2013\/10\/mazinho-bebeto-romario-e1381186203978.jpg\" alt=\"\" width=\"675\" height=\"446\" srcset=\"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2013\/10\/mazinho-bebeto-romario-e1381186203978.jpg 675w, https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2013\/10\/mazinho-bebeto-romario-e1381186203978-300x198.jpg 300w\" sizes=\"auto, (max-width: 675px) 100vw, 675px\" \/><\/a><\/strong><\/p>\n<p>Uno puede contar con orgullo que lleg\u00f3 a observar de cerca al entonces mejor portero del mundo, <strong>Rinat Dassaev<\/strong>, en un Sevilla por el que pas\u00f3 <strong>Maradona <\/strong>o<strong>\u00a0Suker<\/strong>;\u00a0o que en el Zaragoza lleg\u00f3 a ver a <strong>Brehme, Caf\u00fa<\/strong> o <strong>Rijkaard<\/strong> ponerse la blanquilla. \u00a0 \u00a0<!--:--><!--:en--><\/p>\n<p><!--:--><!--more--><!--:es--><\/p>\n<p>Eso ya no sucede, y por desgracia, creo que volver\u00e1 a ocurrir. Ninguna estrella mundial del momento vendr\u00eda ahora a otro club de la Liga que no fuera el Real Madrid o Barcelona. Es cierto, y ya lo comentamos hace unas semanas <a title=\"Mejora la selecci\u00f3n, empeora la Liga\" href=\"http:\/\/www.grada360.com\/futbol\/seleccion-espanola\/20130812\/mejora-seleccion-empeora-liga-201308121834-g3.html\" target=\"_blank\" rel=\"external nofollow\"><strong>recordando el exitoso caso franc\u00e9s de los 90, que a\u00a0medida que mejora la Roja empeora la Liga<\/strong><\/a>. Pero no s\u00f3lo esa variable ha provocado esta situaci\u00f3n.<\/p>\n<p><a href=\"\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2013\/10\/kempes-senyera.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-703\" src=\"\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2013\/10\/kempes-senyera.jpg\" alt=\"\" width=\"300\" height=\"228\" srcset=\"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2013\/10\/kempes-senyera.jpg 700w, https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2013\/10\/kempes-senyera-300x229.jpg 300w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Muchos me recriminan que siempre recuerdo de que el Valencia fich\u00f3 al mejor del mundo (<strong>Kempes<\/strong>) tras un Mundial. Y es que\u00a0<strong>a\u00f1oro esas Ligas en la que la incertidumbre era propiedad de azulgranas o madridistas, que temblaban pensando en las visitas a San Sebasti\u00e1n, A Coru\u00f1a o Pamplona<\/strong> sin contar que ganar en Sevilla, Valencia o Bilbao era considerado un triunfo de post\u00edn y empatar un gran bot\u00edn. Uno hab\u00eda aprendido del f\u00fatbol <strong>lo esencial que le ense\u00f1aban en casa: &#8220;Partido el s\u00e1bado para las televisiones, el domingo el de la tele de &#8216;pago&#8217; y los dem\u00e1s a las cinco de la tarde<\/strong> despu\u00e9s de comer&#8221;.<\/p>\n<p><strong>Ahora, por desgracia, la incertidumbre liguera pasa por el horario en el que se juegan los encuentros de los clubes que no son Real Madrid o Barcelona<\/strong>. Y es que, como ya dec\u00eda este verano y quiz\u00e1 hasta suene repetitivo, <strong>el f\u00fatbol moderno se ha vuelto loco<\/strong>.\u00a0El viernes, <a title=\"M\u00e1laga-Osasuna en Cope\" href=\"https:\/\/twitter.com\/tjcope\/status\/386219698645254145\" target=\"_blank\" rel=\"external nofollow\">camino de los estudios de la Cadena Cope para comentar el M\u00e1laga-Osasuna<\/a> del viernes en <a title=\"Tiempo de Juego\" href=\"https:\/\/twitter.com\/tjcope\" target=\"_blank\" rel=\"external nofollow\">&#8216;Tiempo de Juego&#8217;<\/a>, habl\u00e9 con un buen amigo futbolero que me sorprendi\u00f3: desconoc\u00eda que uno de los dos equipos (el de su padre y al que siempre ha tenido una especial simpat\u00eda) jugaba esa noche a las 22:00 horas. Y eso que se emit\u00eda en abierto por Cuatro.<\/p>\n<p><a href=\"\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2013\/10\/joventut-poses-as-the-1994-european-cup-champions.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-704\" src=\"\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2013\/10\/joventut-poses-as-the-1994-european-cup-champions.jpg\" alt=\"\" width=\"200\" height=\"250\" \/><\/a>Esta an\u00e9cdota me trae a la memoria una conversaci\u00f3n con mi colega <a title=\"Rafa Aguilera\" href=\"https:\/\/twitter.com\/rafa_aguilera\" target=\"_blank\" rel=\"external nofollow\"><strong>Rafa Aguilera<\/strong><\/a>, con el que compart\u00ed muchos viajes y horas de trabajo.<em><strong> &#8220;\u00bfTe acuerdas del basket de los 80 y principios de los 90?<\/strong> Todo el mundo alucinaba con aquello y las Ligas eran peleadas por <em>Estudiantes,<\/em>\u00a0Joventut <\/em>(aquella final perdida ante el Partiz\u00e1n)<em>, Manresa&#8230; Luego <strong>empezaron a convertir la competici\u00f3n en algo clandestino, con horarios infernales<\/strong> y el fervor popular se perdi\u00f3 hasta el punto que <strong>s\u00f3lo los muy fan\u00e1ticos saben ya cuando se juegan los partidos de cada jornada<\/strong>, que duran 3 o 4 d\u00edas. La Liga regular no vale para nada y ya s\u00f3lo importa la Euroliga&#8221;.<\/em> \u00bfLe suena de algo?<\/p>\n<p>Lo cierto es que, aunque duela decirlo, cada d\u00eda est\u00e1 m\u00e1s cerca que algo similar pase con la Liga de f\u00fatbol. Pocos aficionados saben los horarios de los partidos desde que se empezaron a escalonar;<strong><a title=\"Ancelotti acabar\u00eda con 90 puntos\" href=\"http:\/\/www.grada360.com\/futbol\/equipos\/real-madrid-cf\/20131007\/real-madrid-ancelotti-acabaria-201310071955-g3.html\" target=\"_blank\" rel=\"external nofollow\"> ya s\u00f3lo se habla de Madrid y Bar\u00e7a hasta el punto de que los campeones de Liga superan los 90 puntos<\/a><\/strong> y apenas esto nos sorprende. S\u00f3lo sabemos cuando se juega la Champions League, que siempre tiene el mismo horario y se disputa en dos d\u00edas fijos. Eso ayuda. <strong>No me gusta que parezca que la competici\u00f3n est\u00e9 formada por dos y <em>hay 18 palmeros m\u00e1s<\/em>.<\/strong><\/p>\n<p>Por eso aplaudo la aparici\u00f3n de <a title=\"Simeone se esfuerza en crear equipo\" href=\"http:\/\/blogs.grada360.com\/rodrierrasti\/2012\/09\/17\/tener-equipo-o-esforzarse-en-crearlo\/\" target=\"_blank\" rel=\"external nofollow\"><strong>Diego Simeone<\/strong> <\/a>en la Liga. Con su esp\u00edritu ganador hace que el Atl\u00e9tico no convierta esto, como dijo aquella vez <strong>Luis Fern\u00e1ndez<\/strong>, en un torneo de dos en el que los dem\u00e1s luchan por <em><a title=\"Cambios y soluciones para no sentir verg\u00fcenza\" href=\"http:\/\/blogs.grada360.com\/rodrierrasti\/2012\/09\/24\/cambios-y-soluciones-para-no-sentir-verguenza\/\" target=\"_blank\" rel=\"external nofollow\">&#8220;la Liga del chorizo y el jam\u00f3n&#8221;<\/a>. <\/em>Y la Copa del Rey, con este formato actual, ha quedado reducida casi a una Copa de la Liga. Otra pena.<\/p>\n<p><a href=\"\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2013\/10\/Simeone_388154515.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-706\" src=\"\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2013\/10\/Simeone_388154515.jpg\" alt=\"\" width=\"300\" height=\"207\" srcset=\"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2013\/10\/Simeone_388154515.jpg 2777w, https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2013\/10\/Simeone_388154515-300x207.jpg 300w, https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2013\/10\/Simeone_388154515-768x531.jpg 768w, https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2013\/10\/Simeone_388154515-1024x708.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Hay mucha gente que se queja que <a title=\"Los sonidos del f\u00fatbol m\u00e1s emocionante\" href=\"http:\/\/blogs.grada360.com\/rodrierrasti\/2013\/04\/08\/los-sonidos-del-futbol-mas-emocionante\/\" target=\"_blank\" rel=\"external nofollow\"><strong>con demasiada admiracion de la Premier<\/strong><\/a>. Quiz\u00e1 sea verdad, pero es f\u00e1cil hacerlo cuando sabes qu\u00e9 d\u00eda juega cada uno de los equipos participantes. Se sortea el calendario en julio y todos saben cuando jugar\u00e1n cada uno de los clubes las 38 jornadas. Y si hay un imprevisto, all\u00ed tambi\u00e9n llueve y nieva en invierno, hay fechas libres para solucionarlo. <\/p>\n<p>Sinceramente, est\u00e1 en las manos de todos frenar la din\u00e1mica actual que convertir\u00e1 esta Liga, ahora parada por los duelos en los que la selecci\u00f3n lograr\u00e1 el pase para el Mundial, en <a title=\"Gay de Liebana dice que el f\u00fatbol espa\u00f1ol est\u00e1 hundido\" href=\"http:\/\/www.grada360.com\/futbol\/liga-primera\/20120921\/economista-dice-futbol-espanol-201209210952-g3.html\" target=\"_blank\" rel=\"external nofollow\"><strong>un torneo clandestino que juegan 16 equipos -la mayor\u00eda endeudados y al borde la quiebra-<\/strong><\/a> m\u00e1s los dos &#8216;afortunados&#8217; que se miden ese fin de semana a esos clubes m\u00e1s medi\u00e1ticos. Evitemos que esto sea otra ACB.<!--:--><!--:en--><\/p>\n<p><!--:--><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Ya sabemos el horario de uno de los \u00fanicos dos partidos que, al parecer, tiene esta Liga. Hace nada, aqu\u00ed presum\u00edamos de Liga de las estrellas. Los mejores jugadores del mundo estaban en los clubes espa\u00f1oles. No s\u00f3lo en dos clubes, en varios de ella. En mi memoria reciente yo he visto jugar con el [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":159,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,12,18],"tags":[],"class_list":["post-683","post","type-post","status-publish","format-standard","hentry","category-baloncesto","category-clasico","category-liga"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/posts\/683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/users\/159"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/comments?post=683"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/posts\/683\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/media?parent=683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/categories?post=683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/tags?post=683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}