{"id":738,"date":"2013-11-28T10:36:36","date_gmt":"2013-11-28T08:36:36","guid":{"rendered":"http:\/\/blogs.grada360.com\/rodrierrasti\/?p=738"},"modified":"2013-11-28T10:36:36","modified_gmt":"2013-11-28T08:36:36","slug":"el-lider-y-la-fuerza-del-equipo","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/2013\/11\/28\/el-lider-y-la-fuerza-del-equipo\/","title":{"rendered":"El l\u00edder y la fuerza del equipo"},"content":{"rendered":"<p><!--:es--><a href=\"\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2013\/11\/Sergio_Ramos-Carlo_Ancelotti.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-751\" src=\"\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2013\/11\/Sergio_Ramos-Carlo_Ancelotti.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>Muchas veces hemos hablado que el Real Madrid es un conjunto de individualidades; que no es realmente un equipo sino un <em>conglomerado de estrellas<\/em> pero ganar a un rival europeo con inferioridad\u00a0durante m\u00e1s de una hora \u00a0incluso hacerle cuatro goles es algo m\u00e1s que un h<span style=\"font-size: 13px;line-height: 19px\">omenaje a <strong>Helenio Herrera<\/strong>. Una cosa es jugar mejor con uno menos como dec\u00eda el maestro y otra golear en toda una Champions. Y todo ello sin <strong>Cristiano Ronaldo<\/strong>, el supuesto l\u00edder de la manada. <strong>Un equipo unido es la manera m\u00e1s sencilla de poder conseguir objetivos<\/strong> y, obviamente, si cuentas con grandes jugadores es mucho m\u00e1s f\u00e1cil alcanzarlos. <\/span><\/p>\n<p><span style=\"font-size: 13px;line-height: 19px\">Es verdad que fue una manera de devolver el cari\u00f1o mostrado por su gol, pero no estuvo lejos de la reflexi\u00f3n un <strong>Arbeloa<\/strong> que parec\u00eda onmipresente: &#8220;<strong>Xabi Alonso<\/strong> cambia al Real Madrid&#8221;. <a title=\"Florentino P\u00e9rez: \u00abAnoche vimos a un gran equipo; \u00e9se es el camino\u00bb\" href=\"http:\/\/www-origin.grada360.com\/futbol\/20131128\/florentino-perez-anoche-vimos-201311281902-rc.html\" target=\"_blank\" rel=\"external nofollow\">Hasta <strong>Florentino P\u00e9rez<\/strong> lo ha visto claro: &#8220;El partido del Galatasaray es el camino&#8221;.<\/a>\u00a0Y<a title=\"Ramos, roja\" href=\"http:\/\/www.grada360.com\/futbol\/equipos\/real-madrid-cf\/20131128\/ramos-pone-espinas-cantera-201311281140-g3.html\" target=\"_blank\" rel=\"external nofollow\"><strong> Carlo\u00a0Ancelotti<\/strong>, que tuvo un cabreo con <strong>Sergio Ramos<\/strong>,<\/a> tambi\u00e9n lo vio claro.\u00a0<!--:--><!--:en--><\/p>\n<p><!--:--><!--more--><!--:es--><\/span><\/p>\n<p>Por contra, la cabeza m\u00e1s visible del otro club m\u00e1s medi\u00e1tico de la Liga (<strong>Tata Martino<\/strong>)\u00a0pas\u00f3 en Amstedam, quiz\u00e1, <strong>su peor d\u00eda desde que lleg\u00f3 a Barcelona<\/strong>. &#8220;\u00a1Mis equipos no hacen el rid\u00edculo!&#8221; bram\u00f3 &#8211;<a title=\"Broncazo del Tata Martino a la plantilla\" href=\"http:\/\/www.sport.es\/es\/noticias\/barca\/broncazo-del-tata-martino-plantilla-del-barca-2878711\" target=\"_blank\" rel=\"external nofollow\">seg\u00fan informan los dos diarios catalanes<\/a>&#8211; a voz en grito\u00a0en el descanso ante el Ajax. Ni su <em>broncazo<\/em>, ni los cambios de los pesos pesados (<strong>Puyol, Xavi <\/strong>y<strong> Cesc<\/strong>) por canteranos hambrientos, evitaron<span style=\"font-size: 13px;line-height: 19px\">\u00a0su primera derrota.<\/span><span style=\"font-size: 13px;line-height: 19px\">\u00a0<a title=\"Martino: \" href=\"http:\/\/www.grada360.com\/futbol\/equipos\/fc-barcelona\/videos\/20131127\/martino-hemos-perdido-duelos-individuales-2871966296001-agen.html\" target=\"_blank\" rel=\"external nofollow\">Al argentino le molest\u00f3 la falta de actitud e intensidad<\/a>. Es algo que a su compatriota <strong>Diego<\/strong>\u00a0<strong>Simeone<\/strong> le crispa sobre manera, aunque no se recuerda casos recientes en la \u00e9poca <em>Cholo\u00a0<\/em>en este Atl\u00e9tico suyo, fiel a su manera de entender el deporte. Trabajar hasta el final de la mano del compa\u00f1ero. Va en su ADN desde que era jugador.<a href=\"\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2013\/11\/Simeone-Copa-rey-manteado-jugadores-e1385660532396.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-749\" src=\"\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2013\/11\/Simeone-Copa-rey-manteado-jugadores-e1385660532396.jpg\" alt=\"\" width=\"675\" height=\"449\" srcset=\"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2013\/11\/Simeone-Copa-rey-manteado-jugadores-e1385660532396.jpg 675w, https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2013\/11\/Simeone-Copa-rey-manteado-jugadores-e1385660532396-300x200.jpg 300w\" sizes=\"auto, (max-width: 675px) 100vw, 675px\" \/><\/a><\/span><\/p>\n<p><a title=\"Tener equipo o esforzarse en crearlo\" href=\"http:\/\/blogs.grada360.com\/rodrierrasti\/2012\/09\/17\/tener-equipo-o-esforzarse-en-crearlo\/\" target=\"_blank\" rel=\"external nofollow\">Hace unos meses, uno recordaba en este mismo sitio la importancia del l\u00edder en un grupo. Diferenciaba entre el tipo que se limita a\u00a0<strong>encabezar a un equipo o el que se esfuerza en crearlo<\/strong><\/a>. En lo segundo, no hay nadie mejor que Simeone. Al menos por ahora.\u00a0<a title=\"Mod\u00e9licos entrenadores y t\u00e9cnicos modelo\" href=\"http:\/\/blogs.grada360.com\/rodrierrasti\/2013\/01\/17\/341\/\" target=\"_blank\" rel=\"external nofollow\"><strong>Por eso considero que hay t\u00e9cnicos modelo y mod\u00e9licos entrenadores<\/strong><\/a>. Existe un molde del que\u00a0<a title=\"Simeone: Sin el esfuerzo de los jugadores no ser\u00eda posible este momento\" href=\"http:\/\/www.grada360.com\/futbol\/equipos\/atletico-de-madrid\/20131107\/simeone-esfuerzo-jugadores-seria-201311072001-ag.html\" target=\"_blank\" rel=\"external nofollow\">suele cargar con las culpas y reparte los elogios<\/a>, mientras hay otro que acusa a los suyos en las malas: los triunfos tienen un solo padre y<a title=\"\" href=\"http:\/\/www.grada360.com\/futbol\/liga-campeones\/20131127\/mourinho-basilea-gano-porque-201311271329-ag.html\" target=\"_blank\" rel=\"external nofollow\">\u00a0la derrota siempre las mismas caras<\/a>. \u00a0Aunque se sienta poderoso la fuerza del equipo apunta hacia otra direcci\u00f3n. Y, antes o despu\u00e9s, est\u00e1 perdido.<br \/>\n<a href=\"\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2013\/11\/ribery-guardiola.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-752 alignright\" src=\"\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2013\/11\/ribery-guardiola.jpg\" alt=\"\" width=\"180\" height=\"125\" srcset=\"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2013\/11\/ribery-guardiola.jpg 620w, https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-content\/uploads\/sites\/205\/2013\/11\/ribery-guardiola-300x208.jpg 300w\" sizes=\"auto, (max-width: 180px) 100vw, 180px\" \/><\/a><\/p>\n<p>Y creo que el \u00e9xito de <strong>Pep Guardiola<\/strong>\u00a0en Barcelona, al margen de saber plasmar el f\u00fatbol de posici\u00f3n en un terreno de juego, <strong>fue tener al vestuario con \u00e9l a muerte<\/strong>. Como el d\u00eda que ofreci\u00f3 la ya famosa rueda de prensa del Santiago Bernab\u00e9u en la previa de las semifinales de Champions, cuando el equipo le aplaudi\u00f3 en el hotel pese a saltarse su autonorma de no entrar en provocaciones. Ahora, en el Bayern, parec\u00eda que tambi\u00e9n lo hab\u00eda conseguido. Al menos me llam\u00f3 la atenci\u00f3n <a title=\"El Bayern caza en los penaltis una Supercopa vibrante\" href=\"http:\/\/www.grada360.com\/futbol\/supercopa\/20130830\/bayern-caza-penaltis-supercopa-201308302351-g3.html\" target=\"_blank\" rel=\"external nofollow\"><strong>el abrazo de Ribery en Praga<\/strong><\/a>.<\/p>\n<p>Por eso <a title=\"Guardiola busca un topo en el Bayern de M\u00fanich\" href=\"http:\/\/www.grada360.com\/futbol\/liga-alemana\/20131124\/guardiola-busca-topo-bayern-201311242228-g3.html\" target=\"_blank\" rel=\"external nofollow\">me extra\u00f1a tanto lo de la obsesi\u00f3n con las, te\u00f3ricas, filtraciones de once titulares<\/a>. Raro, pero quiz\u00e1 sea algo que nos perdemos con la traducci\u00f3n&#8230; Lo digo porque para <a title=\"Gaby Milito: \" href=\"http:\/\/deportes.terra.es\/futbol\/gaby-milito-guardiola-tiene-el-don-de-clavarla,8dc7055e2ef92410VgnVCM3000009af154d0RCRD.html\" target=\"_blank\" rel=\"external nofollow\"><strong>Gaby Milito: &#8220;Guardiola tiene el don de clavarla&#8221;.<\/strong><\/a><!--:--><!--:en--><\/p>\n<p><!--:--><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Muchas veces hemos hablado que el Real Madrid es un conjunto de individualidades; que no es realmente un equipo sino un conglomerado de estrellas pero ganar a un rival europeo con inferioridad\u00a0durante m\u00e1s de una hora \u00a0incluso hacerle cuatro goles es algo m\u00e1s que un homenaje a Helenio Herrera. Una cosa es jugar mejor con [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":159,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[44,106,109,144,186,196],"class_list":["post-738","post","type-post","status-publish","format-standard","hentry","category-futbol","tag-ancelotti","tag-gaby-milito","tag-guardiola","tag-martino","tag-ribery","tag-simeone"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/posts\/738","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/users\/159"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/comments?post=738"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/posts\/738\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/media?parent=738"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/categories?post=738"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/rodrierrasti\/wp-json\/wp\/v2\/tags?post=738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}