{"id":1654,"date":"2013-10-11T08:05:16","date_gmt":"2013-10-11T07:05:16","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/series-gourmets\/?p=1654"},"modified":"2013-10-11T08:05:16","modified_gmt":"2013-10-11T07:05:16","slug":"matrimonio-con-hijos-la-familia-mas-impresentable-de-la-television","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/series-gourmets\/2013\/10\/11\/matrimonio-con-hijos-la-familia-mas-impresentable-de-la-television\/","title":{"rendered":"Matrimonio con hijos. La familia mas impresentable de la television"},"content":{"rendered":"<p>Matrimonio con hijos, fue una serie rompedora que ha pasado a la historia televisiva por diferentes razones, la primera de ellas es que fue la primera serie que emiti\u00f3 en 1987 un nuevo canal la cadena FOX, en un intento por romper el oligopolio de las tres cadenas hist\u00f3ricas americanas.<\/p>\n<p>Matrimonio con hijos fue la comedia mas irreverente en su momento y era la antitesis de la familia de Bill Cosby, que reinaba en los televisores de aquella \u00e9poca. Sus personajes eran pat\u00e9ticos, unos verdaderos perdedores que se dedicaban la mayor parte del tiempo, a tirarse puyas unos a otros y sin ning\u00fan objetivo, mas que ir tirando como buenamente pudieran, siempre que hubiera otro que estuviera peor que ellos.<\/p>\n<p>El estilo de humor era aparentemente zafio y de brocha gorda, con multitud de referencias sexuales, pero estaba mas elaborado de lo que parec\u00eda, diciendo muchas cosas que mucha gente pensaba pero que no atrev\u00edan a manifestar en alto, en especial sobre la insatisfacci\u00f3n de su vida sexual, pero siempre en clave jocosa y c\u00f3mica.<\/p>\n<p>La serie tuvo un enorme \u00e9xito en todo el mundo y provoc\u00f3 que muchos pa\u00edses, incluido el nuestro, hicieran adaptaciones de la serie, que siempre recordada como la serie que permiti\u00f3 subsistir a la cadena FOX, en sus primeros a\u00f1os de traves\u00eda del desierto televisivo, durante once exitosas temporadas.<\/p>\n<p><strong>Ficha:<\/strong> Matrimonio con hijos (Married\u2026.. with children) 259 episodios. Abr 1987-Jun 1997. Fox (USA)- la 2 (E)<\/p>\n<p><strong><a href=\"\/series-gourmets\/wp-content\/uploads\/sites\/37\/2013\/10\/married-with-children-e1380967674855.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1655\" title=\"married with children\" src=\"\/series-gourmets\/wp-content\/uploads\/sites\/37\/2013\/10\/married-with-children-e1380967674855.jpg\" alt=\"\" width=\"360\" height=\"540\" srcset=\"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2013\/10\/married-with-children-e1380967674855.jpg 360w, https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2013\/10\/married-with-children-e1380967674855-200x300.jpg 200w\" sizes=\"auto, (max-width: 360px) 100vw, 360px\" \/><\/a>Sinopsis:<\/strong> Al Bundy es un dependiente de una zapater\u00eda que lleva una vida bastante miserable, con una mujer que le esquilma todo el dinero que puede para sus caprichos, y dos hijos que no son ning\u00fan dechado de perfecci\u00f3n. La serie relata las historias de esta familia disfuncional, donde todos sus miembros son un peque\u00f1o desastre y sus pat\u00e9ticas historias.<\/p>\n<p><strong>El inicio:<\/strong> Ron Leavitt y Michael G. Moye eran dos veteranos guionistas que hab\u00edan trabajado en muchas sitcoms como \u2018Los Jefferson\u2019 y que crearon \u2018Silver Spoons\u2019, una serie para el lucimiento del actor infantil Ricky Schroeder.<\/p>\n<p><a href=\"\/series-gourmets\/wp-content\/uploads\/sites\/37\/2013\/10\/ron-leavitt-e-michael-g-moye-e1380967734205.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1656\" title=\"ron leavitt e michael g moye\" src=\"\/series-gourmets\/wp-content\/uploads\/sites\/37\/2013\/10\/ron-leavitt-e-michael-g-moye-e1380967734205.jpg\" alt=\"\" width=\"640\" height=\"526\" srcset=\"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2013\/10\/ron-leavitt-e-michael-g-moye-e1380967734205.jpg 640w, https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2013\/10\/ron-leavitt-e-michael-g-moye-e1380967734205-300x247.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a>Ambos recogieron el reto de la cadena FOX, de crear una comedia diferente para poner a la incipiente cadena en la mapa, y la idea la tuvieron clara, una serie gamberra para atraer a la nueva cadena un tipo de publico joven que pudiera ser atractivo a los anunciantes.<\/p>\n<p>Con la carta blanca de la cadena, no se pusieron limites y llevaron la s\u00e1tira y el rid\u00edculo de los personajes hasta donde se pod\u00eda llegar en una cadena en abierto, y el resultado fue un relativo \u00e9xito de publico con \u00a0algunas reacciones contrarias de la caverna americana, que no hicieron mas que atraer curiosos hacia la propuesta novedosa.<\/p>\n<p>El estilo diferente se puede comprobar desde la primera escena del episodio piloto, con una presentaci\u00f3n de los personajes bastante diferente a la habitual, en el primer video tienen los primeros cinco minutos de la serie, sentando las bases de por donde van a ir las cosas, con la sinton\u00eda a cargo de Frank Sinatra y su conocido \u2018Love and marriage\u2019 del a\u00f1o 1955 una magnifica elecci\u00f3n.<br \/>\n<iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/WRCg7xPne40\" frameborder=\"0\" width=\"640\" height=\"480\"><\/iframe><br \/>\n<strong>La trama:<\/strong> Como ya hemos comentado en otras ocasiones en este tipo de comedias, las tramas tienen relativamente poca importancia, lo importante son la definici\u00f3n de los personajes que cada semana se enfrentan a una situaci\u00f3n diferente y vemos como reaccionan de acuerdo a su personalidad definida y esperada por la audiencia.<\/p>\n<p>La primera broma interna es el nombre de la familia, ya que Bundy era el apellido del m\u00e1s famoso asesino en serie de los USA y llamarlo as\u00ed era toda una declaraci\u00f3n de intenciones.<\/p>\n<p>La familia Bundy vive en las afueras de Chicago y est\u00e1 formada por Al, un personaje que trabaja en una zapater\u00eda y que vive de sus recuerdos como antigua estrella del f\u00fatbol americano del instituto, es una persona ruin y mezquina, cuya m\u00e1xima ilusi\u00f3n al acabar el d\u00eda es sentarse a ver deporte en la tele con una cerveza en una mano, y con la otra \u00a0en la bragueta.<\/p>\n<p>Sus intentos por salir de su situaci\u00f3n penosa \u00a0montando esquemas y trapicheos, acaban siempre en desastre y est\u00e1 en un pozo del que no va a salir, en el video pueden ver una de sus peleas fatuas, esta vez contra los ordenadores, incluyendo un viaje on\u00edrico al pasado.<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/mPkq8kzmCiM\" frameborder=\"0\" width=\"640\" height=\"480\"><\/iframe><br \/>\nSu mujer Peggy, fue su amor de instituto, y se casaron muy j\u00f3venes y desde entonces ella no ha hecho nada de provecho, ya que ni trabaja fuera ni hace ninguna tarea en el hogar, dedic\u00e1ndose principalmente a cuidar su cuerpo y comprarse ropa, gastando el escaso dinero que gana su marido. Tiene un insaciable apetito sexual, pero su marido se resiste todo lo que puede y de hecho sus di\u00e1logos est\u00e1n siempre llenos de referencias a sus relaciones sexuales o m\u00e1s bien a su falta de ellas.<\/p>\n<p>La hija mayor Kelly es el prototipo de rubia espectacular y tonta, con enorme \u00e9xito entre los chicos, aunque en los estudios le cuesta hacer la O con un canuto. Siempre va vestida muy sexy, con min\u00fasculas minifaldas y tacones de v\u00e9rtigo y su \u00fanica preocupaci\u00f3n en la vida es pas\u00e1rselo bien y estar con el m\u00e1ximo n\u00famero de chicos. Sus trabajos suelen ser asociados a su belleza, siempre y cuando no abra la boca, como este video de un grupo rockero en el que aparece bailando.<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/LJWKwIcxc5Y\" frameborder=\"0\" width=\"640\" height=\"480\"><\/iframe><br \/>\nEl hijo menor Bud es el t\u00edpico adolescente salido, que va todo el d\u00eda detr\u00e1s de las chicas, aunque recibiendo m\u00e1s calabazas que un supermercado americano la semana anterior a Halloween. Es el mas listo de la familia, aunque en este caso es un dem\u00e9rito, ya que es constantemente humillado por sus padres y su hermana, cre\u00e1ndole un complejo de armas tomar, en el siguiente \u00a0video pueden ver \u00a0una recopilaci\u00f3n de sus mejores momentos, entre los que ver\u00e1n a una jovenc\u00edsima Keri Russell, ahora muy conocida.<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/OoaDKjbMcrs\" frameborder=\"0\" width=\"640\" height=\"480\"><\/iframe><br \/>\nPara compensar semejante desastre, tenemos a sus vecinos aparentemente normales, los Rhoades, Marcy es una persona de bien, aburrida, pol\u00edticamente correcta, feminista y que siempre acaba escandalizada por las historias y el comportamiento de Al, al que repudia enormemente, pero debido a su amistad con Peggy lo tiene que soportar.<\/p>\n<p>El marido de Marcy, Steve se ve arrastrado por las historias de Al, acompa\u00f1\u00e1ndole a clubs de striptease, ligando y haciendo todo tipo de actividades que su mujer le prohibe, la pareja ademas es \u00a0el objeto de multitud de ataques verbales por parte de \u00a0la familia Bundy , que se r\u00eden de su correcci\u00f3n y rectitud.<\/p>\n<p>El reparto se mantuvo casi intocable durante las once temporadas de la serie, con la \u00fanica excepci\u00f3n del marido de Marcy, Steve que la dejo para irse de guardia forestal a Yosemite, siendo sustituido en el coraz\u00f3n de \u00e9sta por un timador de poca monta pero muy atractivo, llamado Jefferson, que hace grandes migas con Al, para convertirse en su nuevo compadre. Para ver la evoluci\u00f3n de la serie pueden ver los t\u00edtulos de cr\u00e9dito de la und\u00e9cima y \u00faltima temporada.<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/ilyNITncXOE\" frameborder=\"0\" width=\"640\" height=\"480\"><\/iframe><br \/>\nLos episodios eran muy parecidos, con Al intentando hacer alguna cosa en contra del criterio de su mujer, que siempre le sale mal, complementado con el en\u00e9simo intento fallido de ligar \u00a0por parte de su hijo y la nueva conquista de su hija, todo ello aderezado por las constantes puyas de la madre, en un festival de risas continuo.<\/p>\n<p>La serie era muy divertida, gracias a los grandes actores que ten\u00eda y por tratar situaciones absurdas, poco convencionales y lejos de la correcci\u00f3n habitual de las comedias familiares, donde se sentaban a la mesa y arreglaban cualquier cosa en los veintid\u00f3s minutos de un episodio y terminaban en un abrazo. El problema era que debido a la zafiedad de la misma, las estrellas invitadas nunca eran de renombre, y contrataban a muchas chicas playboy para lucieran el palmito escasamente vestidas para contentar al personal.<\/p>\n<p>Los Bundy eran totalmente diferentes, una tropa de ego\u00edstas, mirando por su propio bien y que siguen juntos no tanto por amor, sino por comodidad y conveniencia y lo que mas les une es hacer trastadas y bromas al resto de los mortales, que es cuando son capaces de actuar como un equipo, para volver a pelearse entre ellos, en cuanto consiguen el objetivo.<\/p>\n<p>La repetitividad de la serie era un problema y yo la deje de ver hacia la sexta temporada, cuando ya dejo de sorprenderme semanalmente, aunque de vez en cuando sol\u00eda echarle un vistazo y en peque\u00f1as dosis sigue siendo recomendable, pero los 295 episodios seguidos va a ser que no. El buen rollo y la qu\u00edmica entre los actores fueron la base de la serie y como ejemplo, pueden ver este video en ingles de la celebraci\u00f3n de los 25 a\u00f1os de la serie con una reuni\u00f3n de todos los actores de la familia Bundy en 2012<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/93szqRrlhO0\" frameborder=\"0\" width=\"640\" height=\"360\"><\/iframe><\/p>\n<p><strong>Los actores:<\/strong> Ed O\u2019Neill es el patriarca de la familia Al Bundy. O\u2019Neill fue un buen jugador de f\u00fatbol americano en su juventud, llegando a probar para jugar en la NFL con los Pittsburgh Steelers, al no conseguirlo decidi\u00f3 dedicarse a la actuaci\u00f3n haciendo muchos papeles sin relieve hasta conseguir su primer papel principal en esta serie.<\/p>\n<p><a href=\"\/series-gourmets\/wp-content\/uploads\/sites\/37\/2013\/10\/ed-oneill-e1380967824753.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1657\" title=\"ed o'neill\" src=\"\/series-gourmets\/wp-content\/uploads\/sites\/37\/2013\/10\/ed-oneill-e1380967824753.jpg\" alt=\"\" width=\"480\" height=\"640\" srcset=\"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2013\/10\/ed-oneill-e1380967824753.jpg 480w, https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2013\/10\/ed-oneill-e1380967824753-225x300.jpg 225w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/a><\/p>\n<p>O\u00b4Neill est\u00e1 fantastico, como un pobre diablo que se entera de la misa de la mitad y condenado a vivir en su purgatorio familiar, aunque haci\u00e9ndonos re\u00edr a cada momento, en especial en las conversaciones con su mujer, que giran en torno a su capacidad sexual. Su postura preferida de sentarse en el sof\u00e1 con la mano en la bragueta \u00a0se convirti\u00f3 en marca de la casa.<\/p>\n<p>O\u2019Neill ya no se ha bajado del carro de la fama y en la actualidad nos sigue encantando en esa maravilla de comedia que es Modern Family, de la que les hablaremos alg\u00fan d\u00eda.<\/p>\n<p>Katey Sagal encarnaba perfectamente a Peggy su mujer, un prototipo perfecto de una choni madura de la periferia de una gran ciudad, una hambrienta sexual y con el mismo vestuario que llevaba en los sesenta, como ama de casa era una perfecta nulidad y se enorgullec\u00eda de ello.<\/p>\n<p><a href=\"\/series-gourmets\/wp-content\/uploads\/sites\/37\/2013\/10\/katey-sagal.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1658\" title=\"katey sagal\" src=\"\/series-gourmets\/wp-content\/uploads\/sites\/37\/2013\/10\/katey-sagal.jpg\" alt=\"\" width=\"600\" height=\"411\" srcset=\"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2013\/10\/katey-sagal.jpg 600w, https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2013\/10\/katey-sagal-300x206.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a>Sagal es una de las actrices mas polifac\u00e9ticas que conozco, empez\u00f3 su carrera como cantante haciendo coros para Bob Dylan, Olivia Newton-John o Bette Middler, grabando discos hasta la actualidad y como muestra aqu\u00ed tienen este video de su canci\u00f3n \u2018Cant\u00b4t hurry the harvest\u2019.<\/p>\n<p><a href=\"http:\/\/www.youtube.com\/watch?v=R9gmyFmbkeU\" rel=\"external nofollow\">http:\/\/www.youtube.com\/watch?v=R9gmyFmbkeU<\/a><\/p>\n<p>Su carrera posterior ha sido enlazar un buen trabajo tras otro, como hacer la voz de Leila en la serie Futurama, el papel principal en la comedia \u20188 reglas para salir con mi hija\u2019 y su trabajo actual en un completo cambio de registro, como Gemma Teller la matriarca de un club de motoristas en la brillante \u2018Hijos de la Anarqu\u00eda\u2019, demostrando lo gran actriz que es.<\/p>\n<p>El papel de Kelly, la hija mayor rubia despampanante pero tonta del bote fue para Christina Applegate, que con quince a\u00f1os consigui\u00f3 su primer papel como una promiscua adolescente.<\/p>\n<p><a href=\"\/series-gourmets\/wp-content\/uploads\/sites\/37\/2013\/10\/david-faustino-e1380967935280.jpg\"><br \/>\n<\/a><a href=\"\/series-gourmets\/wp-content\/uploads\/sites\/37\/2013\/10\/christina-applegate.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1659\" title=\"christina applegate\" src=\"\/series-gourmets\/wp-content\/uploads\/sites\/37\/2013\/10\/christina-applegate.jpg\" alt=\"\" width=\"475\" height=\"324\" srcset=\"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2013\/10\/christina-applegate.jpg 475w, https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2013\/10\/christina-applegate-300x205.jpg 300w\" sizes=\"auto, (max-width: 475px) 100vw, 475px\" \/><\/a>Applegate se convirti\u00f3 en un verdadero icono sexual para muchos adolescentes de la \u00e9poca, por sus atuendos sexys y provocadores. Applegate ha protagonizado diversas comedias de relativo \u00e9xito, y continua siendo una persona famosa en Hollywood.<\/p>\n<p>David Faustino era Bud, el hijo peque\u00f1o y un verdadero salido sexual en especial con las amigas de su hermana a las que persigue a todas horas. Faustino es un caso paradigm\u00e1tico de ni\u00f1os actores que evolucionan fatal.<\/p>\n<p><a href=\"\/series-gourmets\/wp-content\/uploads\/sites\/37\/2013\/10\/david-faustino-e1380967935280.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1660\" title=\"david-faustino\" src=\"\/series-gourmets\/wp-content\/uploads\/sites\/37\/2013\/10\/david-faustino-e1380967935280.jpg\" alt=\"\" width=\"435\" height=\"580\" srcset=\"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2013\/10\/david-faustino-e1380967935280.jpg 435w, https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2013\/10\/david-faustino-e1380967935280-225x300.jpg 225w\" sizes=\"auto, (max-width: 435px) 100vw, 435px\" \/><\/a>Se ha dedicado a vivir del cuento de su fama de la serie saliendo en realities de famosos y con frecuentes problemas con la ley y las drogas.<\/p>\n<p>Los vecinos de al lado, los Rhoades fueron interpretados por David Garrison y Amanda Bearse, que eran el blanco de todas las bromas de la familia Bundy por su correcci\u00f3n pol\u00edtica y conservadurismo. Garrison ha sido principalmente un actor de musicales de Broadway y por esta raz\u00f3n pidi\u00f3 salir de la serie en su tercera temporada, para volver a hacer teatro, aunque luego volvi\u00f3 de forma espor\u00e1dica.<\/p>\n<p><a href=\"\/series-gourmets\/wp-content\/uploads\/sites\/37\/2013\/10\/amanda-bearse-david-garrison-e1380968007660.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1661\" title=\"amanda bearse david garrison\" src=\"\/series-gourmets\/wp-content\/uploads\/sites\/37\/2013\/10\/amanda-bearse-david-garrison-e1380968007660.jpg\" alt=\"\" width=\"417\" height=\"640\" srcset=\"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2013\/10\/amanda-bearse-david-garrison-e1380968007660.jpg 417w, https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2013\/10\/amanda-bearse-david-garrison-e1380968007660-195x300.jpg 195w\" sizes=\"auto, (max-width: 417px) 100vw, 417px\" \/><\/a>Amanda Bearse era la mujer normal y corriente ridiculizada constantemente por sus vecinos siendo el personaje m\u00e1s emblem\u00e1tico de la irreverencia de la serie, ya que mientras en cualquier otra seria el centro de la acci\u00f3n, aqu\u00ed era el blanco de todos. Bearse estaba magnifica, pero luego ha dirigido sus pasos hacia la direcci\u00f3n, siendo una reputada directora de sitcoms en la actualidad<\/p>\n<p>Cuando Garrison se fue de la serie, fue reemplazado por el guaperas de Ted McGinley, como Jefferson d\u2019Arcy, al que recordamos sobre todo por ser el fot\u00f3grafo de las ultimas temporadas de Vacaciones en el Mar. McGinley es perfecto para este tipo de papeles de guaperas picaron y mujeriego y su asociaci\u00f3n con Al Bundy le dio algo de vida a las ultimas temporadas de la serie<\/p>\n<p><a href=\"\/series-gourmets\/wp-content\/uploads\/sites\/37\/2013\/10\/Ted-mcGInley.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1662\" title=\"Ted mcGInley\" src=\"\/series-gourmets\/wp-content\/uploads\/sites\/37\/2013\/10\/Ted-mcGInley.jpg\" alt=\"\" width=\"400\" height=\"600\" srcset=\"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2013\/10\/Ted-mcGInley.jpg 400w, https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2013\/10\/Ted-mcGInley-200x300.jpg 200w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a>Curiosamente McGinley hasta esta serie era un \u00a0especialista en el descabello de series moribundas, ya que cuando entraba en una serie famosa est\u00e1 era cancelada en como mucho dos temporadas, como le pas\u00f3 en Happy Days, Dinast\u00eda o la propia Vacaciones en el Mar, desde esta serie, solo le hemos podido ver como estrella invitada en multitud de series.<\/p>\n<p><strong>El Final:<\/strong>La serie empez\u00f3 a declinar a partir de la octava temporada, parte por el cansancio art\u00edstico, como por la escasa evoluci\u00f3n de los personajes que repet\u00edan los mismos tics una y otra vez, pero la cadena Fox se resist\u00eda a finiquitarla debido a que fue su primera serie y le ten\u00edan un cari\u00f1o especial.<\/p>\n<p>El final fue un capitulo como otro cualquiera, ya que la cadena esperaba seguir otro a\u00f1o, pero como el precio a pagar a la productora \u00a0por cada episodio fue considerado excesivo, se convirti\u00f3 en el golpe de gracia que hizo que el ultimo capitulo normal \u00a0de la und\u00e9cima temporada fuera el ultimo de la serie. No hubo ninguna despedida, aunque en este tipo de series tampoco es que hiciera mucha falta, pero suele ser una oportunidad para dar algo especial a sus fieles seguidores en lugar de una despedida a la francesa como fue en este caso.<\/p>\n<p><strong>Epilogo:<\/strong>La serie creo que ostenta el record mundial de adaptaciones, con doce pa\u00edses que han hecho una versi\u00f3n, Ademas FOX hizo una secuela a partir de un personaje secundario y la llam\u00f3 \u2018Top of the Heap\u2019, \u00a0que era una p\u00e9sima comedia, pero en la que pueden ver a un jovenc\u00edsimo Matt LeBlanc en su \u00e9poca preFriends, con una pinta autentica de macarrilla, como pueden ver en el video.<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/mUErwyPRdoo\" frameborder=\"0\" width=\"640\" height=\"480\"><\/iframe><br \/>\nEn cuanto a sus adaptaciones las hay de todo tipo, aqu\u00ed pueden ver la curiosa cabecera de la chilena \u2018Casados con hijos\u2019<br \/>\n<iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/m5tx11focCY\" frameborder=\"0\" width=\"640\" height=\"480\"><\/iframe><br \/>\nPor supuesto nuestras cadenas no se pod\u00edan sustraer a esa moda \u00a0y en este sentido las series de Jos\u00e9 Lu\u00eds Moreno \u2018Escenas de Matrimonio\u2019 y posteriores son una clara herencia de esos di\u00e1logos sexuales de los Bundy, aunque pasados por el tamiz castizo. Pero de forma m\u00e1s directa la cadena Cuatro hizo una adaptaci\u00f3n de la serie llamada Matrimonio con Hijos, que dur\u00f3 apenas una temporada, aqu\u00ed pueden ver un ejemplo del engendro<br \/>\n<iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/CkDvboVEASY\" frameborder=\"0\" width=\"640\" height=\"480\"><\/iframe><br \/>\nHoy hemos recordado una serie que ha conseguido un lugar prominente en la historia televisiva, tanto por ayudar a la consolidaci\u00f3n de la cadena en la que se emit\u00eda como por abrir un poco mas los limites de la incorrecci\u00f3n pol\u00edtica en las comedias televisivas, por las que luego han entrado muchas propuestas actuales, por lo que \u00a0esperamos que hayan pasado un buen rato record\u00e1ndola.<\/p>\n<p>Esperamos sus opiniones y comentarios, aqu\u00ed o en nuestra cuenta de twitter (@jefoce) y (@lmejino). Hasta la pr\u00f3xima<\/p>\n<p>Mikel Madinabeitia\/ Lorenzo Mejino<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Matrimonio con hijos, fue una serie rompedora que ha pasado a la historia televisiva por diferentes razones, la primera de ellas es que fue la primera serie que emiti\u00f3 en 1987 un nuevo canal la cadena FOX, en un intento por romper el oligopolio de las tres cadenas hist\u00f3ricas americanas. Matrimonio con hijos fue la [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":61,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25,27,31,20],"tags":[513,672,811,1485,1828],"class_list":["post-1654","post","type-post","status-publish","format-standard","hentry","category-comedia","category-grandes-exitos","category-placeres-inconfesables","category-vicios-de-juventud","tag-christina-applegate","tag-david-faustino","tag-ed-oneill","tag-katey-sagal","tag-matrimonio-con-hijos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Matrimonio con hijos. La familia mas impresentable de la television - Series para gourmets<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2013\/10\/11\/matrimonio-con-hijos-la-familia-mas-impresentable-de-la-television\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Matrimonio con hijos. La familia mas impresentable de la television - Series para gourmets\" \/>\n<meta property=\"og:description\" content=\"Matrimonio con hijos, fue una serie rompedora que ha pasado a la historia televisiva por diferentes razones, la primera de ellas es que fue la primera serie que emiti\u00f3 en 1987 un nuevo canal la cadena FOX, en un intento por romper el oligopolio de las tres cadenas hist\u00f3ricas americanas. Matrimonio con hijos fue la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2013\/10\/11\/matrimonio-con-hijos-la-familia-mas-impresentable-de-la-television\/\" \/>\n<meta property=\"og:site_name\" content=\"Series para gourmets\" \/>\n<meta property=\"article:published_time\" content=\"2013-10-11T07:05:16+00:00\" \/>\n<meta name=\"author\" content=\"Lorenzo Mejino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/lmejino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lorenzo Mejino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2013\/10\/11\/matrimonio-con-hijos-la-familia-mas-impresentable-de-la-television\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2013\/10\/11\/matrimonio-con-hijos-la-familia-mas-impresentable-de-la-television\/\"},\"author\":{\"name\":\"Lorenzo Mejino\",\"@id\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/#\/schema\/person\/da56769d3fbfc3b30239e2cd8e5a6d63\"},\"headline\":\"Matrimonio con hijos. La familia mas impresentable de la television\",\"datePublished\":\"2013-10-11T07:05:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2013\/10\/11\/matrimonio-con-hijos-la-familia-mas-impresentable-de-la-television\/\"},\"wordCount\":2714,\"commentCount\":4,\"keywords\":[\"Christina Applegate\",\"David Faustino\",\"Ed O'Neill\",\"Katey Sagal\",\"Matrimonio con hijos\"],\"articleSection\":[\"Comedia\",\"Grandes exitos\",\"Placeres inconfesables\",\"Vicios de juventud\"],\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2013\/10\/11\/matrimonio-con-hijos-la-familia-mas-impresentable-de-la-television\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2013\/10\/11\/matrimonio-con-hijos-la-familia-mas-impresentable-de-la-television\/\",\"url\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2013\/10\/11\/matrimonio-con-hijos-la-familia-mas-impresentable-de-la-television\/\",\"name\":\"Matrimonio con hijos. La familia mas impresentable de la television - Series para gourmets\",\"isPartOf\":{\"@id\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/#website\"},\"datePublished\":\"2013-10-11T07:05:16+00:00\",\"author\":{\"@id\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/#\/schema\/person\/da56769d3fbfc3b30239e2cd8e5a6d63\"},\"breadcrumb\":{\"@id\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2013\/10\/11\/matrimonio-con-hijos-la-familia-mas-impresentable-de-la-television\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2013\/10\/11\/matrimonio-con-hijos-la-familia-mas-impresentable-de-la-television\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2013\/10\/11\/matrimonio-con-hijos-la-familia-mas-impresentable-de-la-television\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Matrimonio con hijos. La familia mas impresentable de la television\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/#website\",\"url\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/\",\"name\":\"Series para gourmets\",\"description\":\"Propuestas para su men\u00fa televisivo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/#\/schema\/person\/da56769d3fbfc3b30239e2cd8e5a6d63\",\"name\":\"Lorenzo Mejino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/f1b8e233b7c252129e0ef7b19d8cc6ba9504a5eb94c6090f63c17430391df4ca?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f1b8e233b7c252129e0ef7b19d8cc6ba9504a5eb94c6090f63c17430391df4ca?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f1b8e233b7c252129e0ef7b19d8cc6ba9504a5eb94c6090f63c17430391df4ca?s=96&d=mm&r=g\",\"caption\":\"Lorenzo Mejino\"},\"description\":\"Series para gourmets nace con la pretensi\u00f3n de ayudar a personalizar su men\u00fa televisivo con el panorama mundial de series. Cada lunes hablaremos de series remotas ni estadounidenses ni brit\u00e1nicas, no estrenadas en nuestro pa\u00eds. Cada mi\u00e9rcoles de series actuales estrenadas aqu\u00ed y los viernes recordamos series del pasado de la televisi\u00f3n\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/lmejino\"],\"url\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/author\/bouvier\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Matrimonio con hijos. La familia mas impresentable de la television - Series para gourmets","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.diariovasco.com\/series-gourmets\/2013\/10\/11\/matrimonio-con-hijos-la-familia-mas-impresentable-de-la-television\/","og_locale":"es_ES","og_type":"article","og_title":"Matrimonio con hijos. La familia mas impresentable de la television - Series para gourmets","og_description":"Matrimonio con hijos, fue una serie rompedora que ha pasado a la historia televisiva por diferentes razones, la primera de ellas es que fue la primera serie que emiti\u00f3 en 1987 un nuevo canal la cadena FOX, en un intento por romper el oligopolio de las tres cadenas hist\u00f3ricas americanas. Matrimonio con hijos fue la [&hellip;]","og_url":"https:\/\/blogs.diariovasco.com\/series-gourmets\/2013\/10\/11\/matrimonio-con-hijos-la-familia-mas-impresentable-de-la-television\/","og_site_name":"Series para gourmets","article_published_time":"2013-10-11T07:05:16+00:00","author":"Lorenzo Mejino","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/lmejino","twitter_misc":{"Written by":"Lorenzo Mejino","Est. reading time":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.diariovasco.com\/series-gourmets\/2013\/10\/11\/matrimonio-con-hijos-la-familia-mas-impresentable-de-la-television\/#article","isPartOf":{"@id":"https:\/\/blogs.diariovasco.com\/series-gourmets\/2013\/10\/11\/matrimonio-con-hijos-la-familia-mas-impresentable-de-la-television\/"},"author":{"name":"Lorenzo Mejino","@id":"https:\/\/blogs.diariovasco.com\/series-gourmets\/#\/schema\/person\/da56769d3fbfc3b30239e2cd8e5a6d63"},"headline":"Matrimonio con hijos. La familia mas impresentable de la television","datePublished":"2013-10-11T07:05:16+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.diariovasco.com\/series-gourmets\/2013\/10\/11\/matrimonio-con-hijos-la-familia-mas-impresentable-de-la-television\/"},"wordCount":2714,"commentCount":4,"keywords":["Christina Applegate","David Faustino","Ed O'Neill","Katey Sagal","Matrimonio con hijos"],"articleSection":["Comedia","Grandes exitos","Placeres inconfesables","Vicios de juventud"],"inLanguage":"es-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogs.diariovasco.com\/series-gourmets\/2013\/10\/11\/matrimonio-con-hijos-la-familia-mas-impresentable-de-la-television\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogs.diariovasco.com\/series-gourmets\/2013\/10\/11\/matrimonio-con-hijos-la-familia-mas-impresentable-de-la-television\/","url":"https:\/\/blogs.diariovasco.com\/series-gourmets\/2013\/10\/11\/matrimonio-con-hijos-la-familia-mas-impresentable-de-la-television\/","name":"Matrimonio con hijos. La familia mas impresentable de la television - Series para gourmets","isPartOf":{"@id":"https:\/\/blogs.diariovasco.com\/series-gourmets\/#website"},"datePublished":"2013-10-11T07:05:16+00:00","author":{"@id":"https:\/\/blogs.diariovasco.com\/series-gourmets\/#\/schema\/person\/da56769d3fbfc3b30239e2cd8e5a6d63"},"breadcrumb":{"@id":"https:\/\/blogs.diariovasco.com\/series-gourmets\/2013\/10\/11\/matrimonio-con-hijos-la-familia-mas-impresentable-de-la-television\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.diariovasco.com\/series-gourmets\/2013\/10\/11\/matrimonio-con-hijos-la-familia-mas-impresentable-de-la-television\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.diariovasco.com\/series-gourmets\/2013\/10\/11\/matrimonio-con-hijos-la-familia-mas-impresentable-de-la-television\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blogs.diariovasco.com\/series-gourmets\/"},{"@type":"ListItem","position":2,"name":"Matrimonio con hijos. La familia mas impresentable de la television"}]},{"@type":"WebSite","@id":"https:\/\/blogs.diariovasco.com\/series-gourmets\/#website","url":"https:\/\/blogs.diariovasco.com\/series-gourmets\/","name":"Series para gourmets","description":"Propuestas para su men\u00fa televisivo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.diariovasco.com\/series-gourmets\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/blogs.diariovasco.com\/series-gourmets\/#\/schema\/person\/da56769d3fbfc3b30239e2cd8e5a6d63","name":"Lorenzo Mejino","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/f1b8e233b7c252129e0ef7b19d8cc6ba9504a5eb94c6090f63c17430391df4ca?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f1b8e233b7c252129e0ef7b19d8cc6ba9504a5eb94c6090f63c17430391df4ca?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f1b8e233b7c252129e0ef7b19d8cc6ba9504a5eb94c6090f63c17430391df4ca?s=96&d=mm&r=g","caption":"Lorenzo Mejino"},"description":"Series para gourmets nace con la pretensi\u00f3n de ayudar a personalizar su men\u00fa televisivo con el panorama mundial de series. Cada lunes hablaremos de series remotas ni estadounidenses ni brit\u00e1nicas, no estrenadas en nuestro pa\u00eds. Cada mi\u00e9rcoles de series actuales estrenadas aqu\u00ed y los viernes recordamos series del pasado de la televisi\u00f3n","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/lmejino"],"url":"https:\/\/blogs.diariovasco.com\/series-gourmets\/author\/bouvier\/"}]}},"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-json\/wp\/v2\/posts\/1654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-json\/wp\/v2\/comments?post=1654"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-json\/wp\/v2\/posts\/1654\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-json\/wp\/v2\/media?parent=1654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-json\/wp\/v2\/categories?post=1654"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-json\/wp\/v2\/tags?post=1654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}