{"id":16913,"date":"2022-10-03T06:00:34","date_gmt":"2022-10-03T05:00:34","guid":{"rendered":"https:\/\/blogs.diariovasco.com\/series-gourmets\/?p=16913"},"modified":"2022-10-02T08:24:50","modified_gmt":"2022-10-02T07:24:50","slug":"raised-by-refugees-nueva-zelanda-la-segunda-generacion-de-refugiados","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/series-gourmets\/2022\/10\/03\/raised-by-refugees-nueva-zelanda-la-segunda-generacion-de-refugiados\/","title":{"rendered":"Raised by Refugees (Nueva Zelanda):  la segunda generaci\u00f3n de refugiados"},"content":{"rendered":"<p>La infancia de las personalidades famosas est\u00e1 convirti\u00e9ndose en una fuente de inspiraci\u00f3n para series costumbristas como<a href=\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2016\/03\/11\/todo-el-mundo-odia-a-chris-cosas-de-hermanas-y-moesha-el-fin-del-apogeo-de-las-comedias-afroamericanas\/\"> \u2018Everybody Hates Chris\u2019<\/a> sobre Chris Rock , \u2018Young Rock\u2019 sobre Dwayne Johnson o<a href=\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2021\/04\/09\/recien-llegados-fresh-off-the-boat-las-familias-asiaticas-americanas-tambien-existen\/\"> \u2018Fresh off the Boat\u2019<\/a> con el chef taiwan\u00e9s Eddie Huang. SI trasladamos ese concepto a nuestras ant\u00edpodas tenemos a \u2018Raised by Refugees\u2019 sobre la infancia del popular c\u00f3mico neozeland\u00e9s Pax Assadi.<\/p>\n<p>No podemos comparar la popularidad de Pax Assadi ( reconozco que ni sab\u00eda qui\u00e9n era) con la de las otras tres megaestrellas, pero si que coinciden en mostrar la infancia de las minor\u00edas \u00e9tnicas en tiempos recientes en que la discriminaci\u00f3n racial de baja intensidad segu\u00eda presente, a\u00f1adi\u00e9ndole en este caso un toque<a href=\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2019\/09\/11\/ramy-las-brillantes-tribulaciones-de-un-musulman-en-nueva-jersey\/\"> \u2018Ramy\u2019<\/a> al ser hijo de refugiados musulmanes afincados en Nueva Zelanda, de forma contempor\u00e1nea a los atentados del 11-S.<\/p>\n<p>\u2018Raised by refugees\u2019 juega de forma amable y costumbrista a mostrar lo que supone ser criado por refugiados, (traducci\u00f3n literal en espa\u00f1ol de su t\u00edtulo) con esas tres generaciones que conviven bajo el mismo techo en la aparentemente acogedora sociedad neozelandesa, con conflictos y malentendidos de baja intensidad, pero interesantes para conocer la vida de nuestras ant\u00edpodas.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-16917\" src=\"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2022\/09\/general-1.jpg\" alt=\"\" width=\"972\" height=\"534\" srcset=\"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2022\/09\/general-1.jpg 972w, https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2022\/09\/general-1-300x165.jpg 300w, https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2022\/09\/general-1-768x422.jpg 768w, https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2022\/09\/general-1-628x345.jpg 628w\" sizes=\"auto, (max-width: 972px) 100vw, 972px\" \/><\/p>\n<p><strong>Ficha:<\/strong> Raised by Refugees (Nueva Zelanda) 6 ep 25 m feb 2022- . <strong>Idioma:<\/strong> ingl\u00e9s <strong>Cadena:<\/strong> Prime (NZ) \/In\u00e9dita ( E)<\/p>\n<p><strong>La trama:<\/strong> Pax Assadi es un joven de doce a\u00f1os que vive con su familia en un suburbio de Auckland a principios de este milenio. Sus padre Afnan es de origen iran\u00ed y su madre de origen pakistan\u00ed, ambos llegaron como refugiados a Nueva Zelanda en los a\u00f1os ochenta donde se conocieron y formaron una familia formada por el primog\u00e9nito Pax, su hermano menor Mahan, a los que se ha unido su abuelo paterno Masood.<\/p>\n<p>Pax es un chaval que se ha integrado a la perfecci\u00f3n en la sociedad neozelandesa, tanto a nivel de costumbres como de vestimenta, lo que desespera bastante a sus padres que no quieren que abandone sus ra\u00edces musulmanas al occidentalizarse en exceso.<\/p>\n<p>Tampoco ayuda el hecho de no ser un estudiante brillante de grandes notas como ans\u00edan sus padres. Sus progenitores solo aspiran que tenga\u00a0 una mejor vida que el patriarca Afnan que debe compaginar su trabajo en un almac\u00e9n de suministros con hacer horas como taxista pirata para poder llegar a final de mes, como muestra el tr\u00e1iler de la serie.<br \/>\n<iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/4Oy53LGsroo\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><br \/>\nEste tipo de series de infancias de personalidades famosas se centran principalmente en la vida del chaval y su grupo de amigos con los que comparte mucho m\u00e1s tiempo que con su familia y que en el caso de Pax, no deja de ser un grupo especial donde se juntan raritos marginales con hijos de inmigrantes, que mantienen continuos enfrentamientos con las bandas de populares blancos neozelandeses.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-16918\" src=\"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2022\/09\/grupo-amigos.jpg\" alt=\"\" width=\"920\" height=\"517\" srcset=\"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2022\/09\/grupo-amigos.jpg 920w, https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2022\/09\/grupo-amigos-300x169.jpg 300w, https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2022\/09\/grupo-amigos-768x432.jpg 768w, https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2022\/09\/grupo-amigos-628x353.jpg 628w\" sizes=\"auto, (max-width: 920px) 100vw, 920px\" \/>Pax Assadi ( der) ha querido reflejar todos sus recuerdos y an\u00e9cdotas reales infantiles\u00a0 a modo de homenaje a su familia, reserv\u00e1ndose el honor de interpretar a su propio padre. Le cost\u00f3 mucho encontrar al actor infantil ideal para encarnar a su yo infantil, hasta que un d\u00eda por casualidad descubri\u00f3 a Kenus Binu ( izq) , mientras hac\u00eda el ganso con sus amigos en un cine y se vio absolutamente reflejado en el chaval.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-16914\" src=\"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2022\/09\/pareja.jpg\" alt=\"\" width=\"1280\" height=\"720\" srcset=\"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2022\/09\/pareja.jpg 1280w, https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2022\/09\/pareja-300x169.jpg 300w, https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2022\/09\/pareja-768x432.jpg 768w, https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2022\/09\/pareja-628x353.jpg 628w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/>Pax Assadi es una personalidad muy popular a nivel de c\u00f3mico y monologuista en su Nueva Zelanda natal y no ha dudado en cambiar completamente su aspecto habitual para convertirse en su padre Afnan como pueden comparar en las dos fotos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-16915\" src=\"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2022\/09\/pax-assadi.jpg\" alt=\"\" width=\"710\" height=\"399\" srcset=\"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2022\/09\/pax-assadi.jpg 710w, https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2022\/09\/pax-assadi-300x169.jpg 300w, https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2022\/09\/pax-assadi-628x353.jpg 628w\" sizes=\"auto, (max-width: 710px) 100vw, 710px\" \/><\/p>\n<p>A pesar del tono amable y distendido que predomina, Assadi no duda en lanzar algunas cargas de profundidad en especial en temas de discriminaci\u00f3n tanto en el \u00e1mbito escolar como en el social, incluyendo alg\u00fan personaje hilarante como su maestra que es la t\u00edpica enrollada que intenta ser m\u00e1s \u00e9tnicamente correcta que sus propios alumnos.<\/p>\n<p>Sin ser ninguna obra maestra, \u2018Raised by Refugees\u2019 me ha parecido una historia muy interesante para conocer la historia de esos colectivos de refugiados e inmigrantes al otro lado del mundo, por lo que esperando que alguna de las plataformas habituales apueste por ella, les dejo con otro corte de \u2018Raised by Refugees\u2019 donde se centra en las din\u00e1micas familiares de los Assadi, precisamente durante los d\u00edas posteriores al 11-S<br \/>\n<iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/KEmFOjDUftA\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Esperamos sus opiniones y comentarios, aqu\u00ed o en nuestra cuenta de twitter (@lmejino). Hasta la pr\u00f3xima<\/p>\n<p>Lorenzo Mejino<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La infancia de las personalidades famosas est\u00e1 convirti\u00e9ndose en una fuente de inspiraci\u00f3n para series costumbristas como \u2018Everybody Hates Chris\u2019 sobre Chris Rock , \u2018Young Rock\u2019 sobre Dwayne Johnson o \u2018Fresh off the Boat\u2019 con el chef taiwan\u00e9s Eddie Huang. SI trasladamos ese concepto a nuestras ant\u00edpodas tenemos a \u2018Raised by Refugees\u2019 sobre la infancia [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":61,"featured_media":16916,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25,6,9,17],"tags":[7684,7683,7682],"class_list":["post-16913","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comedia","category-eventos","category-juveniles","category-series-remotas","tag-kenus-binu","tag-pax-assadi","tag-raised-by-refugees"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Raised by Refugees (Nueva Zelanda): la segunda generaci\u00f3n de refugiados - Series para gourmets<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2022\/10\/03\/raised-by-refugees-nueva-zelanda-la-segunda-generacion-de-refugiados\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Raised by Refugees (Nueva Zelanda): la segunda generaci\u00f3n de refugiados - Series para gourmets\" \/>\n<meta property=\"og:description\" content=\"La infancia de las personalidades famosas est\u00e1 convirti\u00e9ndose en una fuente de inspiraci\u00f3n para series costumbristas como \u2018Everybody Hates Chris\u2019 sobre Chris Rock , \u2018Young Rock\u2019 sobre Dwayne Johnson o \u2018Fresh off the Boat\u2019 con el chef taiwan\u00e9s Eddie Huang. SI trasladamos ese concepto a nuestras ant\u00edpodas tenemos a \u2018Raised by Refugees\u2019 sobre la infancia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2022\/10\/03\/raised-by-refugees-nueva-zelanda-la-segunda-generacion-de-refugiados\/\" \/>\n<meta property=\"og:site_name\" content=\"Series para gourmets\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-03T05:00:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2022\/09\/destacada-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lorenzo Mejino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/lmejino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lorenzo Mejino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2022\/10\/03\/raised-by-refugees-nueva-zelanda-la-segunda-generacion-de-refugiados\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2022\/10\/03\/raised-by-refugees-nueva-zelanda-la-segunda-generacion-de-refugiados\/\"},\"author\":{\"name\":\"Lorenzo Mejino\",\"@id\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/#\/schema\/person\/da56769d3fbfc3b30239e2cd8e5a6d63\"},\"headline\":\"Raised by Refugees (Nueva Zelanda): la segunda generaci\u00f3n de refugiados\",\"datePublished\":\"2022-10-03T05:00:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2022\/10\/03\/raised-by-refugees-nueva-zelanda-la-segunda-generacion-de-refugiados\/\"},\"wordCount\":757,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2022\/10\/03\/raised-by-refugees-nueva-zelanda-la-segunda-generacion-de-refugiados\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2022\/09\/destacada-2.jpg\",\"keywords\":[\"Kenus Binu\",\"Pax Assadi\",\"Raised by refugees\"],\"articleSection\":[\"Comedia\",\"Eventos\",\"Juveniles\",\"Series remotas\"],\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2022\/10\/03\/raised-by-refugees-nueva-zelanda-la-segunda-generacion-de-refugiados\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2022\/10\/03\/raised-by-refugees-nueva-zelanda-la-segunda-generacion-de-refugiados\/\",\"url\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2022\/10\/03\/raised-by-refugees-nueva-zelanda-la-segunda-generacion-de-refugiados\/\",\"name\":\"Raised by Refugees (Nueva Zelanda): la segunda generaci\u00f3n de refugiados - Series para gourmets\",\"isPartOf\":{\"@id\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2022\/10\/03\/raised-by-refugees-nueva-zelanda-la-segunda-generacion-de-refugiados\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2022\/10\/03\/raised-by-refugees-nueva-zelanda-la-segunda-generacion-de-refugiados\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2022\/09\/destacada-2.jpg\",\"datePublished\":\"2022-10-03T05:00:34+00:00\",\"author\":{\"@id\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/#\/schema\/person\/da56769d3fbfc3b30239e2cd8e5a6d63\"},\"breadcrumb\":{\"@id\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2022\/10\/03\/raised-by-refugees-nueva-zelanda-la-segunda-generacion-de-refugiados\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2022\/10\/03\/raised-by-refugees-nueva-zelanda-la-segunda-generacion-de-refugiados\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2022\/10\/03\/raised-by-refugees-nueva-zelanda-la-segunda-generacion-de-refugiados\/#primaryimage\",\"url\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2022\/09\/destacada-2.jpg\",\"contentUrl\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2022\/09\/destacada-2.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"?????????????????????????????????????????????????????\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2022\/10\/03\/raised-by-refugees-nueva-zelanda-la-segunda-generacion-de-refugiados\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Raised by Refugees (Nueva Zelanda): la segunda generaci\u00f3n de refugiados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/#website\",\"url\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/\",\"name\":\"Series para gourmets\",\"description\":\"Propuestas para su men\u00fa televisivo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/#\/schema\/person\/da56769d3fbfc3b30239e2cd8e5a6d63\",\"name\":\"Lorenzo Mejino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/f1b8e233b7c252129e0ef7b19d8cc6ba9504a5eb94c6090f63c17430391df4ca?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f1b8e233b7c252129e0ef7b19d8cc6ba9504a5eb94c6090f63c17430391df4ca?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f1b8e233b7c252129e0ef7b19d8cc6ba9504a5eb94c6090f63c17430391df4ca?s=96&d=mm&r=g\",\"caption\":\"Lorenzo Mejino\"},\"description\":\"Series para gourmets nace con la pretensi\u00f3n de ayudar a personalizar su men\u00fa televisivo con el panorama mundial de series. Cada lunes hablaremos de series remotas ni estadounidenses ni brit\u00e1nicas, no estrenadas en nuestro pa\u00eds. Cada mi\u00e9rcoles de series actuales estrenadas aqu\u00ed y los viernes recordamos series del pasado de la televisi\u00f3n\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/lmejino\"],\"url\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/author\/bouvier\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Raised by Refugees (Nueva Zelanda): la segunda generaci\u00f3n de refugiados - Series para gourmets","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.diariovasco.com\/series-gourmets\/2022\/10\/03\/raised-by-refugees-nueva-zelanda-la-segunda-generacion-de-refugiados\/","og_locale":"es_ES","og_type":"article","og_title":"Raised by Refugees (Nueva Zelanda): la segunda generaci\u00f3n de refugiados - Series para gourmets","og_description":"La infancia de las personalidades famosas est\u00e1 convirti\u00e9ndose en una fuente de inspiraci\u00f3n para series costumbristas como \u2018Everybody Hates Chris\u2019 sobre Chris Rock , \u2018Young Rock\u2019 sobre Dwayne Johnson o \u2018Fresh off the Boat\u2019 con el chef taiwan\u00e9s Eddie Huang. SI trasladamos ese concepto a nuestras ant\u00edpodas tenemos a \u2018Raised by Refugees\u2019 sobre la infancia [&hellip;]","og_url":"https:\/\/blogs.diariovasco.com\/series-gourmets\/2022\/10\/03\/raised-by-refugees-nueva-zelanda-la-segunda-generacion-de-refugiados\/","og_site_name":"Series para gourmets","article_published_time":"2022-10-03T05:00:34+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2022\/09\/destacada-2.jpg","type":"image\/jpeg"}],"author":"Lorenzo Mejino","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/lmejino","twitter_misc":{"Written by":"Lorenzo Mejino","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.diariovasco.com\/series-gourmets\/2022\/10\/03\/raised-by-refugees-nueva-zelanda-la-segunda-generacion-de-refugiados\/#article","isPartOf":{"@id":"https:\/\/blogs.diariovasco.com\/series-gourmets\/2022\/10\/03\/raised-by-refugees-nueva-zelanda-la-segunda-generacion-de-refugiados\/"},"author":{"name":"Lorenzo Mejino","@id":"https:\/\/blogs.diariovasco.com\/series-gourmets\/#\/schema\/person\/da56769d3fbfc3b30239e2cd8e5a6d63"},"headline":"Raised by Refugees (Nueva Zelanda): la segunda generaci\u00f3n de refugiados","datePublished":"2022-10-03T05:00:34+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.diariovasco.com\/series-gourmets\/2022\/10\/03\/raised-by-refugees-nueva-zelanda-la-segunda-generacion-de-refugiados\/"},"wordCount":757,"commentCount":0,"image":{"@id":"https:\/\/blogs.diariovasco.com\/series-gourmets\/2022\/10\/03\/raised-by-refugees-nueva-zelanda-la-segunda-generacion-de-refugiados\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2022\/09\/destacada-2.jpg","keywords":["Kenus Binu","Pax Assadi","Raised by refugees"],"articleSection":["Comedia","Eventos","Juveniles","Series remotas"],"inLanguage":"es-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogs.diariovasco.com\/series-gourmets\/2022\/10\/03\/raised-by-refugees-nueva-zelanda-la-segunda-generacion-de-refugiados\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogs.diariovasco.com\/series-gourmets\/2022\/10\/03\/raised-by-refugees-nueva-zelanda-la-segunda-generacion-de-refugiados\/","url":"https:\/\/blogs.diariovasco.com\/series-gourmets\/2022\/10\/03\/raised-by-refugees-nueva-zelanda-la-segunda-generacion-de-refugiados\/","name":"Raised by Refugees (Nueva Zelanda): la segunda generaci\u00f3n de refugiados - Series para gourmets","isPartOf":{"@id":"https:\/\/blogs.diariovasco.com\/series-gourmets\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.diariovasco.com\/series-gourmets\/2022\/10\/03\/raised-by-refugees-nueva-zelanda-la-segunda-generacion-de-refugiados\/#primaryimage"},"image":{"@id":"https:\/\/blogs.diariovasco.com\/series-gourmets\/2022\/10\/03\/raised-by-refugees-nueva-zelanda-la-segunda-generacion-de-refugiados\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2022\/09\/destacada-2.jpg","datePublished":"2022-10-03T05:00:34+00:00","author":{"@id":"https:\/\/blogs.diariovasco.com\/series-gourmets\/#\/schema\/person\/da56769d3fbfc3b30239e2cd8e5a6d63"},"breadcrumb":{"@id":"https:\/\/blogs.diariovasco.com\/series-gourmets\/2022\/10\/03\/raised-by-refugees-nueva-zelanda-la-segunda-generacion-de-refugiados\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.diariovasco.com\/series-gourmets\/2022\/10\/03\/raised-by-refugees-nueva-zelanda-la-segunda-generacion-de-refugiados\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/blogs.diariovasco.com\/series-gourmets\/2022\/10\/03\/raised-by-refugees-nueva-zelanda-la-segunda-generacion-de-refugiados\/#primaryimage","url":"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2022\/09\/destacada-2.jpg","contentUrl":"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2022\/09\/destacada-2.jpg","width":1920,"height":1080,"caption":"?????????????????????????????????????????????????????"},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.diariovasco.com\/series-gourmets\/2022\/10\/03\/raised-by-refugees-nueva-zelanda-la-segunda-generacion-de-refugiados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blogs.diariovasco.com\/series-gourmets\/"},{"@type":"ListItem","position":2,"name":"Raised by Refugees (Nueva Zelanda): la segunda generaci\u00f3n de refugiados"}]},{"@type":"WebSite","@id":"https:\/\/blogs.diariovasco.com\/series-gourmets\/#website","url":"https:\/\/blogs.diariovasco.com\/series-gourmets\/","name":"Series para gourmets","description":"Propuestas para su men\u00fa televisivo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.diariovasco.com\/series-gourmets\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/blogs.diariovasco.com\/series-gourmets\/#\/schema\/person\/da56769d3fbfc3b30239e2cd8e5a6d63","name":"Lorenzo Mejino","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/f1b8e233b7c252129e0ef7b19d8cc6ba9504a5eb94c6090f63c17430391df4ca?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f1b8e233b7c252129e0ef7b19d8cc6ba9504a5eb94c6090f63c17430391df4ca?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f1b8e233b7c252129e0ef7b19d8cc6ba9504a5eb94c6090f63c17430391df4ca?s=96&d=mm&r=g","caption":"Lorenzo Mejino"},"description":"Series para gourmets nace con la pretensi\u00f3n de ayudar a personalizar su men\u00fa televisivo con el panorama mundial de series. Cada lunes hablaremos de series remotas ni estadounidenses ni brit\u00e1nicas, no estrenadas en nuestro pa\u00eds. Cada mi\u00e9rcoles de series actuales estrenadas aqu\u00ed y los viernes recordamos series del pasado de la televisi\u00f3n","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/lmejino"],"url":"https:\/\/blogs.diariovasco.com\/series-gourmets\/author\/bouvier\/"}]}},"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-json\/wp\/v2\/posts\/16913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-json\/wp\/v2\/comments?post=16913"}],"version-history":[{"count":4,"href":"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-json\/wp\/v2\/posts\/16913\/revisions"}],"predecessor-version":[{"id":17065,"href":"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-json\/wp\/v2\/posts\/16913\/revisions\/17065"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-json\/wp\/v2\/media\/16916"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-json\/wp\/v2\/media?parent=16913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-json\/wp\/v2\/categories?post=16913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-json\/wp\/v2\/tags?post=16913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}