{"id":21876,"date":"2024-07-26T06:00:06","date_gmt":"2024-07-26T05:00:06","guid":{"rendered":"https:\/\/blogs.diariovasco.com\/series-gourmets\/?p=21876"},"modified":"2024-07-25T10:59:17","modified_gmt":"2024-07-25T09:59:17","slug":"super-pumped-la-batalla-por-uber-el-gran-disruptor-del-transporte","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/series-gourmets\/2024\/07\/26\/super-pumped-la-batalla-por-uber-el-gran-disruptor-del-transporte\/","title":{"rendered":"Super Pumped: La batalla por Uber : el gran disruptor del transporte"},"content":{"rendered":"<p>La digitalizaci\u00f3n de nuestra sociedad ha tenido como consecuencia principal enormes cambios tecnol\u00f3gicos liderados por empresas innovadoras que han funcionado como disruptoras en mercados muy consolidados como es el caso del sector de transporte privado de pasajeros con la irrupci\u00f3n de Uber. Esa historia es el centro de \u2018Super Pumped\u2019 estrenada en nuestro pa\u00eds con el clarificador a\u00f1adido de \u2018La Batalla por Uber\u2019.<\/p>\n<p>El \u00e9xito global de Uber y la personalidad de su creador Travis Kalanick, hace que \u2018Super Pumped\u2019 sea un magn\u00edfico veh\u00edculo para conocer todas las etapas de crecimiento de una controvertida empresa tecnol\u00f3gica que para algunos es un unicornio y para otros un enemigo a aniquilar en una historia de lo m\u00e1s turbulenta.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-21880\" src=\"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2024\/07\/general-1.jpg\" alt=\"\" width=\"1280\" height=\"720\" srcset=\"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2024\/07\/general-1.jpg 1280w, https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2024\/07\/general-1-300x169.jpg 300w, https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2024\/07\/general-1-768x432.jpg 768w, https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2024\/07\/general-1-628x353.jpg 628w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><strong>Ficha:<\/strong> Super Pumped. La batalla por Uber 7 ep 60 min feb-abr 2022 <strong>Cadena:<\/strong> Showtime ( USA) \/ Movistar Series (E)\/ ahora no disponible<\/p>\n<p><strong>La trama;<\/strong><\/p>\n<p>Travis Kalanick es un joven y ambicioso emprendedor que tras diversas experiencias en algunas startups, recoge una idea de su gran amigo Garret Camp, para desarrollar UberCar una aplicaci\u00f3n para conectar la oferta de veh\u00edculos privados de transporte y la demanda de personas para trayectos puerta a puerta, con unas tarifas variables dependiendo del volumen y del momento del recorrido a contratar.<\/p>\n<p>Esa desregulaci\u00f3n salvaje y por libre de las tarifas y la descarada competencia con un sector tan poderoso y controlado como el taxi y las limusinas, centra los primeros episodios de &#8216;Super Pumped&#8217; para ver como nace la empresa y empieza a expandirse m\u00e1s all\u00e1 de su base inicial de San Francisco, con pol\u00edticas muy agresivas y con todo tipo de triqui\u00f1uelas para sortear las ordenanzas locales sobre transporte, como muestran en el tr\u00e1iler original de la serie.<\/p>\n<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/oC_IzAtJMPs?si=lEhcraZhSO5lThpf\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Esa agresividad expansiva y comercial ha tenido reflejo hasta en nuestro pa\u00eds, donde las virulentas protestas de los taxistas en las grandes ciudades espa\u00f1olas frente a lo que consideran una competencia desleal y furtiva por parte de Uber y otras compa\u00f1\u00edas similares, siguen llenando buena parte de los noticiarios.<\/p>\n<p>El centro absoluto de &#8216;Super Pumped&#8217; es la figura de Travis Kalanick ( un exaltado e hiperexcitado Joseph Gordon-Levitt) y la forma tan personalista que tiene de construir su imperio de veh\u00edculos y conductores que muestra en el siguiente video ilustrativo de su personalidad.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"Kalanick&amp;apos;s Truth (from Super Pumped)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/VEhJMeWt8-o?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>Los problemas empiezan cuando tiene que recurrir a financiaci\u00f3n externa para seguir su expansi\u00f3n y debe ceder parte de ese poder a un consejo de administraci\u00f3n formado por sus inversores donde destaca la figura de su \u00e1ngel de la guarda, Bill Gurley ( el siempre eficaz Kyle Chandler, izq) el socio principal de Benchmark una gran empresa de capital riesgo que crey\u00f3 en la idea de Uber desde sus inicios.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-21884\" src=\"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2024\/07\/chandler-thurman.jpg\" alt=\"\" width=\"800\" height=\"600\" srcset=\"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2024\/07\/chandler-thurman.jpg 800w, https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2024\/07\/chandler-thurman-300x225.jpg 300w, https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2024\/07\/chandler-thurman-768x576.jpg 768w, https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2024\/07\/chandler-thurman-628x471.jpg 628w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>Las diferencias de criterio entre Kalanick y Gurley los dos hombres fuertes del consejo sobre las estrategias de crecimiento y consolidaci\u00f3n de Uber, derivan en una batalla campal por el control de Uber, en el seno de un consejo de administraci\u00f3n en el que debe ejercer de \u00e1rbitro, la prestigiosa financiera Amanda Huffington, interpretada por la gran Uma Thurman ( der)<\/p>\n<p>A pesar de la potencia inicial de la idea a desarrollar, &#8216;Super Pumped&#8217; ha tenido un desarrollo bastante desconcertante al centrarse demasiado en las excentricidades de Travis Kalanick, al que presenta como un emprendedor visionario pero m\u00e1s en la l\u00ednea de un l\u00edder de una secta de culto a su personalidad que como un ejecutivo de una empresa multimillonaria.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-21879\" src=\"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2024\/07\/uber.jpg\" alt=\"\" width=\"980\" height=\"551\" srcset=\"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2024\/07\/uber.jpg 980w, https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2024\/07\/uber-300x169.jpg 300w, https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2024\/07\/uber-768x432.jpg 768w, https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2024\/07\/uber-628x353.jpg 628w\" sizes=\"auto, (max-width: 980px) 100vw, 980px\" \/>Tampoco ayuda que sus dos creadores Brian Koppelman ( der) y David Levien ( izq) que fueron los responsables de la brillante &#8216;<a href=\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2016\/11\/09\/billions-choque-de-trenes-de-alta-velocidad-en-wall-street\/\">Billions<\/a>&#8216;, no hayan acertado en esta ocasi\u00f3n en la puesta en escena.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-21882\" src=\"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2024\/07\/levien-koppelman.jpg\" alt=\"\" width=\"660\" height=\"438\" srcset=\"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2024\/07\/levien-koppelman.jpg 660w, https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2024\/07\/levien-koppelman-300x199.jpg 300w, https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2024\/07\/levien-koppelman-628x417.jpg 628w\" sizes=\"auto, (max-width: 660px) 100vw, 660px\" \/>No he entendido la necesidad de introducir con forceps escenas animadas o sin relaci\u00f3n alguna con el hilo empresarial, para reforzar ese aspecto descontrolado de su creador, pero que en mi caso me sacaba de la historia y le hac\u00eda perder mucha credibilidad al infantilizarla demasiado.<\/p>\n<p>El resultado final me ha decepcionado a nivel art\u00edstico, pero por lo menos me ha dado bastantes claves de una de las aventuras empresariales m\u00e1s impactantes de los \u00faltimos a\u00f1os, tanto a nivel de \u00e9xitos como de fracasos.<\/p>\n<p><strong>El protagonista :<\/strong><\/p>\n<p>Joseph Gordon-Levitt es un actor que empez\u00f3 a despuntar como actor infantil en comedias como &#8216;Cosas de Marcianos&#8217; para hacer una transici\u00f3n de lo m\u00e1s fluida hacia papeles m\u00e1s adultos hasta escribir y dirigir interesantes pel\u00edculas, mientras segu\u00eda actuando con grandes personajes como en &#8216;El juicio de los siete de Chicago&#8217; de Aaron Sorkin.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-21881\" src=\"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2024\/07\/joseph-gordon-levitt.jpg\" alt=\"\" width=\"1500\" height=\"843\" srcset=\"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2024\/07\/joseph-gordon-levitt.jpg 1500w, https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2024\/07\/joseph-gordon-levitt-300x169.jpg 300w, https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2024\/07\/joseph-gordon-levitt-768x432.jpg 768w, https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2024\/07\/joseph-gordon-levitt-628x353.jpg 628w\" sizes=\"auto, (max-width: 1500px) 100vw, 1500px\" \/><\/p>\n<p>En esta ocasi\u00f3n Gordon-Levitt est\u00e1 muy desenfocado como Travis Kalanick, con demasiados momentos sobreactuados que ridiculizaban a su personaje en lugar de hacerlo m\u00e1s asequible para poder entender una complicada personalidad llena de matices, que no se ven por ning\u00fan lado en la pantalla, al optar por el recurso f\u00e1cil de exabruptos de ira cuando las cosas no le sal\u00edan bien.<\/p>\n<p>Ese desmadre interpretativo hace que todo el conjunto se resienta, al estar presente en casi todas las escenas y campando completamente a sus anchas con todo tipo de desmanes.<\/p>\n<p><strong>Final y ep\u00edlogo :<\/strong><\/p>\n<p>&#8216;Super Pumped&#8217; es un interesante documento para conocer la gestaci\u00f3n de Uber, una de las multinacionales m\u00e1s importantes y controvertidas de transporte. En principio la intenci\u00f3n inicial era convertirla en una serie antol\u00f3gica apuntando en su 2T a nada menos que Facebook y Mark Zuckerberg, pero por ahora no tengo constancia que hayan conseguido sacarla adelante, supongo que por la brutal oposici\u00f3n legal del propio interesado<\/p>\n<p>En nuestro pa\u00eds se estren\u00f3 con bastante celeridad en Movistar Series, que la estren\u00f3 con la siguiente promoci\u00f3n.<br \/>\n<iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/EcncokJqsXg\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Desgraciadamente, \u2018 Super Pumpued\u2019 ya ha desaparecido del cat\u00e1logo de Movistar apenas dos a\u00f1os despu\u00e9s de su estreno, lo que no deja de ser una prueba evidente de la r\u00e1pida caducidad de muchas series en estos tiempos de consumo compulsivo, pero siempre les quedar\u00e1 la opci\u00f3n del DVD, aunque no descarto que finalmente aparezca como fondo de cat\u00e1logo por SkyShowtime al ser una serie original de Showtime USA<\/p>\n<p>Para cualquier comentario no duden en contactarme aqu\u00ed o a trav\u00e9s de mi cuenta de twitter (@lmejino). Hasta la pr\u00f3xima<\/p>\n<p>Lorenzo Mejino<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La digitalizaci\u00f3n de nuestra sociedad ha tenido como consecuencia principal enormes cambios tecnol\u00f3gicos liderados por empresas innovadoras que han funcionado como disruptoras en mercados muy consolidados como es el caso del sector de transporte privado de pasajeros con la irrupci\u00f3n de Uber. Esa historia es el centro de \u2018Super Pumped\u2019 estrenada en nuestro pa\u00eds con [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":61,"featured_media":21877,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9106,5,6203,32,16],"tags":[387,683,1421,1562,9572,9571,9573],"class_list":["post-21876","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-biograficas","category-drama","category-economicas","category-politica","category-series-del-pasado","tag-brian-koppelman","tag-david-levien","tag-joseph-gordon-lewitt","tag-kyle-chandler","tag-la-batalla-por-uber","tag-super-pumped","tag-uma-thurman"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Super Pumped: La batalla por Uber : el gran disruptor del transporte - Series para gourmets<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2024\/07\/26\/super-pumped-la-batalla-por-uber-el-gran-disruptor-del-transporte\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Super Pumped: La batalla por Uber : el gran disruptor del transporte - Series para gourmets\" \/>\n<meta property=\"og:description\" content=\"La digitalizaci\u00f3n de nuestra sociedad ha tenido como consecuencia principal enormes cambios tecnol\u00f3gicos liderados por empresas innovadoras que han funcionado como disruptoras en mercados muy consolidados como es el caso del sector de transporte privado de pasajeros con la irrupci\u00f3n de Uber. Esa historia es el centro de \u2018Super Pumped\u2019 estrenada en nuestro pa\u00eds con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2024\/07\/26\/super-pumped-la-batalla-por-uber-el-gran-disruptor-del-transporte\/\" \/>\n<meta property=\"og:site_name\" content=\"Series para gourmets\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-26T05:00:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2024\/07\/super-pumped-la-batalla-por-uber-995916.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"608\" \/>\n\t<meta property=\"og:image:height\" content=\"408\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lorenzo Mejino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/lmejino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lorenzo Mejino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2024\/07\/26\/super-pumped-la-batalla-por-uber-el-gran-disruptor-del-transporte\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2024\/07\/26\/super-pumped-la-batalla-por-uber-el-gran-disruptor-del-transporte\/\"},\"author\":{\"name\":\"Lorenzo Mejino\",\"@id\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/#\/schema\/person\/da56769d3fbfc3b30239e2cd8e5a6d63\"},\"headline\":\"Super Pumped: La batalla por Uber : el gran disruptor del transporte\",\"datePublished\":\"2024-07-26T05:00:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2024\/07\/26\/super-pumped-la-batalla-por-uber-el-gran-disruptor-del-transporte\/\"},\"wordCount\":1074,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2024\/07\/26\/super-pumped-la-batalla-por-uber-el-gran-disruptor-del-transporte\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2024\/07\/super-pumped-la-batalla-por-uber-995916.jpg\",\"keywords\":[\"Brian Koppelman\",\"David Levien\",\"Joseph Gordon-Lewitt\",\"Kyle Chandler\",\"La batalla por Uber\",\"Super Pumped\",\"Uma Thurman\"],\"articleSection\":[\"Biogr\u00e1ficas\",\"drama\",\"Econ\u00f3micas\",\"Politica\",\"series del pasado\"],\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2024\/07\/26\/super-pumped-la-batalla-por-uber-el-gran-disruptor-del-transporte\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2024\/07\/26\/super-pumped-la-batalla-por-uber-el-gran-disruptor-del-transporte\/\",\"url\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2024\/07\/26\/super-pumped-la-batalla-por-uber-el-gran-disruptor-del-transporte\/\",\"name\":\"Super Pumped: La batalla por Uber : el gran disruptor del transporte - Series para gourmets\",\"isPartOf\":{\"@id\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2024\/07\/26\/super-pumped-la-batalla-por-uber-el-gran-disruptor-del-transporte\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2024\/07\/26\/super-pumped-la-batalla-por-uber-el-gran-disruptor-del-transporte\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2024\/07\/super-pumped-la-batalla-por-uber-995916.jpg\",\"datePublished\":\"2024-07-26T05:00:06+00:00\",\"author\":{\"@id\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/#\/schema\/person\/da56769d3fbfc3b30239e2cd8e5a6d63\"},\"breadcrumb\":{\"@id\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2024\/07\/26\/super-pumped-la-batalla-por-uber-el-gran-disruptor-del-transporte\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2024\/07\/26\/super-pumped-la-batalla-por-uber-el-gran-disruptor-del-transporte\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2024\/07\/26\/super-pumped-la-batalla-por-uber-el-gran-disruptor-del-transporte\/#primaryimage\",\"url\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2024\/07\/super-pumped-la-batalla-por-uber-995916.jpg\",\"contentUrl\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2024\/07\/super-pumped-la-batalla-por-uber-995916.jpg\",\"width\":608,\"height\":408},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/2024\/07\/26\/super-pumped-la-batalla-por-uber-el-gran-disruptor-del-transporte\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Super Pumped: La batalla por Uber : el gran disruptor del transporte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/#website\",\"url\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/\",\"name\":\"Series para gourmets\",\"description\":\"Propuestas para su men\u00fa televisivo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/#\/schema\/person\/da56769d3fbfc3b30239e2cd8e5a6d63\",\"name\":\"Lorenzo Mejino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/f1b8e233b7c252129e0ef7b19d8cc6ba9504a5eb94c6090f63c17430391df4ca?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f1b8e233b7c252129e0ef7b19d8cc6ba9504a5eb94c6090f63c17430391df4ca?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f1b8e233b7c252129e0ef7b19d8cc6ba9504a5eb94c6090f63c17430391df4ca?s=96&d=mm&r=g\",\"caption\":\"Lorenzo Mejino\"},\"description\":\"Series para gourmets nace con la pretensi\u00f3n de ayudar a personalizar su men\u00fa televisivo con el panorama mundial de series. Cada lunes hablaremos de series remotas ni estadounidenses ni brit\u00e1nicas, no estrenadas en nuestro pa\u00eds. Cada mi\u00e9rcoles de series actuales estrenadas aqu\u00ed y los viernes recordamos series del pasado de la televisi\u00f3n\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/lmejino\"],\"url\":\"https:\/\/blogs.diariovasco.com\/series-gourmets\/author\/bouvier\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Super Pumped: La batalla por Uber : el gran disruptor del transporte - Series para gourmets","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.diariovasco.com\/series-gourmets\/2024\/07\/26\/super-pumped-la-batalla-por-uber-el-gran-disruptor-del-transporte\/","og_locale":"es_ES","og_type":"article","og_title":"Super Pumped: La batalla por Uber : el gran disruptor del transporte - Series para gourmets","og_description":"La digitalizaci\u00f3n de nuestra sociedad ha tenido como consecuencia principal enormes cambios tecnol\u00f3gicos liderados por empresas innovadoras que han funcionado como disruptoras en mercados muy consolidados como es el caso del sector de transporte privado de pasajeros con la irrupci\u00f3n de Uber. Esa historia es el centro de \u2018Super Pumped\u2019 estrenada en nuestro pa\u00eds con [&hellip;]","og_url":"https:\/\/blogs.diariovasco.com\/series-gourmets\/2024\/07\/26\/super-pumped-la-batalla-por-uber-el-gran-disruptor-del-transporte\/","og_site_name":"Series para gourmets","article_published_time":"2024-07-26T05:00:06+00:00","og_image":[{"width":608,"height":408,"url":"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2024\/07\/super-pumped-la-batalla-por-uber-995916.jpg","type":"image\/jpeg"}],"author":"Lorenzo Mejino","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/lmejino","twitter_misc":{"Written by":"Lorenzo Mejino","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.diariovasco.com\/series-gourmets\/2024\/07\/26\/super-pumped-la-batalla-por-uber-el-gran-disruptor-del-transporte\/#article","isPartOf":{"@id":"https:\/\/blogs.diariovasco.com\/series-gourmets\/2024\/07\/26\/super-pumped-la-batalla-por-uber-el-gran-disruptor-del-transporte\/"},"author":{"name":"Lorenzo Mejino","@id":"https:\/\/blogs.diariovasco.com\/series-gourmets\/#\/schema\/person\/da56769d3fbfc3b30239e2cd8e5a6d63"},"headline":"Super Pumped: La batalla por Uber : el gran disruptor del transporte","datePublished":"2024-07-26T05:00:06+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.diariovasco.com\/series-gourmets\/2024\/07\/26\/super-pumped-la-batalla-por-uber-el-gran-disruptor-del-transporte\/"},"wordCount":1074,"commentCount":0,"image":{"@id":"https:\/\/blogs.diariovasco.com\/series-gourmets\/2024\/07\/26\/super-pumped-la-batalla-por-uber-el-gran-disruptor-del-transporte\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2024\/07\/super-pumped-la-batalla-por-uber-995916.jpg","keywords":["Brian Koppelman","David Levien","Joseph Gordon-Lewitt","Kyle Chandler","La batalla por Uber","Super Pumped","Uma Thurman"],"articleSection":["Biogr\u00e1ficas","drama","Econ\u00f3micas","Politica","series del pasado"],"inLanguage":"es-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogs.diariovasco.com\/series-gourmets\/2024\/07\/26\/super-pumped-la-batalla-por-uber-el-gran-disruptor-del-transporte\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogs.diariovasco.com\/series-gourmets\/2024\/07\/26\/super-pumped-la-batalla-por-uber-el-gran-disruptor-del-transporte\/","url":"https:\/\/blogs.diariovasco.com\/series-gourmets\/2024\/07\/26\/super-pumped-la-batalla-por-uber-el-gran-disruptor-del-transporte\/","name":"Super Pumped: La batalla por Uber : el gran disruptor del transporte - Series para gourmets","isPartOf":{"@id":"https:\/\/blogs.diariovasco.com\/series-gourmets\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.diariovasco.com\/series-gourmets\/2024\/07\/26\/super-pumped-la-batalla-por-uber-el-gran-disruptor-del-transporte\/#primaryimage"},"image":{"@id":"https:\/\/blogs.diariovasco.com\/series-gourmets\/2024\/07\/26\/super-pumped-la-batalla-por-uber-el-gran-disruptor-del-transporte\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2024\/07\/super-pumped-la-batalla-por-uber-995916.jpg","datePublished":"2024-07-26T05:00:06+00:00","author":{"@id":"https:\/\/blogs.diariovasco.com\/series-gourmets\/#\/schema\/person\/da56769d3fbfc3b30239e2cd8e5a6d63"},"breadcrumb":{"@id":"https:\/\/blogs.diariovasco.com\/series-gourmets\/2024\/07\/26\/super-pumped-la-batalla-por-uber-el-gran-disruptor-del-transporte\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.diariovasco.com\/series-gourmets\/2024\/07\/26\/super-pumped-la-batalla-por-uber-el-gran-disruptor-del-transporte\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/blogs.diariovasco.com\/series-gourmets\/2024\/07\/26\/super-pumped-la-batalla-por-uber-el-gran-disruptor-del-transporte\/#primaryimage","url":"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2024\/07\/super-pumped-la-batalla-por-uber-995916.jpg","contentUrl":"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-content\/uploads\/sites\/37\/2024\/07\/super-pumped-la-batalla-por-uber-995916.jpg","width":608,"height":408},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.diariovasco.com\/series-gourmets\/2024\/07\/26\/super-pumped-la-batalla-por-uber-el-gran-disruptor-del-transporte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blogs.diariovasco.com\/series-gourmets\/"},{"@type":"ListItem","position":2,"name":"Super Pumped: La batalla por Uber : el gran disruptor del transporte"}]},{"@type":"WebSite","@id":"https:\/\/blogs.diariovasco.com\/series-gourmets\/#website","url":"https:\/\/blogs.diariovasco.com\/series-gourmets\/","name":"Series para gourmets","description":"Propuestas para su men\u00fa televisivo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.diariovasco.com\/series-gourmets\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/blogs.diariovasco.com\/series-gourmets\/#\/schema\/person\/da56769d3fbfc3b30239e2cd8e5a6d63","name":"Lorenzo Mejino","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/f1b8e233b7c252129e0ef7b19d8cc6ba9504a5eb94c6090f63c17430391df4ca?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f1b8e233b7c252129e0ef7b19d8cc6ba9504a5eb94c6090f63c17430391df4ca?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f1b8e233b7c252129e0ef7b19d8cc6ba9504a5eb94c6090f63c17430391df4ca?s=96&d=mm&r=g","caption":"Lorenzo Mejino"},"description":"Series para gourmets nace con la pretensi\u00f3n de ayudar a personalizar su men\u00fa televisivo con el panorama mundial de series. Cada lunes hablaremos de series remotas ni estadounidenses ni brit\u00e1nicas, no estrenadas en nuestro pa\u00eds. Cada mi\u00e9rcoles de series actuales estrenadas aqu\u00ed y los viernes recordamos series del pasado de la televisi\u00f3n","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/lmejino"],"url":"https:\/\/blogs.diariovasco.com\/series-gourmets\/author\/bouvier\/"}]}},"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-json\/wp\/v2\/posts\/21876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-json\/wp\/v2\/comments?post=21876"}],"version-history":[{"count":4,"href":"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-json\/wp\/v2\/posts\/21876\/revisions"}],"predecessor-version":[{"id":21987,"href":"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-json\/wp\/v2\/posts\/21876\/revisions\/21987"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-json\/wp\/v2\/media\/21877"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-json\/wp\/v2\/media?parent=21876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-json\/wp\/v2\/categories?post=21876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/series-gourmets\/wp-json\/wp\/v2\/tags?post=21876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}