{"id":11,"date":"2008-09-23T11:25:22","date_gmt":"2008-09-23T11:25:22","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/sesioncontinua\/?p=11"},"modified":"2008-09-23T11:25:22","modified_gmt":"2008-09-23T11:25:22","slug":"zinemaldi_08_mas_ninos_mas_ninas_y_mas_p","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/2008\/09\/23\/zinemaldi_08_mas_ninos_mas_ninas_y_mas_p\/","title":{"rendered":"Zinemaldi&#039;08: M\u00e1s ni\u00f1os, m\u00e1s ni\u00f1as y m\u00e1s pijamas de rayas"},"content":{"rendered":"<p><P class=MsoBodyTextIndent style=\"MARGIN: 0cm 0cm 0pt 18pt\" align=justify><FONT size=2>Esta actualizaci\u00f3n llega con horas de retraso. Pero es que he tenido una de mis habituales crisis con mi querido ADSL. Yo le mimo, le doy todos los caprichos le trato con cuidado, pero peri\u00f3dicamente le da por ignorarme. Por no hacerme caso. Y de hecho cuando llamo a su 902 ni siquiera descuelga. Todav\u00eda estoy intentado resolver el cacao.<\/FONT><\/P><br \/>\n<P class=MsoBodyTextIndent style=\"MARGIN: 0cm 0cm 0pt 18pt\" align=justify><FONT size=2><SPAN style=\"FONT-SIZE: 8pt; mso-bidi-font-size: 12.0pt\"><FONT size=2>&#8211;<SPAN style=\"FONT: 7pt 'Times New Roman'\"><FONT face=Verdana>&nbsp;<FONT size=2>P<\/FONT><\/FONT><\/SPAN><\/FONT><\/SPAN><SPAN style=\"FONT-SIZE: 8pt; FONT-FAMILY: Verdana; mso-bidi-font-size: 12.0pt\"><FONT size=2>rimer desembarco del cine espa\u00f1ol. La pel\u00edcula en cuesti\u00f3n <I>El patio de mi c\u00e1rcel<\/I> dirigida por la debutante Bel\u00e9n Mac\u00edas y sobre todo, producida por El Deseo, productora de los hermanos Almod\u00f3var. No<\/FONT> <FONT size=2>habr\u00eda estado mal que antes de empezar a rodar hubieran decidido si el objetivo era contar la historia del personaje de Ver\u00f3nica Echegui, convertida en la mejor imitadora de Pen\u00e9lope Cruz conocida, la del grupo de teatro o realizar una denuncia de la situaci\u00f3n de la c\u00e1rceles de mujeres espa\u00f1olas. Porque al final, la pel\u00edcula se queda en tierra de nadie. Y esta versi\u00f3n Disney de presi\u00f3n de mujeres no consigue ninguno de sus prop\u00f3sitos. Hablan mucho, pasan muchas cosas, pero no dice nada. Su gran&nbsp;m\u00e9rito: tener la rueda de prensa con mayor n\u00famero de defensores de la pel\u00edcula sobre la tarima. \u00bfSer\u00e1 este el precio de haber tenido al se\u00f1or Almod\u00f3var entregando el Premio Donostia a Antonio Banderas?<?xml:namespace prefix = o ns = \"urn:schemas-microsoft-com:office:office\" \/><o:p><\/o:p><\/FONT><\/SPAN><\/FONT><\/P><br \/>\n<P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt 36pt; TEXT-INDENT: -18pt; TEXT-ALIGN: justify; mso-list: l0 level1 lfo1; tab-stops: list 36.0pt\" align=justify><FONT size=2>&#8211;<FONT face=Verdana><SPAN style=\"FONT: 7pt 'Times New Roman'\">&nbsp;&nbsp;&nbsp;&nbsp;<FONT size=2>&nbsp;&nbsp;&nbsp;&nbsp; <\/FONT><\/SPAN><SPAN style=\"FONT-SIZE: 8pt; FONT-FAMILY: Verdana; mso-bidi-font-size: 12.0pt\"><FONT size=2>Tienen sentido del humor los programadores del Festival. El mismo d\u00eda y para hacer contraste con esa imagen edulcorada de las c\u00e1rceles en Espa\u00f1a, se presenta la ganadora de la C\u00e1mara de Oro de Cannes, <I>Hunger<\/I>, \u00f3pera prima de Steve McQueen, nada que ver con el que hu\u00eda con Ali MacGraw o se evad\u00eda a lomos de una Triumph Scrambler.<\/FONT><\/SPAN><\/FONT><\/FONT><FONT face=Verdana size=2><SPAN style=\"FONT-SIZE: 8pt; FONT-FAMILY: Verdana; mso-bidi-font-size: 12.0pt\"> <FONT size=2>\u00c9ste es un brit\u00e1nico de la excelente cosecha del 69 con mucho talento para contar historias. Sin lugar a dudas una de las pel\u00edcula m\u00e1s pol\u00e9micas de esta edici\u00f3n. A algunos nos ha parecido poderosa, innovadora y llena de talento y a otros le ha parecido un desfile de violencia superflua y manipuladora<\/FONT>. <FONT size=2>De todas formas, completamente inadecuados los aplausos que se ha o\u00eddo en alg\u00fan pase cuando el guardia de prisiones va a visitar a su madre y pasa lo que pasa (no cuento m\u00e1s)<\/FONT><\/SPAN><\/FONT><\/P><br \/>\n<P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt 36pt; TEXT-INDENT: -18pt; TEXT-ALIGN: justify; mso-list: l0 level1 lfo1; tab-stops: list 36.0pt\" align=justify><FONT size=2>&#8211;<FONT face=Verdana><SPAN style=\"FONT: 7pt 'Times New Roman'\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<FONT size=2>&nbsp;&nbsp;&nbsp; <\/FONT><\/SPAN><SPAN style=\"FONT-SIZE: 8pt; FONT-FAMILY: Verdana; mso-bidi-font-size: 12.0pt\"><FONT size=2>Entre ambas <I>Pandora\u00b4s Box<\/I> una buena pel\u00edcula turca a la que el cuesta demasiado arrancar, aunque algunos miembros de La Banda desertaran, y en Zabaltegi \u2013 Perlas sorpresa agradable con lo nuevo de Assayas <I>Las horas del verano<\/I>, una de las mejores pel\u00edculas vistas hasta ahora en el Zinemaldi. Una mirada certera a la<\/FONT> <FONT size=2>desaparici\u00f3n de la vieja Francia que deber\u00eda ver&nbsp;Jean Becker.<SPAN style=\"COLOR: red\">&nbsp;<\/SPAN><\/FONT><\/SPAN><\/FONT><\/FONT><\/P><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Esta actualizaci\u00f3n llega con horas de retraso. Pero es que he tenido una de mis habituales crisis con mi querido ADSL. Yo le mimo, le doy todos los caprichos le trato con cuidado, pero peri\u00f3dicamente le da por ignorarme. Por no hacerme caso. Y de hecho cuando llamo a su 902 ni siquiera descuelga. Todav\u00eda [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":31,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[4],"class_list":["post-11","post","type-post","status-publish","format-standard","hentry","category-2","tag-896_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/posts\/11","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/comments?post=11"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/posts\/11\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/media?parent=11"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/categories?post=11"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/tags?post=11"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}