{"id":16,"date":"2008-09-18T17:55:20","date_gmt":"2008-09-18T17:55:20","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/sesioncontinua\/?p=16"},"modified":"2008-09-18T17:55:20","modified_gmt":"2008-09-18T17:55:20","slug":"zinemaldi_08_habla_en_ingles","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/2008\/09\/18\/zinemaldi_08_habla_en_ingles\/","title":{"rendered":"Zinemaldi&#039;08: Habla en ingl\u00e9s"},"content":{"rendered":"<p><P align=justify><FONT size=2>Es lo que le grita Javier Bardem a Pen\u00e9lope Cruz en <EM>Vicky Cristina Barcelona<\/EM>. Y es lo que hace Antonio Banderas en <EM>The Other Man<\/EM>. Porque hemos visto s\u00f3lo dos pel\u00edculas y ya tenemos a todos el <EM>star system<\/EM> espa\u00f1ol de Hollywood desplegado. Aunque el resultado no puede ser m\u00e1s diferente.<\/FONT><\/P><br \/>\n<P align=justify><FONT size=2>Curiosamente ambas pel\u00edculas han conseguido la unanimidad de La banda de la Fila 8, que ya est\u00e1 casi en plenitud con la incorporaci\u00f3n de <EM>El productor,<\/EM> que nos acaba de&nbsp;abandonar porque ha quedado con M\u00edguel m\u00e1s conocido como El Duque, <EM>Monypenny<\/EM>&nbsp;que nos ha sorprendido con un <EM>look<\/EM> muy prometedor e <EM>Itsaso<\/EM>&nbsp;un fichaje que nos acompa\u00f1a este a\u00f1o tras pagar la cl\u00e1usula de rescisi\u00f3n que le un\u00eda a la Seminci. A todos nos ha parecido que <EM>The Other Man<\/EM> es muy mala y que <EM>Vicky Cristina Barcelona<\/EM> est\u00e1 muy bien.<\/FONT><\/P><br \/>\n<P align=justify><FONT size=2>Voy por partes. La historia de la pel\u00edcula de Banderas no pasa de telefilm cutre. El gui\u00f3n est\u00e1 lleno de agujeros. Da la impresi\u00f3n de que los int\u00e9rpretes estaban absolutamente perdidos en el rodaje.&nbsp;<EM>The Other Man<\/EM> es&nbsp;falsa, tramposa, obvia, manipuladora. La \u00fanica discusi\u00f3n que ha generado en <EM>La Banda<\/EM> ha sido si las escenas rom\u00e1nticas parec\u00edan m\u00e1s anuncios de colonia de caballero o la promoci\u00f3n de la Semana Fant\u00e1stica de El Corte Ingl\u00e9s. Seguro que a diferencia del a\u00f1o pasado, este a\u00f1o la Secci\u00f3n Oficial va a mejor.<\/FONT><\/P><br \/>\n<P align=justify><FONT size=2>Y el Zinemaldi para comer nos ha puesto lo nuevo de Woody Allen. Y la primera en la frente. Nos han robado la fila 8. Las circunstancias nos han obligado a desplazarnos a la fila 10, pero de momento no se plantea la posibilidad de cambiar el nombre a la banda.<\/FONT><\/P><br \/>\n<P align=justify><FONT size=2><EM>Vicky Cristina Barcelona<\/EM> es muy divertida. Pero el trasfondo de los personajes tiene mucha sustancia. A estas alturas Woody se las sabe todas y con esta pel\u00edcula nos demuestra lo inteligente y h\u00e1bil que es. Quiz\u00e1 no est\u00e1 para genialidades, pero tirando de oficio tiene m\u00e1s que suficiente. Desde el principio nos invita a que nos tomemos su pel\u00edcula a cachondeo. Para que no chirr\u00ede la acumulaci\u00f3n de t\u00f3picos y estereotipos. Y lo consigue. Porque consigue darles la vuelta y convertirlos en el motivo principal de carcajada. Y justifica que los personajes espa\u00f1oles de Bardem y Pe hablen entre ellos en ingl\u00e9s a base de hacer que \u00e9l le repita continuamente a ella lo de &#8220;Habla en ingl\u00e9s&#8221;, convirtiendo una limitaci\u00f3n de producci\u00f3n en motivo de risa. A saber c\u00f3mo se las han arreglado en el doblaje para que esas escenas tengan sentido.<\/FONT><\/P><br \/>\n<P align=justify><FONT size=2>Como suele ocurrir en el cine del neoyorquino todos los actores est\u00e1n bien. Bardem y Rebecca Hall est\u00e1n estupendos. Pero lo de Pen\u00e9lope Cruz es espectacular. Es una verdadera roba-escenas y la pel\u00edcula agradece cada vez que sale en pantalla en un personaje que recuerda a veces a los de Almod\u00f3var. Viendo esta pel\u00edcula uno se da cuenta lo que necesita el cine espa\u00f1ol a dos int\u00e9rpretes del talento de Javier Bardem y Pen\u00e9lope Cruz.<\/FONT><\/P><br \/>\n<P align=justify><FONT size=2>Y ahora me toca mi retiro con Terence Davies. Y un poco de Teledonosti.<\/FONT><\/P><br \/>\n<P>&nbsp;<\/P><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Es lo que le grita Javier Bardem a Pen\u00e9lope Cruz en Vicky Cristina Barcelona. Y es lo que hace Antonio Banderas en The Other Man. Porque hemos visto s\u00f3lo dos pel\u00edculas y ya tenemos a todos el star system espa\u00f1ol de Hollywood desplegado. Aunque el resultado no puede ser m\u00e1s diferente. Curiosamente ambas pel\u00edculas han [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":31,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[4],"class_list":["post-16","post","type-post","status-publish","format-standard","hentry","category-2","tag-896_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/posts\/16","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/comments?post=16"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/posts\/16\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/media?parent=16"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/categories?post=16"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/tags?post=16"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}