{"id":182,"date":"2008-11-26T23:59:16","date_gmt":"2008-11-26T23:59:16","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/sesioncontinua\/?p=182"},"modified":"2008-11-26T23:59:16","modified_gmt":"2008-11-26T23:59:16","slug":"bond_james_bond_la_opinion_experta","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/2008\/11\/26\/bond_james_bond_la_opinion_experta\/","title":{"rendered":"Bond, James Bond. La opini\u00f3n experta"},"content":{"rendered":"<p><P align=justify><FONT size=2>Es la campeona de las taquillas donostiarras. Y de las espa\u00f1olas. Y de las europeas. Y de las mundiales. En un mes ha recaudado m\u00e1s de 400 millones de d\u00f3lares. Y eso que lleva 46 a\u00f1os y m\u00e1s de 20 pel\u00edculas&nbsp;repartiendo mamporros, lig\u00e1ndose a mujeres espectaculares, viajando por todo el mundo y sacando a pasear su licencia para matar. Pero es que \u00e9l es Bond, James Bond.<\/FONT><\/P><br \/>\n<P align=justify><FONT size=2>Y entre los seguidores de este blog, me consta que hay al menos un fan confeso de la serie, casi tan tan fan como Kathy Bates de James Caan en <EM>Misery<\/EM>. Es <EM>Coffeetime People<\/EM> que durante la visita de Richard Gere al pen\u00faltimo Zinemaldi, nos recordaba que hab\u00eda venido acompa\u00f1ado de su se\u00f1ora y ex chica Bond, Carey Lowell. Y como fan fan que es ha tenido el detalle de enviarme su opini\u00f3n acerca de <EM>Quantum of Solace.<\/EM> Y como yo soy legal, reconozco que para este art\u00edculo me he surgido un negro. Esto es lo que le ha parecido la pel\u00edcula.<\/FONT><\/P><br \/>\n<P align=justify><FONT size=2><IMG height=298 src=\"\/sesioncontinua\/wp-content\/uploads\/sites\/17\" width=550><\/FONT><\/P><br \/>\n<P><SPAN lang=ES-TRAD><FONT face=\"Times New Roman\" size=3>&#8220;La nueva pel\u00edcula de James Bond nace como vibrante continuaci\u00f3n de la anterior entrega. Es por ello que el cl\u00e1sico esquema narrativo de planteamiento, nudo y desenlace se queda s\u00f3lo en el nudo y el desenlace.<\/FONT><\/SPAN><\/P><br \/>\n<P><SPAN lang=ES-TRAD><\/SPAN><SPAN lang=ES-TRAD><FONT face=\"Times New Roman\" size=3>S<\/FONT><\/SPAN><SPAN lang=ES-TRAD><FONT face=\"Times New Roman\" size=3>u inicio es muy r\u00e1pido y nos crea una sonrisa similar a la que nos sac\u00f3 en su d\u00eda el arranque de <I>Alta Tensi\u00f3n<\/I>, en la que los \u00e1giles movimientos de Timothy Dalton nos hicieron olvidar de un plumazo los acartonados gestos de las \u00faltimas entregas de Roger Moore.<\/FONT><\/SPAN><\/P><br \/>\n<P><SPAN lang=ES-TRAD><\/SPAN><SPAN lang=ES-TRAD><FONT face=\"Times New Roman\" size=3>Pero una vez pasados los t\u00edtulos de cr\u00e9dito, la historia sigue con el mismo ritmo, en la que apenas da tiempo a asimilar la historia (y aunque me duela decirlo, las pel\u00edculas de JB no tienen en la historia su punto m\u00e1s fuerte).<\/FONT><\/SPAN><\/P><br \/>\n<P><SPAN lang=ES-TRAD><\/SPAN><SPAN lang=ES-TRAD><FONT face=\"Times New Roman\" size=3>Por esto, y dado que los creadores se han remontado a los inicios del personaje en este film, me voy a permitir juzgarlo con un punto de vista cercano al que supusieron las primeras pel\u00edculas.<\/FONT><\/SPAN><\/P><br \/>\n<P><SPAN lang=ES-TRAD><\/SPAN><SPAN lang=ES-TRAD><FONT face=\"Times New Roman\" size=3>La vuelta a los or\u00edgenes que supuso <I>Casino Royale<\/I>, en la que acercaban al personaje de la novela (frente a las fantasiosas historias en las que vimos a Pierce Brosnan), contrasta con el alejamiento que ha tra\u00eddo <I>Quantum of Solace<\/I> respecto de las pel\u00edculas cl\u00e1sicas.<\/FONT><\/SPAN><\/P><br \/>\n<P><SPAN lang=ES-TRAD><\/SPAN><SPAN lang=ES-TRAD><FONT face=\"Times New Roman\" size=3>Y precisamente lo que m\u00e1s echo en falta en <I>Quantum of Solace<\/I> es lo que m\u00e1s desprend\u00eda <I>Agente 007 contra el Doctor No<\/I>: lugares de ensue\u00f1o, lujo y estilo (Martinis con Vodka, trajes a medida confeccionados en Savile Row, etc.).<\/FONT><\/SPAN><\/P><br \/>\n<P><SPAN lang=ES-TRAD><\/SPAN><SPAN lang=ES-TRAD><FONT face=\"Times New Roman\" size=3>Gran parte del que hoy llamamos \u2018estilo ingl\u00e9s\u2019 de James Bond fue creado durante el primer rodaje por Sean Connery y Terence Young, el director. Y es curioso que un director de pel\u00edculas dram\u00e1ticas, como es Marc Forster, haya sido capaz de alejarse tanto de ese estilo.<\/FONT><\/SPAN><\/P><br \/>\n<P><SPAN lang=ES-TRAD><\/SPAN><SPAN lang=ES-TRAD><FONT face=\"Times New Roman\" size=3>De este modo, han perdido muchos de los detalles que han contribuido a crear el personaje de James Bond a lo largo de 22 pel\u00edculas: no menciona su nombre en ning\u00fan momento del film, no bebe Martini con Vodka, se acuesta con una sola chica\u2026 Han querido llegar tan al embri\u00f3n del personaje, que parece que se han olvidado de \u00e9l.<\/FONT><\/SPAN><\/P><br \/>\n<P><SPAN lang=ES-TRAD><\/SPAN><SPAN lang=ES-TRAD><FONT face=\"Times New Roman\" size=3>Pero no s\u00f3lo el personaje huye de s\u00ed mismo, sino que la propia pel\u00edcula tambi\u00e9n lo hace: la espera a la que nos somete para ver la, hasta ahora, secuencia inicial del ca\u00f1\u00f3n; o la melod\u00eda de James Bond, que aparece en el mismo momento.<\/FONT><\/SPAN><\/P><br \/>\n<P><SPAN lang=ES-TRAD><\/SPAN><SPAN lang=ES-TRAD><FONT face=\"Times New Roman\" size=3>Hay estudios que afirman que uno de cada dos habitantes de la tierra ha visto alguna pel\u00edcula de James Bond. Aunque mucho me temo que, si el personaje sigue por estos derroteros, corre el riesgo de que no lo reconozcan.&#8221;<\/FONT><\/SPAN><\/P><br \/>\n<P align=justify><FONT size=2><\/FONT>&nbsp;<\/P><br \/>\n<P align=justify><FONT size=2>Y para que no se diga, aqu\u00ed os paso el link a&nbsp;la cr\u00edtica de la pel\u00edcula que escrib\u00ed para la edici\u00f3n de papel. Que lo de <EM>Bond, James Bond<\/EM> yo tambi\u00e9n me lo he currado.<\/FONT><\/P><br \/>\n<P align=justify><FONT size=2><A href=\"http:\/\/www.diariovasco.com\/20081123\/cultura\/bond-20081123.html\">http:\/\/www.diariovasco.com\/20081123\/cultura\/bond-20081123.html<\/A><\/FONT><\/P><br \/>\n<P align=justify><FONT size=2><\/FONT>&nbsp;<\/P><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Es la campeona de las taquillas donostiarras. Y de las espa\u00f1olas. Y de las europeas. Y de las mundiales. En un mes ha recaudado m\u00e1s de 400 millones de d\u00f3lares. Y eso que lleva 46 a\u00f1os y m\u00e1s de 20 pel\u00edculas&nbsp;repartiendo mamporros, lig\u00e1ndose a mujeres espectaculares, viajando por todo el mundo y sacando a pasear [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":31,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[4],"class_list":["post-182","post","type-post","status-publish","format-standard","hentry","category-2","tag-896_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/posts\/182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/comments?post=182"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/posts\/182\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/media?parent=182"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/categories?post=182"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/tags?post=182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}