{"id":26,"date":"2008-08-20T23:47:22","date_gmt":"2008-08-20T23:47:22","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/sesioncontinua\/?p=26"},"modified":"2008-08-20T23:47:22","modified_gmt":"2008-08-20T23:47:22","slug":"se_les_han_adelantado","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/2008\/08\/20\/se_les_han_adelantado\/","title":{"rendered":"Se les han adelantado&#8230;"},"content":{"rendered":"<p><P align=justify><FONT size=2><IMG hspace=5 src=\"\/sesioncontinua\/wp-content\/uploads\/sites\/17\" align=left>As\u00ed es. No han esperado a que el propio Festival&nbsp;lo comunicara&nbsp;y se les han adelantado. Esta \u00faltima semana el Zinemaldi nos ha anunciado la&nbsp;muy prometedora selecci\u00f3n de&nbsp;t\u00edtulos espa\u00f1oles que estar\u00e1n en la Secci\u00f3n y Zabaltegi,&nbsp;pel\u00edculas de&nbsp;directores j\u00f3venes y con cosas que decir y pr\u00e1cticamente liberada de directores establecidos y acomodados, y un&nbsp; Horizontes Latinos muy atractivo &nbsp;con pel\u00edculas que han triunfado en otros festivales, casi como un Perlas de Otros Festivales Latino. De hecho, pr\u00e1cticamente lo \u00fanico que nos queda por conocer es Zabaltegi y las pel\u00edculas especiales de la Secci\u00f3n Oficial (inauguraci\u00f3n, clausura etc.)<\/FONT><\/P><br \/>\n<P align=justify><FONT size=2>Y andaba yo salseando por las p\u00e1ginas web de las distribuidoras y me encuentro con el p\u00f3ster de <STRONG>&#8220;Happy&#8221;<\/STRONG>, la nueva de Mike Leigh (el de la genial &#8220;Secretos y Mentiras&#8221;, &#8220;Vera Drake&#8221;, &#8220;Todo o nada&#8221; o&nbsp;&#8220;La vida es dulce&#8221;) en el que al lado del Oso de Plata que se llev\u00f3 en Berl\u00edn&#8217;08, se puede ver la Concha del Zinemaldi y&nbsp;la palabra Zabaltegi. As\u00ed que adem\u00e1s de Woody Allen y su <STRONG>&#8220;Vicky Cristina Barcelona&#8221;,<\/STRONG> que ya adelant\u00f3 la distribuidora hace&nbsp;meses que inaugurar\u00eda Zabaltegi y que confirm\u00f3 la semana pasada&nbsp;el propio&nbsp;Zinemaldi, sabemos que tambi\u00e9n podremos ver lo \u00faltimo de Mike Leigh. Todo un lujo.<\/FONT><\/P><br \/>\n<P align=justify><FONT size=2>Precisamente, hace unos d\u00edas pude ver&nbsp;<STRONG>&#8220;Happy&#8221;<\/STRONG> en una escapada cinematogr\u00e1fica a Biarritz acompa\u00f1ado de las ZZ Sisters y de las Synto Girls.&nbsp;Y es muy muy recomendable.&nbsp;Es divertida, alegra, fresca, llena de encanto y&nbsp;con unos personajes tan reales&nbsp;y unos di\u00e1logos tan naturales como es norma en el cine de Leigh.&nbsp;Hay alg\u00fan momento en el que se repite y se echa de menos un soporte argumental de m\u00e1s entidad, pero es de esas pel\u00edculas de las que uno sale con la sonrisa de oreja a oreja y satisfecho de haber decidido ir ese d\u00eda al cine.<\/FONT><\/P><br \/>\n<P align=justify><FONT size=2>Aprovechando el viaje tambi\u00e9n nos escapamos a ver <STRONG>&#8220;Vals con Bashir&#8221;<\/STRONG>, una especie de documental de animaci\u00f3n con el trasfondo de la masacre de Sabra y Chatila que triunf\u00f3 en Cannes&#8217;08. Otra pel\u00edcula magn\u00edfica. Y en relaci\u00f3n a lo que&nbsp;dec\u00eda en el comentario anterior cuando hablaba de &#8220;Wall &#8211; E&#8221;, una demostraci\u00f3n de c\u00f3mo se puede hacer gran cine para adultos utilizando las t\u00e9cnicas de animaci\u00f3n. Ya puestos, no estar\u00eda nada mal que estuviera en el Zinemaldi. De momento, Golem la anuncia PROXIMAMENTE.<\/FONT><\/P><br \/>\n<P align=justify><FONT size=2>Otra de rumores festivaleros: me cuentan que la parte masculina de la pareja m\u00e1s&nbsp;famosa de Hollywood, de&nbsp; numerosa y variada prole y&nbsp;que acaba de mudarse a vivir a casa de nuestros vecinos del norte,&nbsp;finalmente no va a poder visitar el Zinemaldi como ten\u00eda previsto por razones familiares. Una l\u00e1stima.&nbsp;\u00bfQu\u00e9 habr\u00e1 de cierto? \u00bfrumores infundados? \u00bfcu\u00e1ntos a\u00f1os de rumores diciendo que ven\u00eda Robert&nbsp;de Niro tuvimos que esperar&nbsp;para que finalmente&nbsp;viniera? Que yo recuerdo este a\u00f1o es el primero en el que se ha hablado de&nbsp;la visita de este antiguo &#8220;Pollo Loco&#8221;. &nbsp;<\/FONT><\/P><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>As\u00ed es. No han esperado a que el propio Festival&nbsp;lo comunicara&nbsp;y se les han adelantado. Esta \u00faltima semana el Zinemaldi nos ha anunciado la&nbsp;muy prometedora selecci\u00f3n de&nbsp;t\u00edtulos espa\u00f1oles que estar\u00e1n en la Secci\u00f3n y Zabaltegi,&nbsp;pel\u00edculas de&nbsp;directores j\u00f3venes y con cosas que decir y pr\u00e1cticamente liberada de directores establecidos y acomodados, y un&nbsp; Horizontes Latinos muy [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":31,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[4],"class_list":["post-26","post","type-post","status-publish","format-standard","hentry","category-2","tag-896_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/posts\/26","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/comments?post=26"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/posts\/26\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/media?parent=26"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/categories?post=26"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/tags?post=26"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}