{"id":31,"date":"2008-04-26T16:57:46","date_gmt":"2008-04-26T16:57:46","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/sesioncontinua\/?p=31"},"modified":"2008-04-26T16:57:46","modified_gmt":"2008-04-26T16:57:46","slug":"vuelta_a_la_cartelera_comercial","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/2008\/04\/26\/vuelta_a_la_cartelera_comercial\/","title":{"rendered":"Vuelta a la cartelera comercial"},"content":{"rendered":"<p><P align=justify><FONT size=2>Ha sido una semana de mujeres chinas, ni\u00f1os soldado, v\u00edctimas del terrorismo, homosexuales \u00e1rabes, coloquios interesantes, putas camboyanas, hijos desaparecidos, hermanas autistas, estudiantes cabrones, neonazis, visitas papales,&nbsp;sesiones que se alargaban hasta casi la madrugada, ablaci\u00f3n femenina, ancianas moribundas, mercenarios del agua, innecesarios discursos pol\u00edticos de clausura&#8230; pero ya ha pasado el <STRONG>Festival de Cine y Derechos Humanos<\/STRONG> y toca volver a ver que nos ofrece la renovada cartelera&nbsp;donostiarra. Y digo lo de renovada porque&nbsp;mientras algunos&nbsp;est\u00e1bamos &#8220;concienci\u00e1ndonos&#8221; en el Victoria Eugenia en dobles \/ triples&nbsp;sesiones de tarde y casi madrugada,&nbsp;han llegado a los cines comerciales donostiarras&nbsp;m\u00e1s de una docena de estrenos.<\/FONT><\/P><br \/>\n<P align=justify><FONT size=2>Y ante este aluvi\u00f3n de pel\u00edculas que no he visto, he salseado un poco por internet para ver qu\u00e9 es lo que m\u00e1s les ha gustado a los usuarios de imdb y filmaffinity de entre lo que podemos ver en Donosti. Y \u00e9stas son sus favoritas (que no las m\u00edas):<\/FONT><\/P><br \/>\n<P align=justify><FONT size=2><IMG height=158 src=\"\/sesioncontinua\/wp-content\/uploads\/sites\/17\" width=110 vspace=10><IMG height=157 src=\"\/sesioncontinua\/wp-content\/uploads\/sites\/17\" width=110 vspace=10><IMG height=158 src=\"\/sesioncontinua\/wp-content\/uploads\/sites\/17\" width=110 vspace=10><IMG height=158 src=\"\/sesioncontinua\/wp-content\/uploads\/sites\/17\" width=110 vspace=10><IMG height=158 src=\"\/sesioncontinua\/wp-content\/uploads\/sites\/17\" width=110 vspace=10><\/FONT><\/P><br \/>\n<P align=justify><FONT size=2><STRONG>1. Al otro lado<\/STRONG> de Fatih Akin. Ganadora de numerosos premios por su gui\u00f3n que consigue encajar&nbsp;todo tipo de personajes, situaciones, denuncias, culturas, generaciones&#8230; \u00bfun poco demasiado?&nbsp;Toda una veterana de las carteleras.<\/FONT><\/P><br \/>\n<P align=justify><FONT size=2><STRONG>2. El ba\u00f1o del Papa<\/STRONG>. Ganadora entre otros del premio Horizontes Latinos del Zinemaldi. Un entra\u00f1able &#8220;Bienvenido, Mr Marshall&#8221; esta vez en Uruguay y&nbsp;con una visita del Papa como excusa.<\/FONT><\/P><br \/>\n<P align=justify><FONT size=2><STRONG>3. Los falsificadores<\/STRONG>. La ganadora del Oscar a la mejor pel\u00edcula extranjera. Otra&nbsp;sobrevalorada, en mi opinion, pero aqu\u00ed aparece&nbsp;lo que votan los internautas<\/FONT><\/P><br \/>\n<P align=justify><FONT size=2><STRONG>4. La banda nos visita.<\/STRONG> A los chicos de Manga (correcci\u00f3n: sustituyo Golem por Manga, gracias Rafter) se les ha ocurrido estrenarla doblada, carg\u00e1ndose gran parte del trasfondo de la pel\u00edcula. Una visi\u00f3n optimista del conflicto arabe &#8211; israel\u00ed. La ant\u00edtesis del &#8220;To die in Jerusalem&#8221; visto esta semana en el Victoria Eugenia.<\/FONT><\/P><br \/>\n<P align=justify><FONT size=2><STRONG>5. Lars y una chica de verdad.<\/STRONG> Una comedia rom\u00e1ntica distinta, nominada para los Oscars y convertida en pel\u00edcula de culto en los USA.<\/FONT><\/P><br \/>\n<P align=justify><FONT size=2><STRONG>6. Buda explot\u00f3 por verg\u00fcenza.<\/STRONG> Una veterana de la cartelera donostiarra. Ganadora del Premio Especial del Jurado del \u00faltimo Zinemaldi.<\/FONT><\/P><br \/>\n<P align=justify><FONT size=2><STRONG>7. La familia Savage<\/STRONG> con Laura Linney y Philip Seymour Hoffman. Ya la recomend\u00e9 hace unas semanas. Dur\u00edsimo drama con algunos toques de humor.<\/FONT><\/P><br \/>\n<P align=justify><FONT size=2><STRONG>8. Cosas que perdimos en el fuego<\/STRONG> con Halle Berry, Benicio del Toro y David Duchovny dirigidos por Susanne Bier. Star system de Hollywood con la directora de &#8220;Te quiero para siempre&#8221; &#8220;Broders&#8221; o &#8220;Despu\u00e9s de la boda&#8221;. En V.O. en el Trueba.<\/FONT><\/P><br \/>\n<P align=justify><FONT size=2><STRONG>9. Rebobine, por favor de Michel Gondry.<\/STRONG> Divertida y original comedia con much\u00e1 m\u00e1s sustancia de la que aparenta.<\/FONT><\/P><br \/>\n<P align=justify><FONT size=2><STRONG>10. Mil a\u00f1os de Oraci\u00f3n de Wayne Wang.<\/STRONG> La \u00faltima Concha de Oro.<\/FONT><\/P><br \/>\n<P align=justify><FONT size=2>Ahora me toca&nbsp;organizar la agenda.&nbsp;<\/FONT><\/P><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Ha sido una semana de mujeres chinas, ni\u00f1os soldado, v\u00edctimas del terrorismo, homosexuales \u00e1rabes, coloquios interesantes, putas camboyanas, hijos desaparecidos, hermanas autistas, estudiantes cabrones, neonazis, visitas papales,&nbsp;sesiones que se alargaban hasta casi la madrugada, ablaci\u00f3n femenina, ancianas moribundas, mercenarios del agua, innecesarios discursos pol\u00edticos de clausura&#8230; pero ya ha pasado el Festival de Cine y [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":31,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[4],"class_list":["post-31","post","type-post","status-publish","format-standard","hentry","category-2","tag-896_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/posts\/31","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/comments?post=31"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/posts\/31\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/media?parent=31"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/categories?post=31"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/tags?post=31"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}