{"id":39,"date":"2008-09-19T11:36:12","date_gmt":"2008-09-19T11:36:12","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/sesioncontinua\/?p=39"},"modified":"2008-09-19T11:36:12","modified_gmt":"2008-09-19T11:36:12","slug":"zinemaldi_08_cosillas","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/2008\/09\/19\/zinemaldi_08_cosillas\/","title":{"rendered":"Zinemaldi&#039;08: Cosillas"},"content":{"rendered":"<p><P>Unas cosillas aprovechando la inspiraci\u00f3n de estar al lado de Mr. Pumares y Jaume Figueras y en la compa\u00f1\u00eda de las comentaristas blogueras latxeno y lacatalanacerrada.<\/P><br \/>\n<P align=justify>&#8211; Tanta alfombra <FONT color=#ff00ff>fucsia<\/FONT>, antena, tronco o lo que sea del cartel <FONT color=#ff00ff>fucsia<\/FONT> (yo le llamar\u00e9 txirinbolo) y la bolsa del Festi de este a\u00f1o es <FONT color=#0000ff>azul.<\/FONT><FONT size=+0> <\/FONT><FONT size=2>S\u00e9 a quien le ha desbarajustado todos los planes de vestuario y se ha encontrado con varios modelitos que no le combinan. \u00a1Qu\u00e9 desgracia!<\/FONT><\/P><br \/>\n<P align=justify>&#8211; Desvelada la inc\u00f3gnita de la cortinilla de inicio de las pel\u00edculas. Una imagen fija con el txirinbolo fucsia, el cielo azul y un verde bosque con el sonido del mar de fondo. Sencillo a la par que elegante.<\/P><br \/>\n<P align=justify>&#8211; Los compa\u00f1eros de Teledonosti con Supervane a la cabeza, se han aburrido de Zuatzu y los programas especiales del Zinemaldi van a grabarlos en las terrazas del Kursaal, para estar bien cerca de la noticia y al ladito de la <FONT color=#ff00ff>alfombra<\/FONT>.&nbsp;Adem\u00e1s van a regalar entradas a la gente que se acerque por el miniestudio durante la grabaci\u00f3n del programa.<\/P><br \/>\n<P align=justify>&#8211; \u00bfQu\u00e9 pas\u00f3 ayer por la noche en el Zinemaldi Plaza? Esta ma\u00f1ana a las 8:45 hab\u00eda desaparecido un mueble y han aparecido tirados por el suelo los tickets del turno de la pescad&#8230; esto&#8230; de la taquilla y dem\u00e1s enseres. Por cierto, el Festival ha decidido que la taquilla de acreditados &nbsp;no se abra hasta las 9:00 (otros a\u00f1os la hora de apertura era 8:30), por lo que teniendo en cuenta que es la hora a la que empiezan los pases de prensa, sacar las entradsa del d\u00eda siguiente ya no ser\u00e1 la primera tarea a hacer por la ma\u00f1ana.<\/P><br \/>\n<P align=justify>Y la primera peli a concurso: la iran\u00ed <EM>Two-legged horse<\/EM>. Decepcionante. Gui\u00f3n y puesta en escena rudimentarios. Un corto alargad\u00edsimo y con un final&nbsp;sensacionalista y tremendista.<\/P><br \/>\n<P><FONT color=#0000ff><\/FONT>&nbsp;<\/P><br \/>\n<P><FONT color=#0000ff><\/FONT>&nbsp;<\/P><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Unas cosillas aprovechando la inspiraci\u00f3n de estar al lado de Mr. Pumares y Jaume Figueras y en la compa\u00f1\u00eda de las comentaristas blogueras latxeno y lacatalanacerrada. &#8211; Tanta alfombra fucsia, antena, tronco o lo que sea del cartel fucsia (yo le llamar\u00e9 txirinbolo) y la bolsa del Festi de este a\u00f1o es azul. S\u00e9 a [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":31,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[4],"class_list":["post-39","post","type-post","status-publish","format-standard","hentry","category-2","tag-896_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/posts\/39","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/comments?post=39"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/posts\/39\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/media?parent=39"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/categories?post=39"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sesioncontinua\/wp-json\/wp\/v2\/tags?post=39"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}